{"id":8593,"date":"2023-01-25T05:15:52","date_gmt":"2023-01-25T04:15:52","guid":{"rendered":"https:\/\/www.minutepapillote.com\/?p=8593"},"modified":"2024-02-07T15:04:38","modified_gmt":"2024-02-07T14:04:38","slug":"mini-tartelettes-ananas","status":"publish","type":"post","link":"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/","title":{"rendered":"Mini tartelettes ananas du Nouvel An chinois"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8593\" class=\"elementor elementor-8593\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4279499b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4279499b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9055c22\" data-id=\"9055c22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1865a78f elementor-widget elementor-widget-text-editor\" data-id=\"1865a78f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">De <strong>jolis soleils rayonnants<\/strong> pour c\u00e9l\u00e9brer les f\u00eates du <strong>Nouvel An chinois<\/strong> avec ces mini tartelettes ananas. \u00a0Avec une p\u00e2te sabl\u00e9e croustillante, un confit d&rsquo;ananas qui fond en bouche&#8230; des petites gourmandises\u00a0<strong>passionn\u00e9ment<\/strong> addictives &#8211; et tellement <strong>amusantes<\/strong> \u00e0 faire !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20b3ff99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20b3ff99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23dd833\" data-id=\"23dd833\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73ccaaa2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"73ccaaa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ma_petite_recette\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aller \u00e0 la recette<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1257c0e5 elementor-widget elementor-widget-spacer\" data-id=\"1257c0e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-150670ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"150670ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3499e72d\" data-id=\"3499e72d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37fb7ed4 elementor-widget elementor-widget-heading\" data-id=\"37fb7ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">L&#039;article en un coup d&#039;oeil :<\/span>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #f4926a;color:#f4926a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #f4926a;color:#f4926a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/#Des_mini_tartelettes_ananas_amusantes_a_preparer\" >Des mini tartelettes ananas amusantes \u00e0 pr\u00e9parer !<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/#Nouvel_An_chinois_tout_est_symbole\" >Nouvel An chinois : tout est symbole !<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/#Mini_tartelettes_ananas_du_Nouvel_An_chinois\" >Mini tartelettes ananas du Nouvel An chinois<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Des_mini_tartelettes_ananas_amusantes_a_preparer\"><\/span>Des mini tartelettes ananas amusantes \u00e0 pr\u00e9parer !<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f6e39f elementor-widget elementor-widget-text-editor\" data-id=\"57f6e39f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Attention, ambiance travaux manuels pour ces p\u00e2tisseries toute douces ! Ici, deux \u00e9tapes qui changent un peu de la p\u00e2tisserie traditionnelle et s\u00e9rieuse :<\/span><\/p><ul><li><span style=\"color: #000000;\">on fait de la p\u00e2te \u00e0 modeler ! En effet le confit d&rsquo;ananas, assez dense doit \u00eatre form\u00e9 en petites billes &#8211; pour cela, on met \u00e0 profit ses <strong>comp\u00e9tences<\/strong> acquises d\u00e8s le plus jeune \u00e2ge (disons, la maternelle ;-)) &#8211; et pourquoi pas, on fait un<strong> atelier avec les enfants<\/strong> !<\/span><\/li><li><span style=\"color: #000000;\">le d\u00e9coupage de la p\u00e2te est tout aussi <strong>fun<\/strong>, en utilisant de pr\u00e9f\u00e9rence une presse \u00e0 biscuits ; ou \u00e9ventuellement un emporte-pi\u00e8ce, ou bien encore un petit verre \u00e0 liqueur si vous n&rsquo;avez pas de presse. Cela dit, je vous recommande l&rsquo;investissement ; la mienne m&rsquo;a cout\u00e9 tr\u00e8s peu cher (environ 5\u20ac) et je l&rsquo;ai d\u00e9j\u00e0 largement rentabilis\u00e9e !<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40cfc3d e-flex e-con-boxed e-con e-parent\" data-id=\"40cfc3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7279e36 elementor-widget elementor-widget-image\" data-id=\"7279e36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-cookie-press.jpeg\" class=\"attachment-loop-sticky size-loop-sticky wp-image-8621\" alt=\"presse \u00e0 cookies\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2ab593 elementor-widget elementor-widget-image\" data-id=\"f2ab593\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-cookie-press-zoom.jpeg\" class=\"attachment-loop-sticky size-loop-sticky wp-image-8620\" alt=\"zoom sur la presse \u00e0 cookie\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22ea68e elementor-widget elementor-widget-image\" data-id=\"22ea68e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-pompe-cookies.jpeg\" class=\"attachment-loop size-loop wp-image-8617\" alt=\"utilisation presse \u00e0 cookies. pour les mini tartelettes ananas\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af2a97d elementor-widget elementor-widget-image\" data-id=\"af2a97d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-faconnage.jpeg\" class=\"attachment-loop size-loop wp-image-8618\" alt=\"les mini tartelettes ananas apr\u00e8s utilisation presse \u00e0 cookies\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93aa7ba elementor-widget elementor-widget-text-editor\" data-id=\"93aa7ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Bref, pr\u00e9parer des mini tartelettes ananas, c&rsquo;est <strong>amusant<\/strong> &#8211; et cela peut aussi se faire <strong>en famille<\/strong>. Voil\u00e0 une belle ambiance de f\u00eate pour ce Nouvel An chinois !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fa635e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fa635e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-668bfe0\" data-id=\"668bfe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a89daf8 elementor-widget elementor-widget-heading\" data-id=\"5a89daf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Nouvel_An_chinois_tout_est_symbole\"><\/span>Nouvel An chinois : tout est symbole ! <span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-529903cc elementor-widget elementor-widget-text-editor\" data-id=\"529903cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">En plus d&rsquo;\u00eatre amusantes \u00e0 faire et passionn\u00e9ment addictives, ces mini tartelettes ananas rev\u00eatent dans la culture singapourienne \u00a0une signification profonde. En effet, cuisiner ou offrir des <em>pineapple tarts<\/em> est tout un symbole. Vous voulez en savoir plus ? Voil\u00e0 de quoi briller en soci\u00e9t\u00e9 !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a105940 elementor-widget elementor-widget-heading\" data-id=\"a105940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">L'ananas... c'est du bl\u00e9 !<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf0a6d elementor-widget elementor-widget-text-editor\" data-id=\"eaf0a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">L&rsquo;ananas est important pour les <strong>Singapouriens<\/strong>. Ou plut\u00f4t sa <strong>culture<\/strong>. En effet, avant que Singapour soit la cit\u00e9-Etat que l&rsquo;on connait aujourd&rsquo;hui avec son \u00a0centre financier de r\u00e9f\u00e9rence <strong>internationale<\/strong>, donc avant les hauts buildings et le rang (pas si convoit\u00e9) de 2\u00e8me ville<strong> la plus ch\u00e8re au monde<\/strong> &#8211; et bien Singapour \u00e9tait un espace rural (jusque dans les ann\u00e9es 60 tout de m\u00eame !). La culture de l&rsquo;ananas a fait la <strong>fortune\u00a0<\/strong>de nombreuses familles, dont certaines sont devenues de <strong>grands m\u00e9c\u00e8nes<\/strong> pour leur pays. C&rsquo;est dire la place de ce fruit dans l&rsquo;\u00e9conomie, la vie politique et culturelle du 20\u00e8me si\u00e8cle.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ba014 elementor-widget elementor-widget-heading\" data-id=\"b2ba014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">...Et cela remonte \u00e0 longtemps !<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-554caf6 elementor-widget elementor-widget-text-editor\" data-id=\"554caf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 16px;\">La majorit\u00e9 de la population singapourienne est d&rsquo;<strong>origine chinoise<\/strong> (75 \u00e0 80%). \u00a0Les Chinois ont emport\u00e9 dans leurs bagages leur <strong>culture <\/strong>avec\u00a0leurs religions (bouddhiste et tao\u00efste), leur gastronomie, et bien s\u00fbr leurs dialectes. Comme par exemple le hokkien (une des langues officielles de Ta\u00efwan, pour vous donner une id\u00e9e). Et en hokkien, l&rsquo;ananas se dit \u00ab\u00a0<strong>ong lai<\/strong>\u00ab\u00a0. En connaissez-vous la <strong>signification<\/strong> ? \u00a0Et bien, cela pourrait se traduire en anglais par \u00ab\u00a0fortune come\u00a0\u00bb&#8230; en<strong> un <\/strong>mot, l&rsquo;<strong>ananas<\/strong>, c&rsquo;est la\u00a0<\/span><strong>prosp\u00e9rit\u00e9<\/strong>. Ce qui nous renvoie au paragraphe pr\u00e9c\u00e9dent sur la culture de ce fruit. L&rsquo;ananas, c&rsquo;est du bl\u00e9, sur le long terme. Alors, autant le dire avec un g\u00e2teau !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d11be6 elementor-widget elementor-widget-heading\" data-id=\"2d11be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des mini tartelettes ananas qui c\u00e9l\u00e8brent un Singapour multi-culturel<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3bf152 elementor-widget elementor-widget-text-editor\" data-id=\"a3bf152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">La cit\u00e9-Etat doit aussi sa prosp\u00e9rit\u00e9 (on y revient&#8230;) \u00e0 son emplacement g\u00e9ographique, qui lui permet d&rsquo;\u00eatre au carrefour de nombreuses routes maritimes. C&rsquo;est aussi un pays qui a <strong>accueilli<\/strong> plusieurs vagues d&rsquo;immigrations. Singapour a su <strong>s&rsquo;enrichir<\/strong> de ces nombreuses <strong>diversit\u00e9s culturelles<\/strong>\u00a0et peut s&rsquo;enorgueillir aujourd&rsquo;hui d&rsquo;une tr\u00e8s grande tol\u00e9rance religieuse. Et la gastronomie n&rsquo;est pas en reste, t\u00e9moin d&rsquo;<strong>influences chinoises<\/strong> bien \u00e9videmment, mais aussi <strong>indiennes<\/strong>, <strong>malaises<\/strong>, <strong>indon\u00e9siennes<\/strong>&#8230; Et bien s\u00fbr <strong>europ\u00e9ennes,<\/strong> puisque Singapour est rest\u00e9e longtemps sous la coupe <strong>britannique<\/strong>. Avec la p\u00e2te sabl\u00e9e toute <strong>craquante<\/strong> de ces mini tartelettes ananas, que l&rsquo;on pourrait assimiler \u00e0 un <em>short bread<\/em>, on c\u00e9l\u00e8bre donc une influence venue d&rsquo;ailleurs. L&rsquo;<strong>exotisme<\/strong> de l&rsquo;<strong>Occident<\/strong>. Craquant, non ?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-87f4977 e-flex e-con-boxed e-con e-parent\" data-id=\"87f4977\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7521b4a elementor-widget elementor-widget-image\" data-id=\"7521b4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom.jpeg\" class=\"attachment-large size-large wp-image-8612\" alt=\"zoom sur les mini tartelettes ananas\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom.jpeg 1200w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom-225x300.jpeg 225w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom-768x1025.jpeg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom-1151x1536.jpeg 1151w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-zoom-750x1001.jpeg 750w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b736bd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b736bd0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3281e9e6\" data-id=\"3281e9e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0c9947 elementor-widget elementor-widget-spacer\" data-id=\"a0c9947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2427b73b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2427b73b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6923998\" data-id=\"6923998\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23a9bdf6 elementor-widget elementor-widget-menu-anchor\" data-id=\"23a9bdf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ma_petite_recette\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b3bb04 elementor-widget elementor-widget-wpzoom-elementor-recipe-card-widget-cpt\" data-id=\"5b3bb04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpzoom-elementor-recipe-card-widget-cpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpzoom-custom-recipe-card-post wpzoom-rcb-post-shortcode\" data-parent-id=\"8596\" data-recipe-post=\"8596\"><div id=\"wpzoom-premium-recipe-card\" class=\"wp-block-wpzoom-recipe-card-block-recipe-card header-content-align-left block-alignment-left is-style-default\">\n\t\t\t<div class=\"recipe-card-image\">\n\t\t\t<figure>\n\t\t\t\t<a class=\"recipe-card-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-800x530.jpeg\" class=\"wpzoom-recipe-card-image\" alt=\"Mini tartelettes ananas du Nouvel An chinois\" id=\"8611\" data-pin-media=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-800x530.jpeg\" data-pin-description=\"Mini tartelettes ananas du Nouvel An chinois\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-800x530.jpeg 800w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-360x240.jpeg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpzoom-recipe-card-pinit\">\n\t            <a class=\"btn-pinit-link no-print\" data-pin-do=\"buttonPin\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url=https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/&#038;media=https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-800x530.jpeg&#038;description=Mini%20tartelettes%20ananas%20du%20Nouvel%20An%20chinois\" data-pin-custom=\"true\" aria-label=\"Pin recipe on Pinterest\" title=\"Pin recipe on Pinterest\" >\n\t            \t<SVG class=\"wpzoom-rcb-icon-pinit-link\" enable-background=\"new 0 0 30 30\" height=\"30px\" id=\"Pinterest\" version=\"1.1\" viewBox=\"0 0 30 30\" width=\"30px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t            \t    <Path class=\"wpzoom-rcb-pinit-icon\" d=\"M16,0C7.813,0,3,6.105,3,11c0,2.964,2,6,3,6s2,0,2-1s-2-2-2-5c0-4.354,4.773-8,10-8c4.627,0,7,3.224,7,7  c0,4.968-2.735,9-6,9c-1.803,0-3.433-1.172-3-3c0.519-2.184,1-2,2-6c0.342-1.368-0.433-3-2-3c-1.843,0-4,1.446-4,4c0,1.627,1,3,1,3  s-2.245,7.863-2.576,9.263C7.766,26.049,6.938,30,7.938,30S10,28,12,23c0.295-0.738,1-3,1-3c0.599,1.142,3.14,2,5,2  c5.539,0,9-5.24,9-12C27,4.888,22.58,0,16,0z\" \/>\n\t            \t<\/SVG>\n\t            \t<span>Pin<\/span>\n\t            <\/a>\n\t        <\/div><div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link no-print\" href=\"#wpzoom-premium-recipe-card\" aria-label=\"Print recipe\" title=\"Print recipe\" title=\"Print directions\" data-recipe-id=\"8593\">\n                    <svg viewBox=\"0 0 32 32\" width=\"18\" height=\"18\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"wpzoom-rcb-icon-print-link\" aria-hidden=\"true\" focusable=\"false\"><g data-name=\"Layer 55\" id=\"Layer_55\"><path class=\"wpzoom-rcb-print-icon\" d=\"M28,25H25a1,1,0,0,1,0-2h3a1,1,0,0,0,1-1V10a1,1,0,0,0-1-1H4a1,1,0,0,0-1,1V22a1,1,0,0,0,1,1H7a1,1,0,0,1,0,2H4a3,3,0,0,1-3-3V10A3,3,0,0,1,4,7H28a3,3,0,0,1,3,3V22A3,3,0,0,1,28,25Z\"><\/path><path class=\"wpzoom-rcb-print-icon\" d=\"M25,31H7a1,1,0,0,1-1-1V20a1,1,0,0,1,1-1H25a1,1,0,0,1,1,1V30A1,1,0,0,1,25,31ZM8,29H24V21H8Z\"><\/path><path class=\"wpzoom-rcb-print-icon\" d=\"M25,9a1,1,0,0,1-1-1V3H8V8A1,1,0,0,1,6,8V2A1,1,0,0,1,7,1H25a1,1,0,0,1,1,1V8A1,1,0,0,1,25,9Z\"><\/path><rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"2\" x=\"24\" y=\"11\"><\/rect><rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"4\" x=\"18\" y=\"11\"><\/rect><\/g><\/svg>\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div>\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div><!-- \/.recipe-card-image -->\n\t\t\t\t<div class=\"recipe-card-heading\">\n\t\n\t\t\n\t\t\t\t<h2 class=\"recipe-card-title\"><span class=\"ez-toc-section\" id=\"Mini_tartelettes_ananas_du_Nouvel_An_chinois\"><\/span>Mini tartelettes ananas du Nouvel An chinois<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\t\t\t\t\t\t<div class=\"recipe-sub-title\">\n                            <span class=\"recipe-card-author\">Recipe by Helene<\/span>\n            \n            <div class=\"wpzoom-rating-stars-container\" data-rating=\"5.0\" data-rating-total=\"3\" data-recipe-id=\"8596\" data-post-id=\"8593\" data-user-can-rate=\"1\">\n\t\t\t\t<ul class=\"wpzoom-rating-stars\"><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><\/ul><span class=\"wpzoom-rating-stars-average\"><span class=\"wpzoom-rating-average\">5.0<\/span> from <span class=\"wpzoom-rating-total-votes\">3<\/span> votes<\/span>\n\t\t\t\t<em class=\"wpzoom-rating-stars-tooltip\"><\/em>\n\t\t\t<\/div>        <\/div>\n\n        \n\t\t<div class=\"recipe-card-details-top\">\n                    <\/div>\n\t<\/div><!-- \/.recipe-card-heading -->\n\n\t\n\t\t\t<div class=\"recipe-card-details\">\n\t\t\t<div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 1024 1024\"><path d=\"M768 520V51q0-10-4-19.5T753 15q-7-7-16.5-11T717 0q-10 0-19.5 4T681 15q-8 7-11.5 16.5T666 51v469q-34 9-62.5 29T555 596q-21 28-32 61t-11 67q0 40 14 91t40.5 97q26.5 46 64.5 78 38 31 86 31 47 0 85-31 38-32 64.5-78t40.5-97q15-51 15-91 0-34-11-67t-32-61q-21-27-49.5-47T768 520zm-51 402q-31 0-67-68t-36-127q-1-21 6.5-41.5T642 650q15-16 34-25.5t41-10.5q21 1 40.5 10.5T791 650q15 15 22 35.5t6 41.5q0 59-35.5 127T717 922zM358 0q-10 0-19.5 4T322 15q-7 7-11 16.5T307 51v280l-51 34V51q0-10-4-19.5T241 15q-7-7-16.5-11T205 0q-10 0-19.5 4T169 15q-8 7-11.5 16.5T154 51v314l-52-34V51q0-10-3.5-19.5T87 15Q80 8 70.5 4T51 0Q41 0 31.5 4T15 15Q8 22 4 31.5T0 51v307q0 7 1.5 13T6 383q3 5 7.5 9.5T23 401l131 87v485q0 10 3.5 19.5T169 1009q7 7 16.5 11t19.5 4q10 0 19.5-4t16.5-11q7-7 11-16.5t4-19.5V488l131-87q5-4 9-8.5t7-9.5q3-6 5-12t2-13V51q0-10-4-19.5T395 15q-8-7-17-11t-20-4z\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Servings<\/span><p class=\"detail-item-value\">10<\/p><span class=\"detail-item-unit\">servings<\/span><\/div><div class=\"detail-item detail-item-1\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 0C9.62663 0 7.30655 0.703788 5.33316 2.02236C3.35977 3.34094 1.8217 5.21508 0.913451 7.4078C0.00519941 9.60051 -0.232441 12.0133 0.230582 14.3411C0.693605 16.6689 1.83649 18.807 3.51472 20.4853C5.19295 22.1635 7.33115 23.3064 9.65892 23.7694C11.9867 24.2324 14.3995 23.9948 16.5922 23.0865C18.7849 22.1783 20.6591 20.6402 21.9776 18.6668C23.2962 16.6934 24 14.3734 24 12C24 10.4241 23.6896 8.8637 23.0866 7.4078C22.4835 5.95189 21.5996 4.62902 20.4853 3.51472C19.371 2.40041 18.0481 1.5165 16.5922 0.913445C15.1363 0.310389 13.5759 0 12 0ZM12 21.6C10.1013 21.6 8.24524 21.037 6.66653 19.9821C5.08782 18.9272 3.85736 17.4279 3.13076 15.6738C2.40416 13.9196 2.21405 11.9893 2.58447 10.1271C2.95488 8.26491 3.86919 6.55436 5.21178 5.21177C6.55436 3.86919 8.26492 2.95488 10.1271 2.58446C11.9894 2.21404 13.9196 2.40415 15.6738 3.13076C17.4279 3.85736 18.9272 5.08781 19.9821 6.66652C21.037 8.24524 21.6 10.1013 21.6 12C21.6 14.5461 20.5886 16.9879 18.7882 18.7882C16.9879 20.5886 14.5461 21.6 12 21.6ZM15.72 12.756L13.2 11.304V6C13.2 5.68174 13.0736 5.37651 12.8485 5.15147C12.6235 4.92643 12.3183 4.8 12 4.8C11.6817 4.8 11.3765 4.92643 11.1515 5.15147C10.9264 5.37651 10.8 5.68174 10.8 6V12C10.8 12 10.8 12.096 10.8 12.144C10.8071 12.2267 10.8274 12.3077 10.86 12.384C10.8847 12.4552 10.9169 12.5236 10.956 12.588C10.9888 12.6562 11.0291 12.7206 11.076 12.78L11.268 12.936L11.376 13.044L14.496 14.844C14.6789 14.9477 14.8858 15.0014 15.096 15C15.3617 15.0019 15.6205 14.9155 15.8318 14.7544C16.0431 14.5933 16.195 14.3667 16.2637 14.11C16.3323 13.8533 16.3138 13.5811 16.2111 13.3361C16.1083 13.091 15.9272 12.887 15.696 12.756H15.72Z\" fill=\"currentColor\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Prep time<\/span><p class=\"detail-item-value\">30<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><div class=\"detail-item detail-item-2\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg viewbox=\"0 0 512.0016 512.0155\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 278.014q1 34-21 46-13 6-30 5v84q0 41-28 70t-70 29H151q-42 0-72-29t-30-70v-84q-16 1-28-5-22-12-21-46 0-8 7-11.5t13.5 0q6.5 3.5 5.5 11.5 0 18 8 23 5 3 15 2v-52q15 11 62 19 60 9 145.5 9t149.5-10q38-6 55-14v48q11 1 17-2 8-5 8-23-1-8 5.5-11.5t13.5 0q7 3.5 7 11.5zm-150 193q29-10 43-37t13.5-57q-.5-30-.5-60v-12q-1-10-10-14.5t-17.5 0q-8.5 4.5-8.5 14.5 1 5 2 21t1.5 26q.5 10-1 26t-4.5 26.5q-3 10.5-10 20t-17 13.5q-10 3-12 13t4.5 17q6.5 7 16.5 3zm-310-237q0-12 .5-16.5t6-13q5.5-8.5 16.5-13t33.5-8.5q22.5-4 56.5-6-11 3-10 15 0 6 4 10t11 4h1q28-1 49-21l5-4q3-4 6-7h25q23 0 44 1 2 1 5 4l6 6q21 20 49 21h1q7 0 11-4t4-10q1-9-7-14 35 3 56 8t29.5 13.5q8.5 8.5 10 14.5t1.5 19q0 3-5 6-15 12-73.5 19.5t-131.5 7.5q-75 0-132-7.5t-69-19.5q-3-2-3-5zm158-73q4-3 6-5 13-11 29-13l.5-.5.5-.5q3 0 8-1h18q5 0 6.5.5t5.5 1.5h4q15 3 27 13l6 6q1 0 2 1t1 2q3 2 5 4 4 4 8 7 11 7 24 8 9 1 8 8l-4 6v4l-3-4q-27-2-45-19l-4-4q-1-2-2-2l-5-5q-5-4-9-7-7-3-17-5h-1q-3-1-5-1-4-1-8-1h-12q-3 0-5 1-8 1-15 6-4 3-8 7-3 3-7 6l-4 5q-19 17-44 19-4 0-5.5-2t-1.5-4q0-8 7-8 13-1 24-9 4-3 8-7 2-1 4-3 1-1 3-4zm-53-157q4-5 9.5-3t7.5 7.5q2 5.5-2 11.5-5 7-5 13.5t3 11l8 12q5 7.5 7 11.5 12 25 0 50-3 6-8.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3-15.5t-4.5-13.5q-2.5-5-8-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 7.5 12t7 11.5q13 25 1 50-4 6-9.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 8 12t7.5 11.5q12 25 0 50-4 6-9.5 6t-9-5.5q-3.5-5.5-1.5-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-10-24 8-48z\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Cooking time<\/span><p class=\"detail-item-value\">2<\/p><span class=\"detail-item-unit\">hours&nbsp;<\/span><\/div><\/div>\n\t\t<\/div>\n\t\t\n\t\n\t\n    \t\t        <div class=\"wpzoom-nosleep-toggle-container\">\n            <label class=\"switch\">\n\t\t\t\t<input type=\"checkbox\" id=\"toggle_button\">\n                <div class=\"slider round\"><\/div>\n            <\/label>\n                                <span class=\"wpzoom-nosleep-label\">Cook Mode<\/span>\n                                            <p class=\"recipe-card-no-sleep no-print\">Permet \u00e0 la recette de rester visible plus longtemps<\/p>\n                    <\/div>\n    \n\t\t\n\t\t\t<div class=\"recipe-card-ingredients\">\n            \t\t\t\n\t\t\t<h3 class=\"ingredients-title\">Ingr\u00e9dients<\/h3>\n            \t\t\t<ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-1674124698180243\" class=\"ingredient-item ingredient-item-group\"><strong class=\"ingredient-item-group-title\">Pour la p\u00e2te sabl\u00e9e :<\/strong><\/li><li id=\"wpzoom-rcb-ingredient-item-63c91d36c368c\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">200<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">beurre pommade<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-63c91d36c368d\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">60<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">lait concentr\u00e9 sucr\u00e9<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-63c91d36c368e\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">oeuf entier + 1 jaune pour la dorure<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-63c91d36c368f\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">300<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">farine<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-1674124758918712\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">3<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">c<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">uillers \u00e0 soupe sucre<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-1674124770037813\" class=\"ingredient-item ingredient-item-group\"><strong class=\"ingredient-item-group-title\">Pour le confit d'ananas :<\/strong><\/li><li id=\"wpzoom-rcb-ingredient-item-1674124785469922\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">ananas  \/ ou \u00e0 d\u00e9faut de l'ananas en conserve1\/3 de son poids en sucre (\u00e0 ajuster au go\u00fbt pendant la cuisson - ce n'est pas une science exacte, cela d\u00e9pend de la maturit\u00e9 et du taux de sucre de l'ananas) \/ 1\/4 de son poids en sucre si vous utilisez de l'ananas en conserve<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16741248228061291\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">anis \u00e9toil\u00e9<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16741248309231356\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">b\u00e2ton de cannelle<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16741248403421445\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">cl<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">ou de girofle<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16741248510421534\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">filet de jus de citron<\/span>  <\/p><\/li><\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t<div class=\"recipe-card-directions\">\n\t\t\t<h3 class=\"directions-title\">Instructions<\/h3>\n\t\t\t<ul class=\"directions-list\"><li id=\"wpzoom-rcb-direction-step-16741249042142007\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour le confit d'ananas (peut \u00eatre fait plusieurs jours \u00e0 l'avance) :<\/strong><\/li><li id=\"wpzoom-rcb-direction-step-63c91d36c3693\" class=\"direction-step\">Peler l'ananas, le d\u00e9couper, enlever la partie int\u00e9rieure fibreuse et le d\u00e9couper en morceaux<\/li><li id=\"wpzoom-rcb-direction-step-63c91d36c3694\" class=\"direction-step\">Le mixer finement<\/li><li id=\"wpzoom-rcb-direction-step-63c91d36c3695\" class=\"direction-step\">Ajouter les \u00e9pices (anis \u00e9toil\u00e9, cannelle, clou de girofle)<\/li><li id=\"wpzoom-rcb-direction-step-63c91d36c3696\" class=\"direction-step\">Faire chauffer \u00e0 feu moyen en remuant r\u00e9guli\u00e8rement une vingtaine de minutes<\/li><li id=\"wpzoom-rcb-direction-step-16741250560773400\" class=\"direction-step\">Ajouter alors le sucre, baisser le feu et continuer la cuisson en remuant r\u00e9guli\u00e8rement afin que le confit n'attache pas. En fonction de la quantit\u00e9 de jus de votre ananas, cette \u00e9tape peut durer de 1 heure \u00e0 2 heures . C'est \u00e0 la fin de la cuisson qu'il faut le plus remuer car il reste tr\u00e8s peu de liquide. Pour vous donner une id\u00e9e de la consistance, voici celle d'un confit d'ananas achet\u00e9 - celui fait \u00e0 la maison sera l\u00e9g\u00e8rement plus mou, mais suffisamment solide pour en fa\u00e7onner des billes ensuite<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/confit-dananas-en-bille.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/confit-dananas-en-bille.jpeg\" class=\"direction-step-image no-print\" alt=\"Bille de confit d'ananas pour les mini tartelettes ananas\" title=\"confit d'ananas en bille\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-16741251572524665\" class=\"direction-step\">Le confit d'ananas est donc pr\u00eat lorsqu'on ne voit plus de liquide et qu'il a pris une texture solide. Couper alors le feu, ajouter le jus de citron et placer au frais dans une bo\u00eete herm\u00e9tique (apr\u00e8s refroidissement bien sur). <\/li><li id=\"wpzoom-rcb-direction-step-16741252205735626\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour la p\u00e2te sabl\u00e9e :<\/strong><\/li><li id=\"wpzoom-rcb-direction-step-16741252336745707\" class=\"direction-step\">M\u00e9langer le beurre pommade, le lait concentr\u00e9, le sucre et l'oeuf entier (attention, pas le jaune d'oeuf car il est r\u00e9serv\u00e9 \u00e0 la dorure). Vous pouvez utiliser un fouet sans probl\u00e8me<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-beurre-pommade.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-beurre-pommade.jpeg\" class=\"direction-step-image no-print\" alt=\"m\u00e9lange beurre\" title=\"mini tartelettes ananas beurre pommade\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-16741254299397388\" class=\"direction-step\">Ajouter la farine et amalgamer. Ne pas chercher \u00e0 avoir une belle boule de p\u00e2te, il vaut mieux ne pas trop travailler la farine<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-amalgame.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-amalgame.jpeg\" class=\"direction-step-image no-print\" alt=\"\" title=\"mini tartelettes ananas amalgame\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-16741254894118129\" class=\"direction-step\">Placer dans un film cellophane puis au r\u00e9frig\u00e9rateur au minimum 30 minimum (ou au cong\u00e9lateur si vous voulez aller plus vite)<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-pate.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"223\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-pate.jpeg\" class=\"direction-step-image no-print\" alt=\"\" title=\"mini tartelettes ananas p\u00e2te\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-16741256816799283\" class=\"direction-step\">Enduire le plan de travail ainsi qu'un rouleau \u00e0 p\u00e2tisserie de farine, \u00e9taler la p\u00e2te sur une hauteur de 5 \u00e0 7 mm (il faut que ce soit un peu \u00e9pais... mais pas trop !)<\/li><li id=\"wpzoom-rcb-direction-step-16741255284658658\" class=\"direction-step\">A l'aide d'un emporte pi\u00e8ce, ou encore mieux d'une presse \u00e0 cookie (avec une forme l\u00e9g\u00e8rement \u00e9vid\u00e9e au centre si possible), d\u00e9couper les formes dans la p\u00e2te et les d\u00e9poser au fur et \u00e0 mesure sur une feuille de papier sulfuris\u00e9 ou de silicone. Si la p\u00e2te accroche un peu, est trop souple pour \u00eatre travaill\u00e9e, la remettre au frais quelques minutes<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-pompe-cookies.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-pompe-cookies.jpeg\" class=\"direction-step-image no-print\" alt=\"utilisation presse \u00e0 cookies\" title=\"mini tartelettes ananas pompe cookies\" style=\"\"\/><\/a><a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-faconnage.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-faconnage.jpeg\" class=\"direction-step-image no-print\" alt=\"apr\u00e8s utilisation presse \u00e0 cookies\" title=\"mini tartelettes ananas fa\u00e7onnage\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-16741256830379288\" class=\"direction-step\">M\u00e9langer le jaune d'oeuf avec une grosse cuiller \u00e0 soupe d'eau. En enduire les mini tartelettes<\/li><li id=\"wpzoom-rcb-direction-step-167412588017811349\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour les mini tartelettes :<\/strong><\/li><li id=\"wpzoom-rcb-direction-step-167412589589711462\" class=\"direction-step\">Faire des petites boules de la taille d'une bille avec la p\u00e2te d'ananas confit. Moins la p\u00e2te est humide, plus elle est facile \u00e0 travailler<\/li><li id=\"wpzoom-rcb-direction-step-167412595109912111\" class=\"direction-step\">Les d\u00e9poser sur les mini tartelettes<a class=\"direction-step-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-avant-cuisson.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas-avant-cuisson.jpeg\" class=\"direction-step-image no-print\" alt=\"les mini tartelettes ananas pr\u00eates \u00e0 \u00eatre enfourn\u00e9es\" title=\"mini tartelettes ananas avant cuisson\" style=\"\"\/><\/a><\/li><li id=\"wpzoom-rcb-direction-step-167412596811712268\" class=\"direction-step\">Cuire au four th. 160\u00b0 environ 20 minutes, ou jusqu'\u00e0 ce que les mini tartelettes soient l\u00e9g\u00e8rement dor\u00e9es<\/li><\/ul>\n\t\t<\/div>\n\t\n\t\t\t\n\t\n\t\n\t\t\t<div class=\"recipe-card-notes\">\n\t\t\t<h3 class=\"notes-title\">La p'tite astuce Minute Papillote<\/h3>\n\t\t\t<ul class=\"recipe-card-notes-list\"><li>Si vous voulez optimiser votre timing, vous pouvez pr\u00e9parer les billes de p\u00e2te d'ananas pendant que la p\u00e2te sabl\u00e9e repose au frais. Vous les d\u00e9poserez alors sur une assiette, elles ne colleront pas <\/li><li>Si vous r\u00e9sidez \u00e0 Singapour, mais aussi dans d'autres pays du sud-est asiatique, vous pourrez trouver dans les supermarch\u00e9s de la \"pineapple paste filling\" d\u00e9j\u00e0 toute pr\u00eate. Toujours un peu moins bon que fait maison - mais tellement pratique !<\/li><\/ul>\n\t\t<\/div>\n\t\n\t\n\t\n\t\n\t\n\t\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\n    \t\n\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Mini tartelettes ananas du Nouvel An chinois\",\"image\":[\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-500x500.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-500x375.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-480x270.jpeg\"],\"description\":\"\",\"keywords\":\"Cookies, fruits, gouter\",\"author\":{\"@type\":\"Person\",\"name\":\"Helene\"},\"datePublished\":\"2023-01-25T05:15:52+02:00\",\"prepTime\":\"PT30M\",\"cookTime\":\"PT2H\",\"totalTime\":\"PT2H30M\",\"recipeCategory\":[\"Du sucr\\u00e9\",\"Inspiration Asie\"],\"recipeCuisine\":[],\"recipeYield\":[\"10\",\"10 servings\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"200 g beurre pommade\",\"60 g lait concentr\\u00e9 sucr\\u00e9\",\"1  oeuf entier + 1 jaune pour la dorure\",\"300 g farine\",\"3 c uillers \\u00e0 soupe sucre\",\"1  ananas  \\\/ ou \\u00e0 d\\u00e9faut de l'ananas en conserve1\\\/3 de son poids en sucre (\\u00e0 ajuster au go\\u00fbt pendant la cuisson - ce n'est pas une science exacte, cela d\\u00e9pend de la maturit\\u00e9 et du taux de sucre de l'ananas) \\\/ 1\\\/4 de son poids en sucre si vous utilisez de l'ananas en conserve\",\"1  anis \\u00e9toil\\u00e9\",\"1  b\\u00e2ton de cannelle\",\"1 cl ou de girofle\",\"1  filet de jus de citron\"],\"recipeInstructions\":[{\"@type\":\"HowToSection\",\"name\":\"Pour le confit d'ananas (peut \\u00eatre fait plusieurs jours \\u00e0 l'avance) :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Peler l'ananas, le d\\u00e9couper, enlever la partie int\\u00e9rieure fibreuse et le d\\u00e9couper en morceaux\",\"text\":\"Peler l'ananas, le d\\u00e9couper, enlever la partie int\\u00e9rieure fibreuse et le d\\u00e9couper en morceaux\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-63c91d36c3693\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Le mixer finement\",\"text\":\"Le mixer finement\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-63c91d36c3694\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Ajouter les \\u00e9pices (anis \\u00e9toil\\u00e9, cannelle, clou de girofle)\",\"text\":\"Ajouter les \\u00e9pices (anis \\u00e9toil\\u00e9, cannelle, clou de girofle)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-63c91d36c3695\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Faire chauffer \\u00e0 feu moyen en remuant r\\u00e9guli\\u00e8rement une vingtaine de minutes\",\"text\":\"Faire chauffer \\u00e0 feu moyen en remuant r\\u00e9guli\\u00e8rement une vingtaine de minutes\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-63c91d36c3696\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Ajouter alors le sucre, baisser le feu et continuer la cuisson en remuant r\\u00e9guli\\u00e8rement afin que le confit n'attache pas. En fonction de la quantit\\u00e9 de jus de votre ananas, cette \\u00e9tape peut durer de 1 heure \\u00e0 2 heures . C'est \\u00e0 la fin de la cuisson qu'il faut le plus remuer car il reste tr\\u00e8s peu de liquide. Pour vous donner une id\\u00e9e de la consistance, voici celle d'un confit d'ananas achet\\u00e9 - celui fait \\u00e0 la maison sera l\\u00e9g\\u00e8rement plus mou, mais suffisamment solide pour en fa\\u00e7onner des billes ensuite\",\"text\":\"Ajouter alors le sucre, baisser le feu et continuer la cuisson en remuant r\\u00e9guli\\u00e8rement afin que le confit n'attache pas. En fonction de la quantit\\u00e9 de jus de votre ananas, cette \\u00e9tape peut durer de 1 heure \\u00e0 2 heures . C'est \\u00e0 la fin de la cuisson qu'il faut le plus remuer car il reste tr\\u00e8s peu de liquide. Pour vous donner une id\\u00e9e de la consistance, voici celle d'un confit d'ananas achet\\u00e9 - celui fait \\u00e0 la maison sera l\\u00e9g\\u00e8rement plus mou, mais suffisamment solide pour en fa\\u00e7onner des billes ensuite\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741250560773400\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/confit-dananas-en-bille.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"Le confit d'ananas est donc pr\\u00eat lorsqu'on ne voit plus de liquide et qu'il a pris une texture solide. Couper alors le feu, ajouter le jus de citron et placer au frais dans une bo\\u00eete herm\\u00e9tique (apr\\u00e8s refroidissement bien sur).\",\"text\":\"Le confit d'ananas est donc pr\\u00eat lorsqu'on ne voit plus de liquide et qu'il a pris une texture solide. Couper alors le feu, ajouter le jus de citron et placer au frais dans une bo\\u00eete herm\\u00e9tique (apr\\u00e8s refroidissement bien sur).\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741251572524665\",\"image\":\"\"}]},{\"@type\":\"HowToSection\",\"name\":\"Pour la p\\u00e2te sabl\\u00e9e :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"M\\u00e9langer le beurre pommade, le lait concentr\\u00e9, le sucre et l'oeuf entier (attention, pas le jaune d'oeuf car il est r\\u00e9serv\\u00e9 \\u00e0 la dorure). Vous pouvez utiliser un fouet sans probl\\u00e8me\",\"text\":\"M\\u00e9langer le beurre pommade, le lait concentr\\u00e9, le sucre et l'oeuf entier (attention, pas le jaune d'oeuf car il est r\\u00e9serv\\u00e9 \\u00e0 la dorure). Vous pouvez utiliser un fouet sans probl\\u00e8me\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741252336745707\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-beurre-pommade.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"Ajouter la farine et amalgamer. Ne pas chercher \\u00e0 avoir une belle boule de p\\u00e2te, il vaut mieux ne pas trop travailler la farine\",\"text\":\"Ajouter la farine et amalgamer. Ne pas chercher \\u00e0 avoir une belle boule de p\\u00e2te, il vaut mieux ne pas trop travailler la farine\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741254299397388\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-amalgame.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"Placer dans un film cellophane puis au r\\u00e9frig\\u00e9rateur au minimum 30 minimum (ou au cong\\u00e9lateur si vous voulez aller plus vite)\",\"text\":\"Placer dans un film cellophane puis au r\\u00e9frig\\u00e9rateur au minimum 30 minimum (ou au cong\\u00e9lateur si vous voulez aller plus vite)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741254894118129\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-pate.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"Enduire le plan de travail ainsi qu'un rouleau \\u00e0 p\\u00e2tisserie de farine, \\u00e9taler la p\\u00e2te sur une hauteur de 5 \\u00e0 7 mm (il faut que ce soit un peu \\u00e9pais... mais pas trop !)\",\"text\":\"Enduire le plan de travail ainsi qu'un rouleau \\u00e0 p\\u00e2tisserie de farine, \\u00e9taler la p\\u00e2te sur une hauteur de 5 \\u00e0 7 mm (il faut que ce soit un peu \\u00e9pais... mais pas trop !)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741256816799283\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"A l'aide d'un emporte pi\\u00e8ce, ou encore mieux d'une presse \\u00e0 cookie (avec une forme l\\u00e9g\\u00e8rement \\u00e9vid\\u00e9e au centre si possible), d\\u00e9couper les formes dans la p\\u00e2te et les d\\u00e9poser au fur et \\u00e0 mesure sur une feuille de papier sulfuris\\u00e9 ou de silicone. Si la p\\u00e2te accroche un peu, est trop souple pour \\u00eatre travaill\\u00e9e, la remettre au frais quelques minutes\",\"text\":\"A l'aide d'un emporte pi\\u00e8ce, ou encore mieux d'une presse \\u00e0 cookie (avec une forme l\\u00e9g\\u00e8rement \\u00e9vid\\u00e9e au centre si possible), d\\u00e9couper les formes dans la p\\u00e2te et les d\\u00e9poser au fur et \\u00e0 mesure sur une feuille de papier sulfuris\\u00e9 ou de silicone. Si la p\\u00e2te accroche un peu, est trop souple pour \\u00eatre travaill\\u00e9e, la remettre au frais quelques minutes\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741255284658658\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-faconnage.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"M\\u00e9langer le jaune d'oeuf avec une grosse cuiller \\u00e0 soupe d'eau. En enduire les mini tartelettes\",\"text\":\"M\\u00e9langer le jaune d'oeuf avec une grosse cuiller \\u00e0 soupe d'eau. En enduire les mini tartelettes\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-16741256830379288\",\"image\":\"\"}]},{\"@type\":\"HowToSection\",\"name\":\"Pour les mini tartelettes :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Faire des petites boules de la taille d'une bille avec la p\\u00e2te d'ananas confit. Moins la p\\u00e2te est humide, plus elle est facile \\u00e0 travailler\",\"text\":\"Faire des petites boules de la taille d'une bille avec la p\\u00e2te d'ananas confit. Moins la p\\u00e2te est humide, plus elle est facile \\u00e0 travailler\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-167412589589711462\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Les d\\u00e9poser sur les mini tartelettes\",\"text\":\"Les d\\u00e9poser sur les mini tartelettes\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-167412595109912111\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas-avant-cuisson.jpeg\"},{\"@type\":\"HowToStep\",\"name\":\"Cuire au four th. 160\\u00b0 environ 20 minutes, ou jusqu'\\u00e0 ce que les mini tartelettes soient l\\u00e9g\\u00e8rement dor\\u00e9es\",\"text\":\"Cuire au four th. 160\\u00b0 environ 20 minutes, ou jusqu'\\u00e0 ce que les mini tartelettes soient l\\u00e9g\\u00e8rement dor\\u00e9es\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/mini-tartelettes-ananas\\\/#wpzoom-rcb-direction-step-167412596811712268\",\"image\":\"\"}]}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"ratingCount\":3}}<\/script>\n\t<\/div><!-- \/.wp-block-wpzoom-recipe-card-block-recipe-card -->\n\n<style id=\"wpzoom-rcb-block-template-default-inline-css\" type=\"text\/css\">\n\t.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .details-items .detail-item .detail-item-icon {\n                color: #222222;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .details-items .detail-item .detail-item-icon svg path {\n                fill: #222222;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes .recipe-card-notes-list>li::before {\n                border-color: #222222;\n                color: #222222;\n            }.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients {\n                background-color: #FBF9E7;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes .recipe-card-notes-list > li {\n                background-color: #FBF9E7;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default {\n                background-color: #FFFFFF !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients .ingredients-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-directions,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-directions .directions-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-title {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes .recipe-card-notes-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .ingredients-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .directions-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .video-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .equipment-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .notes-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .nutrition-title {\n                color: #333333 !important;\n            }\n<\/style><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30aedc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30aedc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-14b96bdc\" data-id=\"14b96bdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64380a8a elementor-widget elementor-widget-text-editor\" data-id=\"64380a8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>En pleine pr\u00e9paration de Nouvel An chinois ? Essayez aussi ces <a href=\"https:\/\/www.minutepapillote.com\/biscuits-cacahuete\/\">biscuits \u00e0 la cacahu\u00e8te<\/a>, tout \u00e0 fait dans le th\u00e8me. Avec des cacahu\u00e8tes enti\u00e8res ou au beurre de cacahu\u00e8tes, c&rsquo;est vous qui choisissez.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f94f199\" data-id=\"2f94f199\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29200f9f elementor-widget elementor-widget-image\" data-id=\"29200f9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2.jpeg\" class=\"attachment-large size-large wp-image-8602\" alt=\"D\u00e9licieux biscuits cacahu\u00e8te !\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2.jpeg 1200w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2-300x225.jpeg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2-768x576.jpeg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2-750x563.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/biscuits-cacahuete-2-500x375.jpeg 500w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2979681c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2979681c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cd96d32\" data-id=\"4cd96d32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a2ba493 elementor-widget elementor-widget-spacer\" data-id=\"4a2ba493\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e73fa4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e73fa4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-41794f35\" data-id=\"41794f35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b1608d2 elementor-widget elementor-widget-text-editor\" data-id=\"3b1608d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Ou bien encore ces d\u00e9licieux <a href=\"https:\/\/www.minutepapillote.com\/sables-cardamome\/\">biscuits \u00e0 la cardamome<\/a> &#8211; l\u00e0 aussi, une tr\u00e8s belle rencontre entre Orient et Occident !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-74be6af6\" data-id=\"74be6af6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15997c53 elementor-widget elementor-widget-image\" data-id=\"15997c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"531\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/sables-a-la-cardamome-recette-750x531.jpeg\" class=\"attachment-large size-large wp-image-7116\" alt=\"les sabl\u00e9s en gros plan pour la recette\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas. \u00a0Avec une p\u00e2te sabl\u00e9e croustillante, un confit d&rsquo;ananas qui fond en bouche&#8230; des petites gourmandises\u00a0passionn\u00e9ment addictives &#8211; et tellement amusantes \u00e0 faire ! Aller \u00e0 la recette Des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41,411],"tags":[123,132,133],"class_list":["post-8593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucre","category-asie","tag-cookies","tag-fruits","tag-gouter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mini tartelettes ananas du Nouvel An chinois - Minute Papillote<\/title>\n<meta name=\"description\" content=\"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mini tartelettes ananas du Nouvel An chinois\" \/>\n<meta property=\"og:description\" content=\"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/\" \/>\n<meta property=\"og:site_name\" content=\"Minute Papillote\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T04:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T14:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/\"},\"author\":{\"name\":\"Helene\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"headline\":\"Mini tartelettes ananas du Nouvel An chinois\",\"datePublished\":\"2023-01-25T04:15:52+00:00\",\"dateModified\":\"2024-02-07T14:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/\"},\"wordCount\":1422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas.jpeg\",\"keywords\":[\"Cookies\",\"fruits\",\"gouter\"],\"articleSection\":[\"Du sucr\u00e9\",\"Inspiration Asie\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/\",\"name\":\"Mini tartelettes ananas du Nouvel An chinois - Minute Papillote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas.jpeg\",\"datePublished\":\"2023-01-25T04:15:52+00:00\",\"dateModified\":\"2024-02-07T14:04:38+00:00\",\"description\":\"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mini-tartelettes-ananas.jpeg\",\"width\":1200,\"height\":900,\"caption\":\"mini tartelettes ananas traditionnelles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/mini-tartelettes-ananas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.minutepapillote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mini tartelettes ananas du Nouvel An chinois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/\",\"name\":\"MinutePapillote\",\"description\":\"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minutepapillote.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\",\"name\":\"Helene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"width\":498,\"height\":245,\"caption\":\"Helene\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\"},\"sameAs\":[\"https:\\\/\\\/www.minutepapillote.com\",\"https:\\\/\\\/www.instagram.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ-l3TtP5ifNkp2Cb_ZmIkw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mini tartelettes ananas du Nouvel An chinois - Minute Papillote","description":"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/","og_locale":"en_US","og_type":"article","og_title":"Mini tartelettes ananas du Nouvel An chinois","og_description":"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !","og_url":"https:\/\/www.minutepapillote.com\/en\/mini-tartelettes-ananas\/","og_site_name":"Minute Papillote","article_published_time":"2023-01-25T04:15:52+00:00","article_modified_time":"2024-02-07T14:04:38+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg","type":"image\/jpeg"}],"author":"Helene","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#article","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/"},"author":{"name":"Helene","@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"headline":"Mini tartelettes ananas du Nouvel An chinois","datePublished":"2023-01-25T04:15:52+00:00","dateModified":"2024-02-07T14:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/"},"wordCount":1422,"commentCount":0,"publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"image":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg","keywords":["Cookies","fruits","gouter"],"articleSection":["Du sucr\u00e9","Inspiration Asie"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/","url":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/","name":"Mini tartelettes ananas du Nouvel An chinois - Minute Papillote","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#primaryimage"},"image":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg","datePublished":"2023-01-25T04:15:52+00:00","dateModified":"2024-02-07T14:04:38+00:00","description":"De jolis soleils rayonnants pour c\u00e9l\u00e9brer les f\u00eates du Nouvel An chinois avec ces mini tartelettes ananas !","breadcrumb":{"@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#primaryimage","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/01\/mini-tartelettes-ananas.jpeg","width":1200,"height":900,"caption":"mini tartelettes ananas traditionnelles"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minutepapillote.com\/mini-tartelettes-ananas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.minutepapillote.com\/"},{"@type":"ListItem","position":2,"name":"Mini tartelettes ananas du Nouvel An chinois"}]},{"@type":"WebSite","@id":"https:\/\/www.minutepapillote.com\/#website","url":"https:\/\/www.minutepapillote.com\/","name":"MinutePapillote","description":"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs","publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minutepapillote.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c","name":"Helene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","width":498,"height":245,"caption":"Helene"},"logo":{"@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png"},"sameAs":["https:\/\/www.minutepapillote.com","https:\/\/www.instagram.com\/helene_minutepapillote\/","https:\/\/www.pinterest.com\/helene_minutepapillote\/","https:\/\/www.youtube.com\/channel\/UCJ-l3TtP5ifNkp2Cb_ZmIkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/8593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/comments?post=8593"}],"version-history":[{"count":0,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/8593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media\/8611"}],"wp:attachment":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media?parent=8593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/categories?post=8593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/tags?post=8593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}