{"id":7964,"date":"2022-05-20T11:27:53","date_gmt":"2022-05-20T10:27:53","guid":{"rendered":"https:\/\/www.minutepapillote.com\/?p=7964"},"modified":"2024-06-12T09:03:35","modified_gmt":"2024-06-12T08:03:35","slug":"chou-fleur-tahini-grenade","status":"publish","type":"post","link":"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/","title":{"rendered":"Chou-fleur grill\u00e9 sauce tahini et grenade"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7964\" class=\"elementor elementor-7964\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a163ce0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a163ce0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bec88fd\" data-id=\"1bec88fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15cbdb3c elementor-widget elementor-widget-text-editor\" data-id=\"15cbdb3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Voici le chou-fleur grill\u00e9 sauce tahini, ou <strong>l&rsquo;autre fa\u00e7on de manger du chou-fleur<\/strong> \ud83d\ude0a. Je vous propose ici un plat <strong>pr\u00e9par\u00e9 en un rien de temps<\/strong>,<strong> simple<\/strong> et <strong>qui ravit tous les\u00a0<\/strong><b>convives<\/b>. Un plat de semaine, <strong>savoureux<\/strong> et <strong>vegan<\/strong>. Avec cette recette, on cuisine pour toute la famille<strong>\u00a0de quoi se faire du bien sans se casser la t\u00eate<\/strong>. Et \u00e7a, chez Minute Papillote, <strong>on adore<\/strong> !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9aea7f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aea7f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79c40811\" data-id=\"79c40811\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8acfe8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f8acfe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ma_petite_recette\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aller \u00e0 la recette<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-503842b1 elementor-widget elementor-widget-spacer\" data-id=\"503842b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e137280 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e137280\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee1eec0\" data-id=\"ee1eec0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dc53835 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dc53835\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b5bc53a\" data-id=\"7b5bc53a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c1dc54 elementor-widget elementor-widget-heading\" data-id=\"6c1dc54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">L&#039;article en un coup d&#039;oeil :<\/span>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #f4926a;color:#f4926a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #f4926a;color:#f4926a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/#Le_chou-fleur_grille_sauce_tahini_lautre_facon_de_manger_du_chou-fleur\" >Le chou-fleur grill\u00e9 sauce tahini, l'autre fa\u00e7on de manger du chou-fleur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/#Chou-fleur_grille_sauce_tahini_et_grenade\" >Chou-fleur grill\u00e9 sauce tahini et grenade<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Le_chou-fleur_grille_sauce_tahini_lautre_facon_de_manger_du_chou-fleur\"><\/span>Le chou-fleur grill\u00e9 sauce tahini, l'autre fa\u00e7on de manger du chou-fleur<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3480531e elementor-widget elementor-widget-text-editor\" data-id=\"3480531e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Exit les souvenirs d&rsquo;enfance et de cantine, ces reminiscences de l\u00e9gume tout mou et de sauce b\u00e9chamel insipide&#8230; \u00e7a vous parle ? Tout \u00e7a, c&rsquo;est termin\u00e9, et on est bien content (enfin pour moi en tous cas, c&rsquo;est s\u00fbr &#8211; et pour vous ?). On passe donc \u00e0 autre chose, en cuisant le chou-fleur non plus \u00e0 l&rsquo;eau mais au four. Le go\u00fbt n&rsquo;est pas oubli\u00e9 non plus ; on ajoute de la saveur, de l&rsquo;exotisme, du voyage : du s\u00e9same, du cumin, de la grenade&#8230; Et on sert ce chou-fleur r\u00f4ti sauce tahini en\u00a0<strong>plat complet<\/strong> avec des pois chiche ou du boulgour, <strong>en toute simplicit\u00e9&#8230; et gourmandise !<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33226e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33226e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec4c149\" data-id=\"ec4c149\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-748d4c2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"748d4c2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67715447\" data-id=\"67715447\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32a2c234 elementor-widget elementor-widget-menu-anchor\" data-id=\"32a2c234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ma_petite_recette\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-266b5b7 elementor-widget elementor-widget-image\" data-id=\"266b5b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"360\" height=\"480\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\" class=\"attachment-loop-portrait size-loop-portrait wp-image-7985\" alt=\"un plat complet parfait pour un diner de semaine\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194-225x300.jpeg 225w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Le chou-fleur grill\u00e9 : une autre fa\u00e7on de manger du chou-fleur<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a7b4aa elementor-widget elementor-widget-wpzoom-elementor-recipe-card-widget\" data-id=\"43a7b4aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;recipe_card_styles&quot;:&quot;is-style-newdesign&quot;,&quot;video_type&quot;:&quot;embed&quot;}\" data-widget_type=\"wpzoom-elementor-recipe-card-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"wpzoom-premium-recipe-card\" class=\"wp-block-wpzoom-recipe-card-block-recipe-card is-style-newdesign block-alignment-left header-content-align-left\"><div class=\"recipe-card-image\"><figure><img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/Image-JPEG-53F4EC7E2C40-1-800x530.jpeg\" class=\"wpzoom-recipe-card-image\" alt=\"chou fleur r\u00f4ti d\u00e9licieux\" id=\"7966\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/Image-JPEG-53F4EC7E2C40-1-800x530.jpeg 800w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/Image-JPEG-53F4EC7E2C40-1-e1653050593414-360x240.jpeg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><div class=\"wpzoom-recipe-card-pinit\">\n\t            <a class=\"btn-pinit-link no-print\" data-pin-do=\"buttonPin\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url=https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/&#038;media=https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/Image-JPEG-53F4EC7E2C40-1-e1653050613942.jpeg&#038;description=\" data-pin-custom=\"true\" aria-label=\"Pin recipe on Pinterest\" title=\"Pin recipe on Pinterest\" >\n\t            \t<SVG class=\"wpzoom-rcb-icon-pinit-link\" enable-background=\"new 0 0 30 30\" height=\"30px\" id=\"Pinterest\" version=\"1.1\" viewBox=\"0 0 30 30\" width=\"30px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t            \t    <Path class=\"wpzoom-rcb-pinit-icon\" d=\"M16,0C7.813,0,3,6.105,3,11c0,2.964,2,6,3,6s2,0,2-1s-2-2-2-5c0-4.354,4.773-8,10-8c4.627,0,7,3.224,7,7  c0,4.968-2.735,9-6,9c-1.803,0-3.433-1.172-3-3c0.519-2.184,1-2,2-6c0.342-1.368-0.433-3-2-3c-1.843,0-4,1.446-4,4c0,1.627,1,3,1,3  s-2.245,7.863-2.576,9.263C7.766,26.049,6.938,30,7.938,30S10,28,12,23c0.295-0.738,1-3,1-3c0.599,1.142,3.14,2,5,2  c5.539,0,9-5.24,9-12C27,4.888,22.58,0,16,0z\" \/>\n\t            \t<\/SVG>\n\t            \t<span>Pin<\/span>\n\t            <\/a>\n\t        <\/div><div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link elementor-rcb-print-button no-print\" href=\"#\">\n                <svg class=\"wpzoom-rcb-icon-print-link\" width=\"32\" height=\"32\" viewBox=\"0 0 19 18\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M5 7.2C4.822 7.2 4.64799 7.25278 4.49999 7.35168C4.35198 7.45057 4.23663 7.59113 4.16851 7.75558C4.10039 7.92004 4.08257 8.101 4.11729 8.27558C4.15202 8.45016 4.23774 8.61053 4.3636 8.7364C4.48947 8.86226 4.64984 8.94798 4.82442 8.98271C4.999 9.01743 5.17996 8.99961 5.34441 8.93149C5.50887 8.86337 5.64943 8.74802 5.74832 8.60001C5.84722 8.45201 5.9 8.278 5.9 8.1C5.9 7.8613 5.80518 7.63239 5.6364 7.4636C5.46761 7.29482 5.23869 7.2 5 7.2ZM15.8 3.6H14.9V0.9C14.9 0.661305 14.8052 0.432387 14.6364 0.263604C14.4676 0.0948211 14.2387 0 14 0H5C4.76131 0 4.53239 0.0948211 4.3636 0.263604C4.19482 0.432387 4.1 0.661305 4.1 0.9V3.6H3.2C2.48392 3.6 1.79716 3.88446 1.29081 4.39081C0.784464 4.89716 0.5 5.58392 0.5 6.3V11.7C0.5 12.4161 0.784464 13.1028 1.29081 13.6092C1.79716 14.1155 2.48392 14.4 3.2 14.4H4.1V17.1C4.1 17.3387 4.19482 17.5676 4.3636 17.7364C4.53239 17.9052 4.76131 18 5 18H14C14.2387 18 14.4676 17.9052 14.6364 17.7364C14.8052 17.5676 14.9 17.3387 14.9 17.1V14.4H15.8C16.5161 14.4 17.2028 14.1155 17.7092 13.6092C18.2155 13.1028 18.5 12.4161 18.5 11.7V6.3C18.5 5.58392 18.2155 4.89716 17.7092 4.39081C17.2028 3.88446 16.5161 3.6 15.8 3.6ZM5.9 1.8H13.1V3.6H5.9V1.8ZM13.1 16.2H5.9V12.6H13.1V16.2ZM16.7 11.7C16.7 11.9387 16.6052 12.1676 16.4364 12.3364C16.2676 12.5052 16.0387 12.6 15.8 12.6H14.9V11.7C14.9 11.4613 14.8052 11.2324 14.6364 11.0636C14.4676 10.8948 14.2387 10.8 14 10.8H5C4.76131 10.8 4.53239 10.8948 4.3636 11.0636C4.19482 11.2324 4.1 11.4613 4.1 11.7V12.6H3.2C2.9613 12.6 2.73239 12.5052 2.5636 12.3364C2.39482 12.1676 2.3 11.9387 2.3 11.7V6.3C2.3 6.0613 2.39482 5.83239 2.5636 5.6636C2.73239 5.49482 2.9613 5.4 3.2 5.4H15.8C16.0387 5.4 16.2676 5.49482 16.4364 5.6636C16.6052 5.83239 16.7 6.0613 16.7 6.3V11.7Z\" \/>\n                    <\/svg>\n\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div><\/figcaption><\/figure><\/div><!-- \/.recipe-card-image --><div class=\"recipe-card-heading\"><h2 class=\"recipe-card-title\"><span class=\"ez-toc-section\" id=\"Chou-fleur_grille_sauce_tahini_et_grenade\"><\/span>Chou-fleur grill\u00e9 sauce tahini et grenade<span class=\"ez-toc-section-end\"><\/span><\/h2><div class=\"recipe-sub-title\"><span class=\"recipe-card-author\">Recipe by Helene<\/span><div class=\"wpzoom-rating-stars-container\" data-rating=\"5.0\" data-rating-total=\"4\" data-recipe-id=\"7964\" data-post-id=\"7964\" data-user-can-rate=\"1\">\n\t\t\t\t<ul class=\"wpzoom-rating-stars\"><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><\/ul><span class=\"wpzoom-rating-stars-average\"><span class=\"wpzoom-rating-average\">5.0<\/span> from <span class=\"wpzoom-rating-total-votes\">4<\/span> votes<\/span>\n\t\t\t\t<em class=\"wpzoom-rating-stars-tooltip\"><\/em>\n\t\t\t<\/div><\/div><\/div><!-- \/.recipe-card-heading --><div class=\"wpzoom-nosleep-toggle-container\">\n        <label class=\"switch\">\n            <input type=\"checkbox\" id=\"toggle_button\">\n            <div class=\"slider round\"><\/div>\n        <\/label><span class=\"wpzoom-nosleep-label\">Cook Mode<\/span><p class=\"recipe-card-no-sleep no-print\">Permet \u00e0 la recette de rester visible plus longtemps<\/p><\/div><div class=\"recipe-card-details\"><div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 1024 1024\"><path d=\"M768 520V51q0-10-4-19.5T753 15q-7-7-16.5-11T717 0q-10 0-19.5 4T681 15q-8 7-11.5 16.5T666 51v469q-34 9-62.5 29T555 596q-21 28-32 61t-11 67q0 40 14 91t40.5 97q26.5 46 64.5 78 38 31 86 31 47 0 85-31 38-32 64.5-78t40.5-97q15-51 15-91 0-34-11-67t-32-61q-21-27-49.5-47T768 520zm-51 402q-31 0-67-68t-36-127q-1-21 6.5-41.5T642 650q15-16 34-25.5t41-10.5q21 1 40.5 10.5T791 650q15 15 22 35.5t6 41.5q0 59-35.5 127T717 922zM358 0q-10 0-19.5 4T322 15q-7 7-11 16.5T307 51v280l-51 34V51q0-10-4-19.5T241 15q-7-7-16.5-11T205 0q-10 0-19.5 4T169 15q-8 7-11.5 16.5T154 51v314l-52-34V51q0-10-3.5-19.5T87 15Q80 8 70.5 4T51 0Q41 0 31.5 4T15 15Q8 22 4 31.5T0 51v307q0 7 1.5 13T6 383q3 5 7.5 9.5T23 401l131 87v485q0 10 3.5 19.5T169 1009q7 7 16.5 11t19.5 4q10 0 19.5-4t16.5-11q7-7 11-16.5t4-19.5V488l131-87q5-4 9-8.5t7-9.5q3-6 5-12t2-13V51q0-10-4-19.5T395 15q-8-7-17-11t-20-4z\" \/><\/svg><\/span><span class=\"detail-item-label\">Servings<\/span><p class=\"detail-item-value\">4<\/p><span class=\"detail-item-unit\">servings<\/span><\/div><div class=\"detail-item detail-item-1\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 0C9.62663 0 7.30655 0.703788 5.33316 2.02236C3.35977 3.34094 1.8217 5.21508 0.913451 7.4078C0.00519941 9.60051 -0.232441 12.0133 0.230582 14.3411C0.693605 16.6689 1.83649 18.807 3.51472 20.4853C5.19295 22.1635 7.33115 23.3064 9.65892 23.7694C11.9867 24.2324 14.3995 23.9948 16.5922 23.0865C18.7849 22.1783 20.6591 20.6402 21.9776 18.6668C23.2962 16.6934 24 14.3734 24 12C24 10.4241 23.6896 8.8637 23.0866 7.4078C22.4835 5.95189 21.5996 4.62902 20.4853 3.51472C19.371 2.40041 18.0481 1.5165 16.5922 0.913445C15.1363 0.310389 13.5759 0 12 0ZM12 21.6C10.1013 21.6 8.24524 21.037 6.66653 19.9821C5.08782 18.9272 3.85736 17.4279 3.13076 15.6738C2.40416 13.9196 2.21405 11.9893 2.58447 10.1271C2.95488 8.26491 3.86919 6.55436 5.21178 5.21177C6.55436 3.86919 8.26492 2.95488 10.1271 2.58446C11.9894 2.21404 13.9196 2.40415 15.6738 3.13076C17.4279 3.85736 18.9272 5.08781 19.9821 6.66652C21.037 8.24524 21.6 10.1013 21.6 12C21.6 14.5461 20.5886 16.9879 18.7882 18.7882C16.9879 20.5886 14.5461 21.6 12 21.6ZM15.72 12.756L13.2 11.304V6C13.2 5.68174 13.0736 5.37651 12.8485 5.15147C12.6235 4.92643 12.3183 4.8 12 4.8C11.6817 4.8 11.3765 4.92643 11.1515 5.15147C10.9264 5.37651 10.8 5.68174 10.8 6V12C10.8 12 10.8 12.096 10.8 12.144C10.8071 12.2267 10.8274 12.3077 10.86 12.384C10.8847 12.4552 10.9169 12.5236 10.956 12.588C10.9888 12.6562 11.0291 12.7206 11.076 12.78L11.268 12.936L11.376 13.044L14.496 14.844C14.6789 14.9477 14.8858 15.0014 15.096 15C15.3617 15.0019 15.6205 14.9155 15.8318 14.7544C16.0431 14.5933 16.195 14.3667 16.2637 14.11C16.3323 13.8533 16.3138 13.5811 16.2111 13.3361C16.1083 13.091 15.9272 12.887 15.696 12.756H15.72Z\" fill=\"currentColor\" \/><\/svg><\/span><span class=\"detail-item-label\">Prep time<\/span><p class=\"detail-item-value\">5<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><div class=\"detail-item detail-item-2\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg viewbox=\"0 0 512.0016 512.0155\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 278.014q1 34-21 46-13 6-30 5v84q0 41-28 70t-70 29H151q-42 0-72-29t-30-70v-84q-16 1-28-5-22-12-21-46 0-8 7-11.5t13.5 0q6.5 3.5 5.5 11.5 0 18 8 23 5 3 15 2v-52q15 11 62 19 60 9 145.5 9t149.5-10q38-6 55-14v48q11 1 17-2 8-5 8-23-1-8 5.5-11.5t13.5 0q7 3.5 7 11.5zm-150 193q29-10 43-37t13.5-57q-.5-30-.5-60v-12q-1-10-10-14.5t-17.5 0q-8.5 4.5-8.5 14.5 1 5 2 21t1.5 26q.5 10-1 26t-4.5 26.5q-3 10.5-10 20t-17 13.5q-10 3-12 13t4.5 17q6.5 7 16.5 3zm-310-237q0-12 .5-16.5t6-13q5.5-8.5 16.5-13t33.5-8.5q22.5-4 56.5-6-11 3-10 15 0 6 4 10t11 4h1q28-1 49-21l5-4q3-4 6-7h25q23 0 44 1 2 1 5 4l6 6q21 20 49 21h1q7 0 11-4t4-10q1-9-7-14 35 3 56 8t29.5 13.5q8.5 8.5 10 14.5t1.5 19q0 3-5 6-15 12-73.5 19.5t-131.5 7.5q-75 0-132-7.5t-69-19.5q-3-2-3-5zm158-73q4-3 6-5 13-11 29-13l.5-.5.5-.5q3 0 8-1h18q5 0 6.5.5t5.5 1.5h4q15 3 27 13l6 6q1 0 2 1t1 2q3 2 5 4 4 4 8 7 11 7 24 8 9 1 8 8l-4 6v4l-3-4q-27-2-45-19l-4-4q-1-2-2-2l-5-5q-5-4-9-7-7-3-17-5h-1q-3-1-5-1-4-1-8-1h-12q-3 0-5 1-8 1-15 6-4 3-8 7-3 3-7 6l-4 5q-19 17-44 19-4 0-5.5-2t-1.5-4q0-8 7-8 13-1 24-9 4-3 8-7 2-1 4-3 1-1 3-4zm-53-157q4-5 9.5-3t7.5 7.5q2 5.5-2 11.5-5 7-5 13.5t3 11l8 12q5 7.5 7 11.5 12 25 0 50-3 6-8.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3-15.5t-4.5-13.5q-2.5-5-8-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 7.5 12t7 11.5q13 25 1 50-4 6-9.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 8 12t7.5 11.5q12 25 0 50-4 6-9.5 6t-9-5.5q-3.5-5.5-1.5-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-10-24 8-48z\" \/><\/svg><\/span><span class=\"detail-item-label\">Cooking time<\/span><p class=\"detail-item-value\">25<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><\/div><!-- \/.details-items --><\/div><!-- \/.recipe-card-details --><div class=\"recipe-card-food-labels\"><ul class=\"food-labels-list\"><\/ul><\/div><div class=\"recipe-card-ingredients\"><h3 class=\"ingredients-title\">Ingredients<\/h3><ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284706\" class=\"ingredient-item ingredient-item-group\"><strong class=\"ingredient-item-group-title\">Pour le chou-fleur grill\u00e9 :<\/strong><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f28470a\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1 gros chou-fleur ou 2 petits<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284753\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>filet d'huile d'olive<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f28477c\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>aromates : 3 cuillers \u00e0 soupe de zaatar ou 1 cuiller \u00e0 soupe de cumin<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f28479e\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>sel, poivre (ou piment)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f2847be\" class=\"ingredient-item ingredient-item-group\"><strong class=\"ingredient-item-group-title\">Pour le tahini :<\/strong><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f2847c1\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>3 cuillers \u00e0 soupe de tahini (p\u00e2te de s\u00e9same, rayon international des grandes surfaces en g\u00e9n\u00e9ral ou fait maison)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f2847e1\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1\/2 jus de citron\u00a0<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284800\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1\/2 gousse d'ail (ou plus si vous aimez)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284828\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>environ 1\/2 verre d'eau - ou plus, pour une consistance plus fluide<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284850\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1\/2 cuiller \u00e0 caf\u00e9 de cumin<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f284870\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>sel<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e8f28488e\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>optionnel : quelques branches de coriandre<\/p><\/span><\/div><\/li><\/ul><\/div><!-- \/.recipe-card-ingredients --><div class=\"recipe-card-directions\"><h3 class=\"directions-title\">Directions<\/h3><ul class=\"directions-list\"><li id=\"wpzoom-rcb-62451a6\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour le chou-fleur grill\u00e9 :<\/strong><\/li><li id=\"wpzoom-rcb-f36e068\" class=\"direction-step\"><p>Enlever les feuilles du chou-fleur et d\u00e9couper le en grosses sommit\u00e9s (plus les sommit\u00e9s seront grosses, plus le chou-fleur sera grill\u00e9 en conservant une chair encore ferme)<\/p><\/li><li id=\"wpzoom-rcb-346ffe3\" class=\"direction-step\"><p>Les d\u00e9poser alors sur une feuille de papier cuisson sur la l\u00e8che-frite ou un grand plat \u00e0 four<\/p><\/li><li id=\"wpzoom-rcb-7a09cd2\" class=\"direction-step\"><p>Puis disperser dessus les aromates, le sel et le poivre et terminer en arrosant d'un g\u00e9n\u00e9reux filet d'huile d'olive<\/p><img decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-768x576.jpg\" class=\"direction-step-image no-print\" alt=\"la pr\u00e9paration chou-fleur grill\u00e9 sauce tahini\" id=\"7989\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-768x576.jpg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-300x225.jpg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-1024x768.jpg 1024w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-750x563.jpg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-500x375.jpg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-1536x1152.jpg 1536w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-2048x1536.jpg 2048w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-avant-cuisson-1320x990.jpg 1320w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-ca18b68\" class=\"direction-step\"><p>Cuire au four 200\u00b0 entre 25 et 40 minutes, en fonction de la taille des sommit\u00e9s. Le chou fleur doit \u00eatre bien grill\u00e9 et la chair doit \u00eatre encore un peu ferme<\/p><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-768x576.jpg\" class=\"direction-step-image no-print\" alt=\"chou-fleur grill\u00e9 cuit\" id=\"7990\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-768x576.jpg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-300x225.jpg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-1024x768.jpg 1024w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-750x563.jpg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-500x375.jpg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-1536x1152.jpg 1536w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-2048x1536.jpg 2048w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-apres-cuisson-1320x990.jpg 1320w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-499e9e0\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour la sauce tahini :<\/strong><\/li><li id=\"wpzoom-rcb-5b27253\" class=\"direction-step\"><p>Mettre dans un petit robot (Babycook par exemple) la p\u00e2te de s\u00e9same, le jus de citron, l'ail d\u00e9germ\u00e9 et hach\u00e9, le cumin et \u00e9ventuellement la coriandre cisel\u00e9e (je n'en ai pas mis ici, mais j'adore !). Mixer. La p\u00e2te va en premier lieu s'\u00e9paissir ; c'est normal, c'est une \u00e9mulsion<\/p><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-768x576.jpg\" class=\"direction-step-image no-print\" alt=\"pr\u00e9paration de la sauce tahini\" id=\"7991\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-768x576.jpg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-300x225.jpg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-1024x768.jpg 1024w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-750x563.jpg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-500x375.jpg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-1536x1152.jpg 1536w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-2048x1536.jpg 2048w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-preparation-tahina-1320x990.jpg 1320w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-6b8f281\" class=\"direction-step\"><p>D\u00e9tendre la pr\u00e9paration en ajoutant de l'eau par petite quantit\u00e9 jusqu'\u00e0 la consistance souhait\u00e9e (je trouve que la consistance comme un yaourt liquide est parfaite ; sur la photo elle est encore un peu \u00e9paisse).<\/p><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-768x576.jpg\" class=\"direction-step-image no-print\" alt=\"sauce tahini - ajout d&#039;eau pour liqu\u00e9fier\" id=\"7992\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-768x576.jpg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-300x225.jpg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-1024x768.jpg 1024w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-750x563.jpg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-500x375.jpg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-1536x1152.jpg 1536w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-2048x1536.jpg 2048w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-sauce-tahini-1320x990.jpg 1320w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-590c29d\" class=\"direction-step\"><p>Enfin, saler, go\u00fbter et rectifier l'assaisonnement<\/p><\/li><li id=\"wpzoom-rcb-d4390c3\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Dressage du chou-fleur grill\u00e9 sauce tahini et grenade :<\/strong><\/li><li id=\"wpzoom-rcb-cd02955\" class=\"direction-step\"><p>D\u00e9poser le chou-fleur dans un plat de service avec \u00e9ventuellement des pois chiche<\/p><\/li><li id=\"wpzoom-rcb-ea8aac9\" class=\"direction-step\"><p>Verser une partie de la sauce sur le chou-fleur et ajouter des grains de grenade. Servir avec des pois chiche ou du boulgour et proposer du rab de sauce pour les plus gourmands !<\/p><\/li><\/ul><\/div><!-- \/.recipe-card-directions --><div class=\"recipe-card-notes\"><h3 class=\"notes-title\">L&#039;astuce Minute PAPILLOTE !<\/h3><ul class=\"recipe-card-notes-list\"><li class=\"wpzoom-rc-note-text\">La sauce tahini se conserve quelques jours au r\u00e9frig\u00e9rateur dans un r\u00e9cipient ferm\u00e9. Utilisez la sauce restante (s'il en reste...) pour tremper quelques crudit\u00e9s  ou ajouter des pois chiche cuits et confectionnez ainsi un d\u00e9licieux houmous maison !<\/li><\/ul><\/div><!-- \/.recipe-card-notes -->\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Chou-fleur grill\\u00e9 sauce tahini et grenade\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Image-JPEG-53F4EC7E2C40-1-800x530.jpeg\",\"description\":\"\",\"keywords\":[\"\\u00e9pices\",\"facile\",\"rapide\",\"sans gluten\",\"sans lactose\",\"sante\",\"vegan\"],\"author\":{\"@type\":\"Person\",\"name\":\"Helene\"},\"datePublished\":\"2022-05-20T11:27:53+02:00\",\"prepTime\":\"PT5M\",\"cookTime\":\"PT25M\",\"totalTime\":\"PT30M\",\"recipeCategory\":[\"L\\u00e9gumes et L\\u00e9gumineuses\",\"Plats principaux\",\"Sans gluten\",\"Sans lactose\",\"Vegan\",\"V\\u00e9g\\u00e9tarien\",\"Vite fait - bien fait\"],\"recipeCuisine\":[],\"recipeYield\":[\"4\",\"4 servings\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"1 gros chou-fleur ou 2 petits\",\"filet d'huile d'olive\",\"aromates : 3 cuillers \\u00e0 soupe de zaatar ou 1 cuiller \\u00e0 soupe de cumin\",\"sel, poivre (ou piment)\",\"3 cuillers \\u00e0 soupe de tahini (p\\u00e2te de s\\u00e9same, rayon international des grandes surfaces en g\\u00e9n\\u00e9ral ou fait maison)\",\"1\\\/2 jus de citron\\u00a0\",\"1\\\/2 gousse d'ail (ou plus si vous aimez)\",\"environ 1\\\/2 verre d'eau - ou plus, pour une consistance plus fluide\",\"1\\\/2 cuiller \\u00e0 caf\\u00e9 de cumin\",\"sel\",\"optionnel : quelques branches de coriandre\"],\"recipeInstructions\":[{\"@type\":\"HowToSection\",\"name\":\"Pour le chou-fleur grill\\u00e9 :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Enlever les feuilles du chou-fleur et d\\u00e9couper le en grosses sommit\\u00e9s (plus les sommit\\u00e9s seront grosses, plus le chou-fleur sera grill\\u00e9 en conservant une chair encore ferme)\",\"text\":\"Enlever les feuilles du chou-fleur et d\\u00e9couper le en grosses sommit\\u00e9s (plus les sommit\\u00e9s seront grosses, plus le chou-fleur sera grill\\u00e9 en conservant une chair encore ferme)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-f36e068\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Les d\\u00e9poser alors sur une feuille de papier cuisson sur la l\\u00e8che-frite ou un grand plat \\u00e0 four\",\"text\":\"Les d\\u00e9poser alors sur une feuille de papier cuisson sur la l\\u00e8che-frite ou un grand plat \\u00e0 four\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-346ffe3\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Puis disperser dessus les aromates, le sel et le poivre et terminer en arrosant d'un g\\u00e9n\\u00e9reux filet d'huile d'olive\",\"text\":\"Puis disperser dessus les aromates, le sel et le poivre et terminer en arrosant d'un g\\u00e9n\\u00e9reux filet d'huile d'olive\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-7a09cd2\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Cuire au four 200\\u00b0 entre 25 et 40 minutes, en fonction de la taille des sommit\\u00e9s. Le chou fleur doit \\u00eatre bien grill\\u00e9 et la chair doit \\u00eatre encore un peu ferme\",\"text\":\"Cuire au four 200\\u00b0 entre 25 et 40 minutes, en fonction de la taille des sommit\\u00e9s. Le chou fleur doit \\u00eatre bien grill\\u00e9 et la chair doit \\u00eatre encore un peu ferme\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-ca18b68\",\"image\":\"\"}]},{\"@type\":\"HowToSection\",\"name\":\"Pour la sauce tahini :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Mettre dans un petit robot (Babycook par exemple) la p\\u00e2te de s\\u00e9same, le jus de citron, l'ail d\\u00e9germ\\u00e9 et hach\\u00e9, le cumin et \\u00e9ventuellement la coriandre cisel\\u00e9e (je n'en ai pas mis ici, mais j'adore !). Mixer. La p\\u00e2te va en premier lieu s'\\u00e9paissir ; c'est normal, c'est une \\u00e9mulsion\",\"text\":\"Mettre dans un petit robot (Babycook par exemple) la p\\u00e2te de s\\u00e9same, le jus de citron, l'ail d\\u00e9germ\\u00e9 et hach\\u00e9, le cumin et \\u00e9ventuellement la coriandre cisel\\u00e9e (je n'en ai pas mis ici, mais j'adore !). Mixer. La p\\u00e2te va en premier lieu s'\\u00e9paissir ; c'est normal, c'est une \\u00e9mulsion\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-5b27253\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"D\\u00e9tendre la pr\\u00e9paration en ajoutant de l'eau par petite quantit\\u00e9 jusqu'\\u00e0 la consistance souhait\\u00e9e (je trouve que la consistance comme un yaourt liquide est parfaite ; sur la photo elle est encore un peu \\u00e9paisse).\",\"text\":\"D\\u00e9tendre la pr\\u00e9paration en ajoutant de l'eau par petite quantit\\u00e9 jusqu'\\u00e0 la consistance souhait\\u00e9e (je trouve que la consistance comme un yaourt liquide est parfaite ; sur la photo elle est encore un peu \\u00e9paisse).\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-6b8f281\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Enfin, saler, go\\u00fbter et rectifier l'assaisonnement\",\"text\":\"Enfin, saler, go\\u00fbter et rectifier l'assaisonnement\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-590c29d\",\"image\":\"\"}]},{\"@type\":\"HowToSection\",\"name\":\"Dressage du chou-fleur grill\\u00e9 sauce tahini et grenade :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"D\\u00e9poser le chou-fleur dans un plat de service avec \\u00e9ventuellement des pois chiche\",\"text\":\"D\\u00e9poser le chou-fleur dans un plat de service avec \\u00e9ventuellement des pois chiche\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-cd02955\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Verser une partie de la sauce sur le chou-fleur et ajouter des grains de grenade. Servir avec des pois chiche ou du boulgour et proposer du rab de sauce pour les plus gourmands !\",\"text\":\"Verser une partie de la sauce sur le chou-fleur et ajouter des grains de grenade. Servir avec des pois chiche ou du boulgour et proposer du rab de sauce pour les plus gourmands !\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/chou-fleur-tahini-grenade\\\/#wpzoom-rcb-ea8aac9\",\"image\":\"\"}]}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"ratingCount\":4}}<\/script><\/div><!-- \/.wp-block-wpzoom-recipe-card-block-recipe-card -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bf07ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bf07ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ba6d760\" data-id=\"ba6d760\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-889f13a elementor-widget elementor-widget-text-editor\" data-id=\"889f13a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">\u00a0<\/span><\/p><p>D\u00e8s que le soleil arrive, je transforme ce plat de chou-fleur grill\u00e9 en <a href=\"https:\/\/www.minutepapillote.com\/chou-fleur-et-pois-chiche-salade-facon-ottolenghi\/\">salade de chou-fleur et pois chiche<\/a>. Un plat complet, tout aussi gourmand !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1527fa\" data-id=\"a1527fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e59bc95 elementor-widget elementor-widget-image\" data-id=\"e59bc95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.minutepapillote.com\/chou-fleur-et-pois-chiche-salade-facon-ottolenghi\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche.jpeg\" class=\"attachment-large size-large wp-image-11522\" alt=\"chou fleur et pois chiche en salade \u00e0 la mani\u00e8re d&apos;Ottolenghi\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche.jpeg 1200w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche-750x563.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche-500x375.jpeg 500w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche-300x225.jpeg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2024\/06\/chou-fleur-pois-chiche-768x576.jpeg 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8c56bca e-flex e-con-boxed e-con e-parent\" data-id=\"8c56bca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd1503 elementor-widget elementor-widget-spacer\" data-id=\"afd1503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a88c555 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a88c555\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-19d72faf\" data-id=\"19d72faf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-639b4bdf elementor-widget elementor-widget-text-editor\" data-id=\"639b4bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\"><br><\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">Pas de repas sans dessert&#8230; Pour continuer dans la simplicit\u00e9 et encha\u00eener de mani\u00e8re vitamin\u00e9e, vous ne r\u00e9sisterez pas \u00e0 cette <\/span><a href=\"https:\/\/www.minutepapillote.com\/salade-oranges-caramel-epice\/\" style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">salade d&rsquo;oranges et son caramel \u00e9pic\u00e9<\/a><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\"> !<\/span><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61b068ff\" data-id=\"61b068ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-732e71b7 elementor-widget elementor-widget-image\" data-id=\"732e71b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.minutepapillote.com\/salade-oranges-caramel-epice\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/01\/salade-oranges-caramel-epice-1-750x530.jpeg\" class=\"attachment-large size-large wp-image-6625\" alt=\"salade d&apos;oranges et caramel \u00e9pic\u00e9 : un dessert tout en vitamines et en fraicheur\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/01\/salade-oranges-caramel-epice-1-750x530.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/01\/salade-oranges-caramel-epice-1-750x530-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Voici le chou-fleur grill\u00e9 sauce tahini, ou l&rsquo;autre fa\u00e7on de manger du chou-fleur \ud83d\ude0a. Je vous propose ici un plat pr\u00e9par\u00e9 en un rien de temps, simple et qui ravit tous les\u00a0convives. Un plat de semaine, savoureux et vegan. Avec cette recette, on cuisine pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[57,410,413,414,415,416,105],"tags":[117,74,75,122,121,106,129],"class_list":["post-7964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legumes-legumineuses","category-plats-principaux","category-sans-gluten","category-sans-lactose","category-vegan","category-vegetarien","category-vite-fait-bien-fait","tag-epices","tag-facile","tag-rapide","tag-sans-gluten","tag-sans-lactose","tag-sante","tag-vegan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chou-fleur grill\u00e9 sauce tahini et grenade - Minute Papillote<\/title>\n<meta name=\"description\" content=\"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chou-fleur grill\u00e9 sauce tahini et grenade\" \/>\n<meta property=\"og:description\" content=\"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/\" \/>\n<meta property=\"og:site_name\" content=\"Minute Papillote\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-20T10:27:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T08:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/\"},\"author\":{\"name\":\"Helene\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"headline\":\"Chou-fleur grill\u00e9 sauce tahini et grenade\",\"datePublished\":\"2022-05-20T10:27:53+00:00\",\"dateModified\":\"2024-06-12T08:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/\"},\"wordCount\":694,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\",\"keywords\":[\"\u00e9pices\",\"facile\",\"rapide\",\"sans gluten\",\"sans lactose\",\"sante\",\"vegan\"],\"articleSection\":[\"L\u00e9gumes et L\u00e9gumineuses\",\"Plats principaux\",\"Sans gluten\",\"Sans lactose\",\"Vegan\",\"V\u00e9g\u00e9tarien\",\"Vite fait - bien fait\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/\",\"name\":\"Chou-fleur grill\u00e9 sauce tahini et grenade - Minute Papillote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\",\"datePublished\":\"2022-05-20T10:27:53+00:00\",\"dateModified\":\"2024-06-12T08:03:35+00:00\",\"description\":\"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg\",\"width\":500,\"height\":666,\"caption\":\"un plat complet parfait pour un diner de semaine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/chou-fleur-tahini-grenade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.minutepapillote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chou-fleur grill\u00e9 sauce tahini et grenade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/\",\"name\":\"MinutePapillote\",\"description\":\"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minutepapillote.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\",\"name\":\"Helene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"width\":498,\"height\":245,\"caption\":\"Helene\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\"},\"sameAs\":[\"https:\\\/\\\/www.minutepapillote.com\",\"https:\\\/\\\/www.instagram.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ-l3TtP5ifNkp2Cb_ZmIkw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chou-fleur grill\u00e9 sauce tahini et grenade - Minute Papillote","description":"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/","og_locale":"en_US","og_type":"article","og_title":"Chou-fleur grill\u00e9 sauce tahini et grenade","og_description":"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !","og_url":"https:\/\/www.minutepapillote.com\/en\/chou-fleur-tahini-grenade\/","og_site_name":"Minute Papillote","article_published_time":"2022-05-20T10:27:53+00:00","article_modified_time":"2024-06-12T08:03:35+00:00","og_image":[{"width":500,"height":666,"url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg","type":"image\/jpeg"}],"author":"Helene","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#article","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/"},"author":{"name":"Helene","@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"headline":"Chou-fleur grill\u00e9 sauce tahini et grenade","datePublished":"2022-05-20T10:27:53+00:00","dateModified":"2024-06-12T08:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/"},"wordCount":694,"commentCount":2,"publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"image":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg","keywords":["\u00e9pices","facile","rapide","sans gluten","sans lactose","sante","vegan"],"articleSection":["L\u00e9gumes et L\u00e9gumineuses","Plats principaux","Sans gluten","Sans lactose","Vegan","V\u00e9g\u00e9tarien","Vite fait - bien fait"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/","url":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/","name":"Chou-fleur grill\u00e9 sauce tahini et grenade - Minute Papillote","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#primaryimage"},"image":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg","datePublished":"2022-05-20T10:27:53+00:00","dateModified":"2024-06-12T08:03:35+00:00","description":"Une petite cuisson au four et... hop ! Ce chou-fleur grill\u00e9 sauce tahini et grenade rejoint sans chichi la table du d\u00eener\ud83d\ude0a. Sain et facile !","breadcrumb":{"@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#primaryimage","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/05\/chou-fleur-grille-sauce-tahini-gro-e1653049703194.jpeg","width":500,"height":666,"caption":"un plat complet parfait pour un diner de semaine"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minutepapillote.com\/chou-fleur-tahini-grenade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.minutepapillote.com\/"},{"@type":"ListItem","position":2,"name":"Chou-fleur grill\u00e9 sauce tahini et grenade"}]},{"@type":"WebSite","@id":"https:\/\/www.minutepapillote.com\/#website","url":"https:\/\/www.minutepapillote.com\/","name":"MinutePapillote","description":"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs","publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minutepapillote.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c","name":"Helene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","width":498,"height":245,"caption":"Helene"},"logo":{"@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png"},"sameAs":["https:\/\/www.minutepapillote.com","https:\/\/www.instagram.com\/helene_minutepapillote\/","https:\/\/www.pinterest.com\/helene_minutepapillote\/","https:\/\/www.youtube.com\/channel\/UCJ-l3TtP5ifNkp2Cb_ZmIkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/comments?post=7964"}],"version-history":[{"count":0,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media\/7985"}],"wp:attachment":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media?parent=7964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/categories?post=7964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/tags?post=7964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}