{"id":7234,"date":"2022-02-22T13:15:26","date_gmt":"2022-02-22T12:15:26","guid":{"rendered":"https:\/\/www.minutepapillote.com\/?p=7234"},"modified":"2025-10-09T19:38:20","modified_gmt":"2025-10-09T17:38:20","slug":"tajine-agneau-kumquats-confits","status":"publish","type":"post","link":"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/","title":{"rendered":"Tajine d&rsquo;agneau et kumquats confits"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7234\" class=\"elementor elementor-7234\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40a8874a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40a8874a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25f1d9e3\" data-id=\"25f1d9e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-642db6e5 elementor-widget elementor-widget-text-editor\" data-id=\"642db6e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Les kumquats&#8230; Comme ils sont <strong>color\u00e9s et s\u00e9duisants<\/strong> ! Ils nous font de l&rsquo;oeil sur les \u00e9tals, n&rsquo;est-ce-pas ? Mais peuvent nous laisser perplexes. Car <em>comment les cuisiner ?<\/em> Et <em>avec quel produit les associer ?<\/em> Rassurez-vous, c&rsquo;est tr\u00e8s <strong>simple<\/strong> ! Je vous propose ici une version sucr\u00e9e-sal\u00e9e avec ce d\u00e9licieux tajine d&rsquo;agneau et kumquats confits. Un r\u00e9gal \u00e0 peine <strong>acidul\u00e9<\/strong>, le <strong>fondant<\/strong> de la viande, le <strong>croquant<\/strong> des amandes, la <strong>pointe de fra\u00eecheur<\/strong> de la coriandre&#8230;.mmmh&#8230;.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a8a6eb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a8a6eb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11662ad8\" data-id=\"11662ad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320522ac elementor-align-center elementor-widget elementor-widget-button\" data-id=\"320522ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ma_petite_recette\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aller \u00e0 la recette<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4580948 elementor-widget elementor-widget-spacer\" data-id=\"4580948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7769a984 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7769a984\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c5ccff7\" data-id=\"4c5ccff7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ed2cfb elementor-widget elementor-widget-heading\" data-id=\"53ed2cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">L&#039;article en un coup d&#039;oeil :<\/span>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #f4926a;color:#f4926a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #f4926a;color:#f4926a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/#Les_kumquats_comment_les_manger\" >Les kumquats : comment les manger ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/#Tajine_dagneau_et_kumquats_confits_les_bienfaits_de_la_cuisson_lente\" >Tajine d'agneau et kumquats confits : les bienfaits de la cuisson lente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/#Tajine_dagneau_et_kumquats_confits\" >Tajine d&#039;agneau et kumquats confits<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Les_kumquats_comment_les_manger\"><\/span>Les kumquats : comment les manger ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-719d0fb9 elementor-widget elementor-widget-text-editor\" data-id=\"719d0fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Ce<strong> joli<\/strong> petit agrume a plus d&rsquo;un tour dans son sac. Car sa peau est<strong> sucr\u00e9e<\/strong>, sa chair l\u00e9g\u00e8rement acide et ses p\u00e9pins amers &#8211; on a presque fait le tour de la gastronomie avec ces trois saveurs ; c&rsquo;est rare ! D&rsquo;ailleurs, il ne lui manquerait plus que la saveur sal\u00e9e et l&rsquo;umami pour \u00eatre un plat \u00e0 lui tout seul.<\/span><br \/><span style=\"color: #000000;\"><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif;\"><em>Comment tirer parti de cette belle association sucr\u00e9\/acide\/amer<\/em> ? Ou <em>encore comment le cuisiner ou l&rsquo;associer avec des ingr\u00e9dients ?<\/em> Voici quelques pistes.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a37d4d elementor-widget elementor-widget-heading\" data-id=\"9a37d4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">1001 mani\u00e8res (ou presque) d'aimer les kumquats <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60654ec elementor-widget elementor-widget-text-editor\" data-id=\"60654ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\">en<span style=\"text-decoration: underline; color: #ff6600;\"> <strong>salade de fruits<\/strong><\/span>. L\u00e0, le kumquat vient donner du peps \u00e0 une salade toute b\u00eate. Et <strong>cette couleur, quel bonheur !<\/strong><\/span><\/li><li><span style=\"color: #000000;\">en fruit \u00e0 croquer, <span style=\"text-decoration: underline; color: #ff6600;\"><strong>en formule snack ou petite gourmandise<\/strong><\/span>. Mais autant vous le dire tout de suite : on adore ou on d\u00e9teste. Par exemple, ma fille a\u00een\u00e9e d\u00e8s l&rsquo;\u00e2ge de deux ans d\u00e9vorait avec avidit\u00e9 ces petits agrumes. Un vrai plaisir pour elle. Enfin, pour \u00eatre tout a fait honn\u00eate avec vous, elle craquait aussi pour le citron, capable de mordre dans un quartier avec gourmandise \ud83e\udd14. Je vous laisse en tirer les conclusions qui vous conviendront&#8230;<\/span><\/li><li><span style=\"color: #000000;\">ou bien<span style=\"text-decoration: underline; color: #ff6600;\"><strong> en<\/strong> <strong>salade sal\u00e9e<\/strong><\/span> : <strong>pour encore plus de peps<\/strong> ! A associer avec une crudit\u00e9 qui a du caract\u00e8re : de la roquette, une salade tr\u00e9vise. Remarquable.<\/span><\/li><li><span style=\"color: #000000;\">et pourquoi pas <span style=\"text-decoration: underline; color: #ff6600;\"><strong>en<\/strong> <strong>condiment ou\u00a0sauce <\/strong><\/span>&#8211;\u00a0vinaigrette par exemple, de la mani\u00e8re dont vous feriez une vinaigrette d&rsquo;orange. Rassurez-vous, pas besoin de r\u00e9cup\u00e9rer le jus des fruits \u00a0avec un mini presse kumquat, une mini cuiller et ses mini doigts. <em>On hache finement \u00a0les kumquats<\/em>, c&rsquo;est bien suffisant et bien plus rapide.<\/span><\/li><li><span style=\"color: #000000;\">enfin,<span style=\"text-decoration: underline; color: #ff6600;\"><strong> en accompagnement d&rsquo;une viande<\/strong><\/span> comme ici ce <strong>tajine d&rsquo;agneau et kumquats confits<\/strong>. Pour corriger l&rsquo;acidit\u00e9 de la chair des agrumes, on les laisse d&rsquo;abord confire dans un sirop de sucre tr\u00e8s l\u00e9ger. Puis on cuit le tajine et les kumquats loooongtemps. Pour un<strong> r\u00e9sultat fondant et l\u00e9ger<\/strong> en bouche, il n&rsquo;y a pas mieux !<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46fe6819 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46fe6819\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f8bfa54\" data-id=\"3f8bfa54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e9a0434 elementor-widget elementor-widget-heading\" data-id=\"2e9a0434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Tajine_dagneau_et_kumquats_confits_les_bienfaits_de_la_cuisson_lente\"><\/span>Tajine d'agneau et kumquats confits : les bienfaits de la cuisson lente<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-433fc189 elementor-widget elementor-widget-text-editor\" data-id=\"433fc189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Et oui, la recette du succ\u00e8s d&rsquo;une viande mijot\u00e9e, c&rsquo;est <em>le temps pass\u00e9<\/em>. Non, pas n\u00e9cessairement le temps pass\u00e9 \u00e0 couper les l\u00e9gumes, assaisonner la viande, faire la vaisselle&#8230; mais le temps pass\u00e9 \u00e0 cuire \u00e0 tout petits bouillons, l\u00e0 sur le coin du feu. Alors aujourd&rsquo;hui, on ne cuit plus sur la cuisini\u00e8re \u00e0 bois (qui reste tout de m\u00eame une formule de cuisson incroyable &#8211; douces pens\u00e9es pour ma grand-m\u00e8re qui a longtemps cuisin\u00e9 de cette mani\u00e8re), mais on utilise son four. Qui a un r\u00e9gulateur de temp\u00e9rature. Et qui souvent, est programmable. Ainsi le tour est jou\u00e9, le four travaille&#8230; <em>pas nous<\/em> !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e3feaba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e3feaba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-745db490\" data-id=\"745db490\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eff16b0 elementor-widget elementor-widget-text-editor\" data-id=\"3eff16b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Alors, on s&rsquo;y met ? On le cuisine ce tajine d&rsquo;agneau et kumquats confits ?\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-730244ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"730244ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32ccf577\" data-id=\"32ccf577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b58dc49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b58dc49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d27ec5c\" data-id=\"4d27ec5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e0c892c elementor-widget elementor-widget-menu-anchor\" data-id=\"3e0c892c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ma_petite_recette\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eabb9f elementor-widget elementor-widget-wpzoom-elementor-recipe-card-widget\" data-id=\"2eabb9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/1_C2_qbdzaw&quot;,&quot;recipe_card_styles&quot;:&quot;is-style-newdesign&quot;,&quot;video_title&quot;:&quot;Tajine agneau et kumquats confits&quot;,&quot;video_description&quot;:&quot;Un plat raffin\\u00e9 en saveurs sucr\\u00e9es et sal\\u00e9es&quot;,&quot;video_type&quot;:&quot;embed&quot;}\" data-widget_type=\"wpzoom-elementor-recipe-card-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"wpzoom-premium-recipe-card\" class=\"wp-block-wpzoom-recipe-card-block-recipe-card is-style-newdesign block-alignment-left header-content-align-left\"><div class=\"recipe-card-image\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-agneau-kumquats-confits-2.jpeg\" class=\"wpzoom-recipe-card-image\" alt=\"Tajine d&#039;agneau et kumquats confits\" id=\"7239\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-agneau-kumquats-confits-2.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-agneau-kumquats-confits-2-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption><div class=\"wpzoom-recipe-card-pinit\">\n\t            <a class=\"btn-pinit-link no-print\" data-pin-do=\"buttonPin\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url=https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/&#038;media=https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-agneau-kumquats-confits-2.jpeg&#038;description=Un%20tajine%20en%20sucr\u00e9\/sal\u00e9%20qui%20vous%20surprendra%20!\" data-pin-custom=\"true\" aria-label=\"Pin recipe on Pinterest\" title=\"Pin recipe on Pinterest\" >\n\t            \t<SVG class=\"wpzoom-rcb-icon-pinit-link\" enable-background=\"new 0 0 30 30\" height=\"30px\" id=\"Pinterest\" version=\"1.1\" viewBox=\"0 0 30 30\" width=\"30px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t            \t    <Path class=\"wpzoom-rcb-pinit-icon\" d=\"M16,0C7.813,0,3,6.105,3,11c0,2.964,2,6,3,6s2,0,2-1s-2-2-2-5c0-4.354,4.773-8,10-8c4.627,0,7,3.224,7,7  c0,4.968-2.735,9-6,9c-1.803,0-3.433-1.172-3-3c0.519-2.184,1-2,2-6c0.342-1.368-0.433-3-2-3c-1.843,0-4,1.446-4,4c0,1.627,1,3,1,3  s-2.245,7.863-2.576,9.263C7.766,26.049,6.938,30,7.938,30S10,28,12,23c0.295-0.738,1-3,1-3c0.599,1.142,3.14,2,5,2  c5.539,0,9-5.24,9-12C27,4.888,22.58,0,16,0z\" \/>\n\t            \t<\/SVG>\n\t            \t<span>Pin<\/span>\n\t            <\/a>\n\t        <\/div><div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link elementor-rcb-print-button no-print\" href=\"#\">\n                <svg class=\"wpzoom-rcb-icon-print-link\" width=\"32\" height=\"32\" viewBox=\"0 0 19 18\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M5 7.2C4.822 7.2 4.64799 7.25278 4.49999 7.35168C4.35198 7.45057 4.23663 7.59113 4.16851 7.75558C4.10039 7.92004 4.08257 8.101 4.11729 8.27558C4.15202 8.45016 4.23774 8.61053 4.3636 8.7364C4.48947 8.86226 4.64984 8.94798 4.82442 8.98271C4.999 9.01743 5.17996 8.99961 5.34441 8.93149C5.50887 8.86337 5.64943 8.74802 5.74832 8.60001C5.84722 8.45201 5.9 8.278 5.9 8.1C5.9 7.8613 5.80518 7.63239 5.6364 7.4636C5.46761 7.29482 5.23869 7.2 5 7.2ZM15.8 3.6H14.9V0.9C14.9 0.661305 14.8052 0.432387 14.6364 0.263604C14.4676 0.0948211 14.2387 0 14 0H5C4.76131 0 4.53239 0.0948211 4.3636 0.263604C4.19482 0.432387 4.1 0.661305 4.1 0.9V3.6H3.2C2.48392 3.6 1.79716 3.88446 1.29081 4.39081C0.784464 4.89716 0.5 5.58392 0.5 6.3V11.7C0.5 12.4161 0.784464 13.1028 1.29081 13.6092C1.79716 14.1155 2.48392 14.4 3.2 14.4H4.1V17.1C4.1 17.3387 4.19482 17.5676 4.3636 17.7364C4.53239 17.9052 4.76131 18 5 18H14C14.2387 18 14.4676 17.9052 14.6364 17.7364C14.8052 17.5676 14.9 17.3387 14.9 17.1V14.4H15.8C16.5161 14.4 17.2028 14.1155 17.7092 13.6092C18.2155 13.1028 18.5 12.4161 18.5 11.7V6.3C18.5 5.58392 18.2155 4.89716 17.7092 4.39081C17.2028 3.88446 16.5161 3.6 15.8 3.6ZM5.9 1.8H13.1V3.6H5.9V1.8ZM13.1 16.2H5.9V12.6H13.1V16.2ZM16.7 11.7C16.7 11.9387 16.6052 12.1676 16.4364 12.3364C16.2676 12.5052 16.0387 12.6 15.8 12.6H14.9V11.7C14.9 11.4613 14.8052 11.2324 14.6364 11.0636C14.4676 10.8948 14.2387 10.8 14 10.8H5C4.76131 10.8 4.53239 10.8948 4.3636 11.0636C4.19482 11.2324 4.1 11.4613 4.1 11.7V12.6H3.2C2.9613 12.6 2.73239 12.5052 2.5636 12.3364C2.39482 12.1676 2.3 11.9387 2.3 11.7V6.3C2.3 6.0613 2.39482 5.83239 2.5636 5.6636C2.73239 5.49482 2.9613 5.4 3.2 5.4H15.8C16.0387 5.4 16.2676 5.49482 16.4364 5.6636C16.6052 5.83239 16.7 6.0613 16.7 6.3V11.7Z\" \/>\n                    <\/svg>\n\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div><\/figcaption><\/figure><\/div><!-- \/.recipe-card-image --><div class=\"recipe-card-heading\"><h2 class=\"recipe-card-title\"><span class=\"ez-toc-section\" id=\"Tajine_dagneau_et_kumquats_confits\"><\/span>Tajine d&#039;agneau et kumquats confits<span class=\"ez-toc-section-end\"><\/span><\/h2><div class=\"recipe-sub-title\"><span class=\"recipe-card-author\">Recipe by Helene<\/span><div class=\"wpzoom-rating-stars-container\" data-rating=\"4.7\" data-rating-total=\"3\" data-recipe-id=\"7234\" data-post-id=\"7234\" data-user-can-rate=\"1\">\n\t\t\t\t<ul class=\"wpzoom-rating-stars\"><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-three-quarters-star wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-three-quarters\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><\/ul><span class=\"wpzoom-rating-stars-average\"><span class=\"wpzoom-rating-average\">4.7<\/span> from <span class=\"wpzoom-rating-total-votes\">3<\/span> votes<\/span>\n\t\t\t\t<em class=\"wpzoom-rating-stars-tooltip\"><\/em>\n\t\t\t<\/div><\/div><\/div><!-- \/.recipe-card-heading --><div class=\"wpzoom-nosleep-toggle-container\">\n        <label class=\"switch\">\n            <input type=\"checkbox\" id=\"toggle_button\">\n            <div class=\"slider round\"><\/div>\n        <\/label><span class=\"wpzoom-nosleep-label\">Cook Mode<\/span><p class=\"recipe-card-no-sleep no-print\">Permet \u00e0 la recette de rester visible plus longtemps<\/p><\/div><div class=\"recipe-card-details\"><div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 1024 1024\"><path d=\"M768 520V51q0-10-4-19.5T753 15q-7-7-16.5-11T717 0q-10 0-19.5 4T681 15q-8 7-11.5 16.5T666 51v469q-34 9-62.5 29T555 596q-21 28-32 61t-11 67q0 40 14 91t40.5 97q26.5 46 64.5 78 38 31 86 31 47 0 85-31 38-32 64.5-78t40.5-97q15-51 15-91 0-34-11-67t-32-61q-21-27-49.5-47T768 520zm-51 402q-31 0-67-68t-36-127q-1-21 6.5-41.5T642 650q15-16 34-25.5t41-10.5q21 1 40.5 10.5T791 650q15 15 22 35.5t6 41.5q0 59-35.5 127T717 922zM358 0q-10 0-19.5 4T322 15q-7 7-11 16.5T307 51v280l-51 34V51q0-10-4-19.5T241 15q-7-7-16.5-11T205 0q-10 0-19.5 4T169 15q-8 7-11.5 16.5T154 51v314l-52-34V51q0-10-3.5-19.5T87 15Q80 8 70.5 4T51 0Q41 0 31.5 4T15 15Q8 22 4 31.5T0 51v307q0 7 1.5 13T6 383q3 5 7.5 9.5T23 401l131 87v485q0 10 3.5 19.5T169 1009q7 7 16.5 11t19.5 4q10 0 19.5-4t16.5-11q7-7 11-16.5t4-19.5V488l131-87q5-4 9-8.5t7-9.5q3-6 5-12t2-13V51q0-10-4-19.5T395 15q-8-7-17-11t-20-4z\" \/><\/svg><\/span><span class=\"detail-item-label\">Servings<\/span><p class=\"detail-item-value\">6<\/p><span class=\"detail-item-unit\">servings<\/span><\/div><div class=\"detail-item detail-item-1\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 0C9.62663 0 7.30655 0.703788 5.33316 2.02236C3.35977 3.34094 1.8217 5.21508 0.913451 7.4078C0.00519941 9.60051 -0.232441 12.0133 0.230582 14.3411C0.693605 16.6689 1.83649 18.807 3.51472 20.4853C5.19295 22.1635 7.33115 23.3064 9.65892 23.7694C11.9867 24.2324 14.3995 23.9948 16.5922 23.0865C18.7849 22.1783 20.6591 20.6402 21.9776 18.6668C23.2962 16.6934 24 14.3734 24 12C24 10.4241 23.6896 8.8637 23.0866 7.4078C22.4835 5.95189 21.5996 4.62902 20.4853 3.51472C19.371 2.40041 18.0481 1.5165 16.5922 0.913445C15.1363 0.310389 13.5759 0 12 0ZM12 21.6C10.1013 21.6 8.24524 21.037 6.66653 19.9821C5.08782 18.9272 3.85736 17.4279 3.13076 15.6738C2.40416 13.9196 2.21405 11.9893 2.58447 10.1271C2.95488 8.26491 3.86919 6.55436 5.21178 5.21177C6.55436 3.86919 8.26492 2.95488 10.1271 2.58446C11.9894 2.21404 13.9196 2.40415 15.6738 3.13076C17.4279 3.85736 18.9272 5.08781 19.9821 6.66652C21.037 8.24524 21.6 10.1013 21.6 12C21.6 14.5461 20.5886 16.9879 18.7882 18.7882C16.9879 20.5886 14.5461 21.6 12 21.6ZM15.72 12.756L13.2 11.304V6C13.2 5.68174 13.0736 5.37651 12.8485 5.15147C12.6235 4.92643 12.3183 4.8 12 4.8C11.6817 4.8 11.3765 4.92643 11.1515 5.15147C10.9264 5.37651 10.8 5.68174 10.8 6V12C10.8 12 10.8 12.096 10.8 12.144C10.8071 12.2267 10.8274 12.3077 10.86 12.384C10.8847 12.4552 10.9169 12.5236 10.956 12.588C10.9888 12.6562 11.0291 12.7206 11.076 12.78L11.268 12.936L11.376 13.044L14.496 14.844C14.6789 14.9477 14.8858 15.0014 15.096 15C15.3617 15.0019 15.6205 14.9155 15.8318 14.7544C16.0431 14.5933 16.195 14.3667 16.2637 14.11C16.3323 13.8533 16.3138 13.5811 16.2111 13.3361C16.1083 13.091 15.9272 12.887 15.696 12.756H15.72Z\" fill=\"currentColor\" \/><\/svg><\/span><span class=\"detail-item-label\">Prep time<\/span><p class=\"detail-item-value\">25<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><div class=\"detail-item detail-item-2\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg viewbox=\"0 0 512.0016 512.0155\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 278.014q1 34-21 46-13 6-30 5v84q0 41-28 70t-70 29H151q-42 0-72-29t-30-70v-84q-16 1-28-5-22-12-21-46 0-8 7-11.5t13.5 0q6.5 3.5 5.5 11.5 0 18 8 23 5 3 15 2v-52q15 11 62 19 60 9 145.5 9t149.5-10q38-6 55-14v48q11 1 17-2 8-5 8-23-1-8 5.5-11.5t13.5 0q7 3.5 7 11.5zm-150 193q29-10 43-37t13.5-57q-.5-30-.5-60v-12q-1-10-10-14.5t-17.5 0q-8.5 4.5-8.5 14.5 1 5 2 21t1.5 26q.5 10-1 26t-4.5 26.5q-3 10.5-10 20t-17 13.5q-10 3-12 13t4.5 17q6.5 7 16.5 3zm-310-237q0-12 .5-16.5t6-13q5.5-8.5 16.5-13t33.5-8.5q22.5-4 56.5-6-11 3-10 15 0 6 4 10t11 4h1q28-1 49-21l5-4q3-4 6-7h25q23 0 44 1 2 1 5 4l6 6q21 20 49 21h1q7 0 11-4t4-10q1-9-7-14 35 3 56 8t29.5 13.5q8.5 8.5 10 14.5t1.5 19q0 3-5 6-15 12-73.5 19.5t-131.5 7.5q-75 0-132-7.5t-69-19.5q-3-2-3-5zm158-73q4-3 6-5 13-11 29-13l.5-.5.5-.5q3 0 8-1h18q5 0 6.5.5t5.5 1.5h4q15 3 27 13l6 6q1 0 2 1t1 2q3 2 5 4 4 4 8 7 11 7 24 8 9 1 8 8l-4 6v4l-3-4q-27-2-45-19l-4-4q-1-2-2-2l-5-5q-5-4-9-7-7-3-17-5h-1q-3-1-5-1-4-1-8-1h-12q-3 0-5 1-8 1-15 6-4 3-8 7-3 3-7 6l-4 5q-19 17-44 19-4 0-5.5-2t-1.5-4q0-8 7-8 13-1 24-9 4-3 8-7 2-1 4-3 1-1 3-4zm-53-157q4-5 9.5-3t7.5 7.5q2 5.5-2 11.5-5 7-5 13.5t3 11l8 12q5 7.5 7 11.5 12 25 0 50-3 6-8.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3-15.5t-4.5-13.5q-2.5-5-8-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 7.5 12t7 11.5q13 25 1 50-4 6-9.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 8 12t7.5 11.5q12 25 0 50-4 6-9.5 6t-9-5.5q-3.5-5.5-1.5-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-10-24 8-48z\" \/><\/svg><\/span><span class=\"detail-item-label\">Cooking time<\/span><p class=\"detail-item-value\">2 \u00e0 4<\/p><span class=\"detail-item-unit\">heures<\/span><\/div><\/div><!-- \/.details-items --><\/div><!-- \/.recipe-card-details --><div class=\"recipe-card-food-labels\"><ul class=\"food-labels-list\"><\/ul><\/div><p class=\"recipe-card-summary\">Un tajine en sucr\u00e9\/sal\u00e9 qui vous surprendra !<\/p><div class=\"recipe-card-ingredients\"><h3 class=\"ingredients-title\">Ingredients<\/h3><ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc757e\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1kg agneau (\u00e9paule ou collier) d\u00e9coup\u00e9 en cubes de 5x5cm<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc75c1\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>300g kumquats (environ)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc75ed\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>150g sucre (voire 200g si vos kumquats ne sont pas tr\u00e8s m\u00fbrs)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc7611\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1 \u00e0 2 oignons<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc7632\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>gousses d'ail (autant que vous voulez)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc7652\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>2 \u00e0 3 cuillers \u00e0 soupe d'\u00e9pices \u00e0 tajine\u00a0<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc7671\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>2 cuiller \u00e0 soupe de miel (optionnel)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc769d\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>2 petites poign\u00e9es d'amandes \u00e9mond\u00e9es torr\u00e9fi\u00e9es<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc76bd\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>de la coriandre<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56ebcbc76dc\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1 cube de bouillon d'agneau de bonne qualit\u00e9 (ou \u00e0 d\u00e9faut du bouillon de boeuf, ou de volaille ou 1 Kub or).<br \/>Personnellement, j'essaie d'utiliser un bouillon de volaille maison, assez relev\u00e9 et cuit avec de nombreuses \u00e9pices.\u00a0<\/p><\/span><\/div><\/li><\/ul><\/div><!-- \/.recipe-card-ingredients --><div class=\"recipe-card-directions\"><h3 class=\"directions-title\">Directions<\/h3><ul class=\"directions-list\"><li id=\"wpzoom-rcb-62451a6\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour les kumquats confits (peut \u00eatre r\u00e9alis\u00e9 la veille de la cuisson du tajine) :<\/strong><\/li><li id=\"wpzoom-rcb-f36e068\" class=\"direction-step\"><p>Faire bouillir 200g d'eau avec le sucre<\/p><\/li><li id=\"wpzoom-rcb-346ffe3\" class=\"direction-step\"><p>Ajouter les kumquats et faire cuire \u00e0 petits bouillons pendant une quinzaine de minutes. La cuisson est finie lorsque les kumquats sont gonfl\u00e9s<\/p><img decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/kmquats-confits.jpeg\" class=\"direction-step-image no-print\" alt=\"les kumquats confits : tout gonfl\u00e9s en fin de cuisson\" id=\"7251\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/kmquats-confits.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/kmquats-confits-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-f8a0392\" class=\"direction-step\"><p>Lorsque la pr\u00e9paration est ti\u00e8de, go\u00fbter un kumquat ; si il vous semble trop acide (c'est-\u00e0-dire si les kumquats n'\u00e9taient pas tr\u00e8s m\u00fbrs), rajouter du sucre (50g environ), faire bouillir puis arr\u00eater le feu\u00a0<\/p><\/li><li id=\"wpzoom-rcb-7a09cd2\" class=\"direction-step\"><p>Laisser reposer \u00e0 temp\u00e9rature ambiante (en ayant mis un couvercle sur la casserole)<\/p><\/li><li id=\"wpzoom-rcb-4f3823c\" class=\"direction-step direction-step-group\"><strong class=\"direction-step-group-title\">Pour le tajine (peut \u00eatre pr\u00e9par\u00e9 la vaille ou l&#039;avant-veille) :<\/strong><\/li><li id=\"wpzoom-rcb-c987510\" class=\"direction-step\"><p>Faire revenir les oignons \u00e9minc\u00e9s dans de l'huile neutre<\/p><\/li><li id=\"wpzoom-rcb-591561d\" class=\"direction-step\"><p>Lorsqu'ils sont translucides, les r\u00e9server dans un r\u00e9cipient<\/p><\/li><li id=\"wpzoom-rcb-10306f0\" class=\"direction-step\"><p>Puis remettre un peu de mati\u00e8re grasse et faire dorer la viande<\/p><\/li><li id=\"wpzoom-rcb-c4ae136\" class=\"direction-step\"><p>Lorsque l'agneau a pris couleur, ajouter les \u00e9pices \u00e0 tajine et continuer \u00e0 faire rissoler pendant une minute (\u00e7a sent bon !)<\/p><\/li><li id=\"wpzoom-rcb-bdd6fad\" class=\"direction-step\"><p>Puis ajouter les oignons, le miel, les 3\/4 des kumquats (gardez en quelques uns pour la d\u00e9coration), les gousses d'ail en chemise, l'\u00e9quivalent de 1\/2 verre de jus des kumquats et du sel<\/p><\/li><li id=\"wpzoom-rcb-422bcb5\" class=\"direction-step\"><p>Enfin, recouvrir d'eau chaude \u00e0 hauteur<\/p><img decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-la-cuisson.jpeg\" class=\"direction-step-image no-print\" alt=\"tajine d&#039;agneau et kumquats confits - la cuisson\" id=\"7250\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-la-cuisson.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-la-cuisson-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/li><li id=\"wpzoom-rcb-6f7d7f1\" class=\"direction-step\"><p>Go\u00fbter et rectifier l'assaisonnement - en sel mais aussi en jus de kumquats : vous pouvez tout \u00e0 fait en ajouter en fonction de votre go\u00fbt<\/p><\/li><li id=\"wpzoom-rcb-77cb8fc\" class=\"direction-step\"><p>Poser un couvercle herm\u00e9tique et placer au four :<\/p><ul><li>soit \u00e0 160\u00b0 pendant 2 \u00e0 3 heures<\/li><li>soit \u00e0 120\u00b0 pendant 4 heures (ma m\u00e9thode pr\u00e9f\u00e9r\u00e9e !)<\/li><\/ul><p>V\u00e9rifier r\u00e9guli\u00e8rement qu'il y a encore du liquide dans la cocotte ; sinon rajouter de l'eau<\/p><\/li><li id=\"wpzoom-rcb-943de34\" class=\"direction-step\"><p>Servir bien chaud, avec le reste des kumquats r\u00e9chauff\u00e9s, des amandes \u00e9mond\u00e9es torr\u00e9fi\u00e9es ainsi que des pluches de coriandre<\/p><\/li><\/ul><\/div><!-- \/.recipe-card-directions --><div class=\"recipe-card-video no-print\"><h3 class=\"video-title\">Tajine agneau et kumquats confits<\/h3><iframe title=\"Tagine d&amp;apos;agneau aux kumquats - un plat mijot\u00e9, acidul\u00e9 et savoureux !\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/1_C2_qbdzaw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"recipe-card-notes\"><h3 class=\"notes-title\">L&#039;astuce Minute PAPILLOTE !<\/h3><ul class=\"recipe-card-notes-list\"><li class=\"wpzoom-rc-note-text\">Astuce n\u00b01 : ce tajine d'agneau et kumquats confits est encore meilleur pr\u00e9par\u00e9 la veille ou l'avant-veille ; essayez, vous ne le regretterez pas !<\/li><li class=\"wpzoom-rc-note-text\">Astuce n\u00b02 : vous pouvez servir ce tajine avec les l\u00e9gumes de votre choix - personnellement, je le propose avec de la semoule de couscous (bien s\u00fbr !) ainsi qu'un m\u00e9lange de navets cuits \u00e0 la vapeur et de f\u00e8ves. Remarquable !<\/li><li class=\"wpzoom-rc-note-text\">Astuce n\u00b03 : les kumquats qui cuiront avec le tajine perdront en couleur et devraient se fondre dans la pr\u00e9paration ; ils donnent leur saveur au plat. Le 1\/4 des kumquats confits r\u00e9serv\u00e9s auront conserv\u00e9, eux, leur couleur et leur texture et serviront \u00e0 d\u00e9corer le tajine au moment du service. Comme cela, c'est bon et c'est joli !<\/li><\/ul><\/div><!-- \/.recipe-card-notes -->\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Tajine d'agneau et kumquats confits\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-agneau-kumquats-confits-2.jpeg\",\"description\":\"Un tajine en sucr\\u00e9\\\/sal\\u00e9 qui vous surprendra !\",\"keywords\":[\"\\u00e9pices\",\"facile\",\"sans gluten\"],\"author\":{\"@type\":\"Person\",\"name\":\"Helene\"},\"datePublished\":\"2022-02-22T13:15:26+02:00\",\"prepTime\":\"PT25M\",\"cookTime\":\"PT2M\",\"totalTime\":\"PT27M\",\"recipeCategory\":[\"Plats principaux\",\"Sans gluten\",\"Sans lactose\"],\"recipeCuisine\":[],\"recipeYield\":[\"6\",\"6 servings\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"1kg agneau (\\u00e9paule ou collier) d\\u00e9coup\\u00e9 en cubes de 5x5cm\",\"300g kumquats (environ)\",\"150g sucre (voire 200g si vos kumquats ne sont pas tr\\u00e8s m\\u00fbrs)\",\"1 \\u00e0 2 oignons\",\"gousses d'ail (autant que vous voulez)\",\"2 \\u00e0 3 cuillers \\u00e0 soupe d'\\u00e9pices \\u00e0 tajine\\u00a0\",\"2 cuiller \\u00e0 soupe de miel (optionnel)\",\"2 petites poign\\u00e9es d'amandes \\u00e9mond\\u00e9es torr\\u00e9fi\\u00e9es\",\"de la coriandre\",\"1 cube de bouillon d'agneau de bonne qualit\\u00e9 (ou \\u00e0 d\\u00e9faut du bouillon de boeuf, ou de volaille ou 1 Kub or).Personnellement, j'essaie d'utiliser un bouillon de volaille maison, assez relev\\u00e9 et cuit avec de nombreuses \\u00e9pices.\\u00a0\"],\"recipeInstructions\":[{\"@type\":\"HowToSection\",\"name\":\"Pour les kumquats confits (peut \\u00eatre r\\u00e9alis\\u00e9 la veille de la cuisson du tajine) :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Faire bouillir 200g d'eau avec le sucre\",\"text\":\"Faire bouillir 200g d'eau avec le sucre\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-f36e068\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Ajouter les kumquats et faire cuire \\u00e0 petits bouillons pendant une quinzaine de minutes. La cuisson est finie lorsque les kumquats sont gonfl\\u00e9s\",\"text\":\"Ajouter les kumquats et faire cuire \\u00e0 petits bouillons pendant une quinzaine de minutes. La cuisson est finie lorsque les kumquats sont gonfl\\u00e9s\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-346ffe3\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Lorsque la pr\\u00e9paration est ti\\u00e8de, go\\u00fbter un kumquat ; si il vous semble trop acide (c'est-\\u00e0-dire si les kumquats n'\\u00e9taient pas tr\\u00e8s m\\u00fbrs), rajouter du sucre (50g environ), faire bouillir puis arr\\u00eater le feu\\u00a0\",\"text\":\"Lorsque la pr\\u00e9paration est ti\\u00e8de, go\\u00fbter un kumquat ; si il vous semble trop acide (c'est-\\u00e0-dire si les kumquats n'\\u00e9taient pas tr\\u00e8s m\\u00fbrs), rajouter du sucre (50g environ), faire bouillir puis arr\\u00eater le feu\\u00a0\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-f8a0392\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Laisser reposer \\u00e0 temp\\u00e9rature ambiante (en ayant mis un couvercle sur la casserole)\",\"text\":\"Laisser reposer \\u00e0 temp\\u00e9rature ambiante (en ayant mis un couvercle sur la casserole)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-7a09cd2\",\"image\":\"\"}]},{\"@type\":\"HowToSection\",\"name\":\"Pour le tajine (peut \\u00eatre pr\\u00e9par\\u00e9 la vaille ou l'avant-veille) :\",\"itemListElement\":[{\"@type\":\"HowToStep\",\"name\":\"Faire revenir les oignons \\u00e9minc\\u00e9s dans de l'huile neutre\",\"text\":\"Faire revenir les oignons \\u00e9minc\\u00e9s dans de l'huile neutre\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-c987510\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Lorsqu'ils sont translucides, les r\\u00e9server dans un r\\u00e9cipient\",\"text\":\"Lorsqu'ils sont translucides, les r\\u00e9server dans un r\\u00e9cipient\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-591561d\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Puis remettre un peu de mati\\u00e8re grasse et faire dorer la viande\",\"text\":\"Puis remettre un peu de mati\\u00e8re grasse et faire dorer la viande\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-10306f0\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Lorsque l'agneau a pris couleur, ajouter les \\u00e9pices \\u00e0 tajine et continuer \\u00e0 faire rissoler pendant une minute (\\u00e7a sent bon !)\",\"text\":\"Lorsque l'agneau a pris couleur, ajouter les \\u00e9pices \\u00e0 tajine et continuer \\u00e0 faire rissoler pendant une minute (\\u00e7a sent bon !)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-c4ae136\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Puis ajouter les oignons, le miel, les 3\\\/4 des kumquats (gardez en quelques uns pour la d\\u00e9coration), les gousses d'ail en chemise, l'\\u00e9quivalent de 1\\\/2 verre de jus des kumquats et du sel\",\"text\":\"Puis ajouter les oignons, le miel, les 3\\\/4 des kumquats (gardez en quelques uns pour la d\\u00e9coration), les gousses d'ail en chemise, l'\\u00e9quivalent de 1\\\/2 verre de jus des kumquats et du sel\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-bdd6fad\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Enfin, recouvrir d'eau chaude \\u00e0 hauteur\",\"text\":\"Enfin, recouvrir d'eau chaude \\u00e0 hauteur\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-422bcb5\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Go\\u00fbter et rectifier l'assaisonnement - en sel mais aussi en jus de kumquats : vous pouvez tout \\u00e0 fait en ajouter en fonction de votre go\\u00fbt\",\"text\":\"Go\\u00fbter et rectifier l'assaisonnement - en sel mais aussi en jus de kumquats : vous pouvez tout \\u00e0 fait en ajouter en fonction de votre go\\u00fbt\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-6f7d7f1\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Poser un couvercle herm\\u00e9tique et placer au four :soit \\u00e0 160\\u00b0 pendant 2 \\u00e0 3 heuressoit \\u00e0 120\\u00b0 pendant 4 heures (ma m\\u00e9thode pr\\u00e9f\\u00e9r\\u00e9e !)V\\u00e9rifier r\\u00e9guli\\u00e8rement qu'il y a encore du liquide dans la cocotte ; sinon rajouter de l'eau\",\"text\":\"Poser un couvercle herm\\u00e9tique et placer au four :soit \\u00e0 160\\u00b0 pendant 2 \\u00e0 3 heuressoit \\u00e0 120\\u00b0 pendant 4 heures (ma m\\u00e9thode pr\\u00e9f\\u00e9r\\u00e9e !)V\\u00e9rifier r\\u00e9guli\\u00e8rement qu'il y a encore du liquide dans la cocotte ; sinon rajouter de l'eau\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-77cb8fc\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Servir bien chaud, avec le reste des kumquats r\\u00e9chauff\\u00e9s, des amandes \\u00e9mond\\u00e9es torr\\u00e9fi\\u00e9es ainsi que des pluches de coriandre\",\"text\":\"Servir bien chaud, avec le reste des kumquats r\\u00e9chauff\\u00e9s, des amandes \\u00e9mond\\u00e9es torr\\u00e9fi\\u00e9es ainsi que des pluches de coriandre\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/tajine-agneau-kumquats-confits\\\/#wpzoom-rcb-943de34\",\"image\":\"\"}]}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"4.7\",\"ratingCount\":3,\"reviewCount\":1},\"video\":{\"@type\":\"VideoObject\",\"name\":\"Tajine d'agneau et kumquats confits\",\"description\":\"Un tajine en sucr\\u00e9\\\/sal\\u00e9 qui vous surprendra !\",\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-agneau-kumquats-confits-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/youtu.be\\\/1_C2_qbdzaw\",\"embedUrl\":\"https:\\\/\\\/youtu.be\\\/1_C2_qbdzaw\",\"uploadDate\":\"2022-02-22T13:15:26+02:00\",\"duration\":\"\"}}<\/script><\/div><!-- \/.wp-block-wpzoom-recipe-card-block-recipe-card -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11548ef1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11548ef1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-6c0d9b56\" data-id=\"6c0d9b56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3761eda8 elementor-widget elementor-widget-text-editor\" data-id=\"3761eda8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Pour pr\u00e9parer ce d\u00e9licieux plat mijot\u00e9, vous pourrez faire vous-m\u00eame vos propres <a href=\"https:\/\/www.minutepapillote.com\/epices-tajine\/\">\u00e9pices tajine<\/a>. Une merveille ! (mais aussi pratique et \u00e9conomique !)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-40239bdd\" data-id=\"40239bdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-373ab7ee elementor-widget elementor-widget-image\" data-id=\"373ab7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/epices-tajine-portrait-750x500.jpeg\" class=\"attachment-loop-sticky size-loop-sticky wp-image-8763\" alt=\"bocal d&apos;\u00e9pices \u00e0 tajine maison pr\u00eat \u00e0 l&apos;emploi\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/epices-tajine-portrait-750x500.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/epices-tajine-portrait-360x240.jpeg 360w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7293585 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7293585\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79168ed\" data-id=\"79168ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a826ca elementor-widget elementor-widget-spacer\" data-id=\"9a826ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-145c36c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145c36c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a495ac3\" data-id=\"a495ac3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67429cf elementor-widget elementor-widget-text-editor\" data-id=\"67429cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Envie de tout savoir sur comment r\u00e9ussir son tajine ? D\u00e9couvrez<a href=\"https:\/\/www.minutepapillote.com\/astuces-tajine-agneau\/\"> ici<\/a> toutes les astuces !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-74ba303\" data-id=\"74ba303\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86ecb48 elementor-widget elementor-widget-image\" data-id=\"86ecb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.minutepapillote.com\/astuces-tajine-agneau\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine.jpeg\" class=\"attachment-large size-large wp-image-8811\" alt=\"toutes les solutions pour faire un bon tajine\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine.jpeg 1200w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine-300x225.jpeg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine-768x576.jpeg 768w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine-750x563.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2023\/02\/comment-faire-un-bon-tajine-500x375.jpeg 500w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c352a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c352a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ceec62\" data-id=\"1ceec62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d107f2a elementor-widget elementor-widget-spacer\" data-id=\"d107f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0338a50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0338a50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-70dd8f0\" data-id=\"70dd8f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e61f414 elementor-widget elementor-widget-text-editor\" data-id=\"e61f414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Juste avant de servir ce tajine, vous pouvez proposer \u00e0 vos invit\u00e9s ces amuse bouche de <a href=\"https:\/\/www.minutepapillote.com\/creme-betteraves-chantilly-raifort\/\">cr\u00e8me de betteraves avec sa chantilly raifort.<\/a>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e21ed94\" data-id=\"e21ed94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6907b92 elementor-widget elementor-widget-image\" data-id=\"6907b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/creme-de-betteraves-et-chantilly-raifort-1-750x530.jpeg\" class=\"attachment-large size-large wp-image-6988\" alt=\"verrines chic pour un go\u00fbt surprenant et s\u00e9duisant\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/creme-de-betteraves-et-chantilly-raifort-1-750x530.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/creme-de-betteraves-et-chantilly-raifort-1-750x530-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c605ad2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c605ad2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff4653a\" data-id=\"ff4653a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3e5735 elementor-widget elementor-widget-spacer\" data-id=\"f3e5735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70a832ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70a832ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5e7ad952\" data-id=\"5e7ad952\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19975789 elementor-widget elementor-widget-text-editor\" data-id=\"19975789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Et pour finir sur une touche d&rsquo;agrumes, cette <a href=\"https:\/\/www.minutepapillote.com\/salade-pamplemousse-gelee-verveine\/\">salade de pamplemousse et sa gel\u00e9e l\u00e9g\u00e8re de verveine infus\u00e9e<\/a>\u00a0fera merveille !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-52d0f3cb\" data-id=\"52d0f3cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f1bd29 elementor-widget elementor-widget-image\" data-id=\"6f1bd29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/salade-de-pamplemousse-en-gelee-legere-de-verveine-recette-750x530.jpeg\" class=\"attachment-large size-large wp-image-7199\" alt=\"La recette de la salade de pamplemousse et verveine\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les kumquats&#8230; Comme ils sont color\u00e9s et s\u00e9duisants ! Ils nous font de l&rsquo;oeil sur les \u00e9tals, n&rsquo;est-ce-pas ? Mais peuvent nous laisser perplexes. Car comment les cuisiner ? Et avec quel produit les associer ? Rassurez-vous, c&rsquo;est tr\u00e8s simple ! Je vous propose ici [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[410,413,414],"tags":[117,74,122],"class_list":["post-7234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plats-principaux","category-sans-gluten","category-sans-lactose","tag-epices","tag-facile","tag-sans-gluten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tajine d&#039;agneau et kumquats confits - Minute Papillote<\/title>\n<meta name=\"description\" content=\"Ce tajine d&#039;agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tajine d&#039;agneau et kumquats confits\" \/>\n<meta property=\"og:description\" content=\"Ce tajine d&#039;agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/\" \/>\n<meta property=\"og:site_name\" content=\"Minute Papillote\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T12:15:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T17:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/\"},\"author\":{\"name\":\"Helene\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"headline\":\"Tajine d&rsquo;agneau et kumquats confits\",\"datePublished\":\"2022-02-22T12:15:26+00:00\",\"dateModified\":\"2025-10-09T17:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/\"},\"wordCount\":1256,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg\",\"keywords\":[\"\u00e9pices\",\"facile\",\"sans gluten\"],\"articleSection\":[\"Plats principaux\",\"Sans gluten\",\"Sans lactose\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/\",\"name\":\"Tajine d'agneau et kumquats confits - Minute Papillote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg\",\"datePublished\":\"2022-02-22T12:15:26+00:00\",\"dateModified\":\"2025-10-09T17:38:20+00:00\",\"description\":\"Ce tajine d'agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg\",\"width\":2560,\"height\":1811,\"caption\":\"tajine d'agneau et kumquats confits, la photo du r\u00e9gal en sucr\u00e9 sal\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/tajine-agneau-kumquats-confits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.minutepapillote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tajine d&rsquo;agneau et kumquats confits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/\",\"name\":\"MinutePapillote\",\"description\":\"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minutepapillote.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\",\"name\":\"Helene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"width\":498,\"height\":245,\"caption\":\"Helene\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\"},\"sameAs\":[\"https:\\\/\\\/www.minutepapillote.com\",\"https:\\\/\\\/www.instagram.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ-l3TtP5ifNkp2Cb_ZmIkw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tajine d'agneau et kumquats confits - Minute Papillote","description":"Ce tajine d'agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/","og_locale":"en_US","og_type":"article","og_title":"Tajine d'agneau et kumquats confits","og_description":"Ce tajine d'agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !","og_url":"https:\/\/www.minutepapillote.com\/en\/tajine-agneau-kumquats-confits\/","og_site_name":"Minute Papillote","article_published_time":"2022-02-22T12:15:26+00:00","article_modified_time":"2025-10-09T17:38:20+00:00","og_image":[{"width":2560,"height":1811,"url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Helene","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#article","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/"},"author":{"name":"Helene","@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"headline":"Tajine d&rsquo;agneau et kumquats confits","datePublished":"2022-02-22T12:15:26+00:00","dateModified":"2025-10-09T17:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/"},"wordCount":1256,"commentCount":2,"publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"image":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg","keywords":["\u00e9pices","facile","sans gluten"],"articleSection":["Plats principaux","Sans gluten","Sans lactose"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/","url":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/","name":"Tajine d'agneau et kumquats confits - Minute Papillote","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#primaryimage"},"image":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg","datePublished":"2022-02-22T12:15:26+00:00","dateModified":"2025-10-09T17:38:20+00:00","description":"Ce tajine d'agneau aux kumquats confits est tr\u00e8s simple \u00e0 faire et sa cuisson lente lui donnera un fondant incroyable !","breadcrumb":{"@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#primaryimage","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/tajine-dagneau-et-kumquats-confits-1-scaled.jpeg","width":2560,"height":1811,"caption":"tajine d'agneau et kumquats confits, la photo du r\u00e9gal en sucr\u00e9 sal\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minutepapillote.com\/tajine-agneau-kumquats-confits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.minutepapillote.com\/"},{"@type":"ListItem","position":2,"name":"Tajine d&rsquo;agneau et kumquats confits"}]},{"@type":"WebSite","@id":"https:\/\/www.minutepapillote.com\/#website","url":"https:\/\/www.minutepapillote.com\/","name":"MinutePapillote","description":"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs","publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minutepapillote.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c","name":"Helene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","width":498,"height":245,"caption":"Helene"},"logo":{"@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png"},"sameAs":["https:\/\/www.minutepapillote.com","https:\/\/www.instagram.com\/helene_minutepapillote\/","https:\/\/www.pinterest.com\/helene_minutepapillote\/","https:\/\/www.youtube.com\/channel\/UCJ-l3TtP5ifNkp2Cb_ZmIkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":0,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media\/7262"}],"wp:attachment":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}