{"id":7132,"date":"2022-02-16T14:02:20","date_gmt":"2022-02-16T13:02:20","guid":{"rendered":"https:\/\/www.minutepapillote.com\/?p=7132"},"modified":"2023-10-19T05:13:14","modified_gmt":"2023-10-19T04:13:14","slug":"pesto-chou-kale-noisettes","status":"publish","type":"post","link":"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/","title":{"rendered":"Pesto de chou kale et noisettes &#8211; chouette, c&rsquo;est l&rsquo;hiver !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7132\" class=\"elementor elementor-7132\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95294c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95294c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-451c7e5\" data-id=\"451c7e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4861181 elementor-widget elementor-widget-text-editor\" data-id=\"4861181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aujourd&rsquo;hui, zoom sur un <strong>superaliment<\/strong> de l&rsquo;hiver. Il n&rsquo;y en a pas tant que \u00e7a, alors n&rsquo;h\u00e9sitez pas, foncez sur cette recette de pesto de chou kale et noisettes ! Et puisqu&rsquo;elle a beaucoup pour plaire, cette p&rsquo;tite recette est aussi d&rsquo;une <strong>grande simplicit\u00e9<\/strong> \u00e0 faire. Qui plus est, elle peut tr\u00e8s bien se pr\u00e9parer en <strong>last minute<\/strong>, lorsque les copains d\u00e9barquent \u00e0 l&rsquo;improviste, belle-maman reste finalement d\u00eener ou bien encore, les enfants ont TRES faim, l\u00e0, maintenant, tout de suite ! (Oui, je sais, cela n&rsquo;arrive pas souvent&#8230;)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56466eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56466eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74ac4642\" data-id=\"74ac4642\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-527e5a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"527e5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ma_petite_recette\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aller \u00e0 la recette<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-615d6cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"615d6cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9647a7\" data-id=\"e9647a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f4ef5a elementor-widget elementor-widget-spacer\" data-id=\"0f4ef5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72faa42 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72faa42\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45b8d75\" data-id=\"45b8d75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-482a25e elementor-widget elementor-widget-heading\" data-id=\"482a25e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">L&#039;article en un coup d&#039;oeil :<\/span>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #f4926a;color:#f4926a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #f4926a;color:#f4926a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/#Le_chou_KALE_le_legume_SANTE_par_excellence\" >Le chou KALE : le l\u00e9gume SANTE par excellence<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/#Une_recette_SIMPLE_pour_ce_delicieux_pesto_de_chou_kale_et_noisettes\" >Une recette SIMPLE pour ce d\u00e9licieux pesto de chou kale et noisettes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/#Le_pesto_de_chou_kale_et_noisettes_la_recette_CHALEUREUSE_et_CONVIVIALE\" >Le pesto de chou kale et noisettes : la recette CHALEUREUSE et CONVIVIALE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/#Pesto_de_chou_kale_et_noisettes\" >Pesto de chou kale et noisettes<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Le_chou_KALE_le_legume_SANTE_par_excellence\"><\/span>Le chou KALE : le l\u00e9gume SANTE par excellence<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf78a9 e-transform elementor-widget elementor-widget-text-editor\" data-id=\"5bf78a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je vous parlais d&rsquo;un zoom sur ce superaliment de l&rsquo;hiver. Ce l\u00e9gume presque oubli\u00e9 a reparu sur les \u00e9tals anglo-saxons il y a quelques ann\u00e9es et se trouve maintenant facilement en Europe de l&rsquo;ouest, o\u00f9 il est en passe de devenir pl\u00e9biscit\u00e9. Quant \u00e0 l&rsquo;Europe centrale, o\u00f9 j&rsquo;ai v\u00e9cu quelques ann\u00e9es, ce l\u00e9gume n&rsquo;a jamais \u00e9t\u00e9 oubli\u00e9 car il pousse d&rsquo;autant mieux&#8230; qu&rsquo;il fait froid ! C&rsquo;est donc un indispensable de la cuisine du quotidien.<\/p><p>Mais ne nous \u00e9garons pas, revenons \u00e0 notre petit chou. \u00a0Il est tout d&rsquo;abord charg\u00e9 en vitamines C et K. C&rsquo;est aussi une bombe de calcium. Des fibres aussi. Tout cela avec justes quelques calories, \u00e0 peine visibles. S\u00e9duissant, non ? <br \/>Et attendez de voir la simplicit\u00e9 de cette recette de pesto de chou kale aux noisettes &#8211; d&rsquo;une facilit\u00e9 incroyable !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d198020 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d198020\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c832f2b\" data-id=\"c832f2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c87d98 elementor-widget elementor-widget-text-editor\" data-id=\"2c87d98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">\u00a0<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">Mais d&rsquo;ailleurs, avez-vous d\u00e9j\u00e0 rep\u00e9r\u00e9 le chou kale chez votre primeur ou au rayon fruits et l\u00e9gumes de votre fournisseur pr\u00e9f\u00e9r\u00e9 ?\u00a0<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">Voici \u00e0 quoi ressemble une feuille :<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d0fc6b\" data-id=\"9d0fc6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa14658 elementor-widget elementor-widget-image\" data-id=\"aa14658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/feuille-de-chou-kale-300x212.jpeg\" class=\"attachment-medium size-medium wp-image-7153\" alt=\"a quoi ressemble une feuille de chou kale\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/feuille-de-chou-kale-300x212.jpeg 300w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/feuille-de-chou-kale.jpeg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9955396 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9955396\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c5f53b\" data-id=\"2c5f53b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9e599b elementor-widget elementor-widget-spacer\" data-id=\"e9e599b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26afaeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26afaeb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd0f311\" data-id=\"cd0f311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7bc893 elementor-widget elementor-widget-heading\" data-id=\"b7bc893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Une_recette_SIMPLE_pour_ce_delicieux_pesto_de_chou_kale_et_noisettes\"><\/span>Une recette SIMPLE pour ce d\u00e9licieux pesto de chou kale et noisettes<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec722ea elementor-widget elementor-widget-text-editor\" data-id=\"ec722ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je suis d&rsquo;accord avec vous, il vous faudra tout de m\u00eame du chou kale. Mais finalement, ce l\u00e9gume se conserve tr\u00e8s bien. Au r\u00e9frig\u00e9rateur, dans le bac \u00e0 l\u00e9gumes par exemple, ou encore mieux, \u00e0 la mani\u00e8re de mon amie Chantal du blog <a href=\"https:\/\/lesmenusplaisir.com\/les-chips-de-kale\/\">www.lesmenusplaisir.com<\/a>\u00a0. Elle propose de conserver le kale dans \u00ab\u00a0un pot rempli d&rsquo;eau, \u00e0 temp\u00e9rature ambiante\u00a0\u00bb. Malin et fastoche, non ?<\/p><p>Pour cette recette, il vous faudra aussi du parmesan, r\u00e2p\u00e9 ou non. Du domaine du faisable, non ? Quant aux noisettes propos\u00e9es dans cette recette, vous pouvez tr\u00e8s bien les remplacer par des pignons de pin, comme dans le classique pesto de basilic. Ou par des graines de tournesol. Ou des noix de cajou. En fait, ce que vous avez dans votre placard !<\/p><p><br \/>Vous voulez conna\u00eetre une autre bonne nouvelle ? \u00a0Les quantit\u00e9s indiqu\u00e9es dans la recette ci-dessous sont MODULABLES. Vous adorez le parmesan ? Mettez en un peu plus ! Ou au contraire, les enfants ont d\u00e9j\u00e0 consomm\u00e9 presque tout le paquet dans leurs p\u00e2tes hier soir ? Mettez en un peu moins, inutile d&rsquo;aller courir \u00e0 la sup\u00e9rette encore ouverte, voire de vous faire livrer. M\u00eame chose pour l&rsquo;huile d&rsquo;olive, pour une recette all\u00e9g\u00e9e. Bref, avec cette recette de pesto de chou kale et noisettes, ON SE DETEND !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4ccdfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4ccdfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f402804\" data-id=\"f402804\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72286e0 elementor-widget elementor-widget-heading\" data-id=\"72286e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Le_pesto_de_chou_kale_et_noisettes_la_recette_CHALEUREUSE_et_CONVIVIALE\"><\/span>Le pesto de chou kale et noisettes : la recette CHALEUREUSE et CONVIVIALE<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5bf4cc elementor-widget elementor-widget-text-editor\" data-id=\"a5bf4cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette recette modulable et toute simple \u00e0 faire se servira aussi de mani\u00e8re&#8230; toute simple ! Pas besoin de mettre les petits plats dans les grands. On met le bol au centre de la table, le pain grill\u00e9 (mmmh, le pain aux noisettes toast\u00e9&#8230;) juste \u00e0 c\u00f4t\u00e9. Une invitation \u00e0 se servir soi-m\u00eame, faire une p&rsquo;tite tartine pour sa voisine, se faire offrir une branchette de pain par son voisin. Pas de chichis, on est l\u00e0 pour \u00eatre ensemble, savourer le temps qui passe, sans souci de l&rsquo;apr\u00e8s. ON EST BIEN.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fb58a13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fb58a13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f05891e\" data-id=\"1f05891e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2111f1b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2111f1b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-258c957b\" data-id=\"258c957b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c15c608 elementor-widget elementor-widget-menu-anchor\" data-id=\"7c15c608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ma_petite_recette\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f0022da elementor-widget elementor-widget-wpzoom-elementor-recipe-card-widget\" data-id=\"4f0022da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;recipe_card_styles&quot;:&quot;is-style-newdesign&quot;,&quot;video_type&quot;:&quot;embed&quot;}\" data-widget_type=\"wpzoom-elementor-recipe-card-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"wpzoom-premium-recipe-card\" class=\"wp-block-wpzoom-recipe-card-block-recipe-card is-style-newdesign block-alignment-left header-content-align-left\"><div class=\"recipe-card-image\"><figure><img decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-de-chou-kale-et-noisettes-750x530.jpeg\" class=\"wpzoom-recipe-card-image\" alt=\"Pesto de chou kale et noisettes\" id=\"7140\" \/><figcaption><div class=\"wpzoom-recipe-card-pinit\">\n\t            <a class=\"btn-pinit-link no-print\" data-pin-do=\"buttonPin\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url=https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/&#038;media=https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-de-chou-kale-et-noisettes-750x530.jpeg&#038;description=\" data-pin-custom=\"true\" aria-label=\"Pin recipe on Pinterest\" title=\"Pin recipe on Pinterest\" >\n\t            \t<SVG class=\"wpzoom-rcb-icon-pinit-link\" enable-background=\"new 0 0 30 30\" height=\"30px\" id=\"Pinterest\" version=\"1.1\" viewBox=\"0 0 30 30\" width=\"30px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t            \t    <Path class=\"wpzoom-rcb-pinit-icon\" d=\"M16,0C7.813,0,3,6.105,3,11c0,2.964,2,6,3,6s2,0,2-1s-2-2-2-5c0-4.354,4.773-8,10-8c4.627,0,7,3.224,7,7  c0,4.968-2.735,9-6,9c-1.803,0-3.433-1.172-3-3c0.519-2.184,1-2,2-6c0.342-1.368-0.433-3-2-3c-1.843,0-4,1.446-4,4c0,1.627,1,3,1,3  s-2.245,7.863-2.576,9.263C7.766,26.049,6.938,30,7.938,30S10,28,12,23c0.295-0.738,1-3,1-3c0.599,1.142,3.14,2,5,2  c5.539,0,9-5.24,9-12C27,4.888,22.58,0,16,0z\" \/>\n\t            \t<\/SVG>\n\t            \t<span>Pin<\/span>\n\t            <\/a>\n\t        <\/div><div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link elementor-rcb-print-button no-print\" href=\"#\">\n                <svg class=\"wpzoom-rcb-icon-print-link\" width=\"32\" height=\"32\" viewBox=\"0 0 19 18\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M5 7.2C4.822 7.2 4.64799 7.25278 4.49999 7.35168C4.35198 7.45057 4.23663 7.59113 4.16851 7.75558C4.10039 7.92004 4.08257 8.101 4.11729 8.27558C4.15202 8.45016 4.23774 8.61053 4.3636 8.7364C4.48947 8.86226 4.64984 8.94798 4.82442 8.98271C4.999 9.01743 5.17996 8.99961 5.34441 8.93149C5.50887 8.86337 5.64943 8.74802 5.74832 8.60001C5.84722 8.45201 5.9 8.278 5.9 8.1C5.9 7.8613 5.80518 7.63239 5.6364 7.4636C5.46761 7.29482 5.23869 7.2 5 7.2ZM15.8 3.6H14.9V0.9C14.9 0.661305 14.8052 0.432387 14.6364 0.263604C14.4676 0.0948211 14.2387 0 14 0H5C4.76131 0 4.53239 0.0948211 4.3636 0.263604C4.19482 0.432387 4.1 0.661305 4.1 0.9V3.6H3.2C2.48392 3.6 1.79716 3.88446 1.29081 4.39081C0.784464 4.89716 0.5 5.58392 0.5 6.3V11.7C0.5 12.4161 0.784464 13.1028 1.29081 13.6092C1.79716 14.1155 2.48392 14.4 3.2 14.4H4.1V17.1C4.1 17.3387 4.19482 17.5676 4.3636 17.7364C4.53239 17.9052 4.76131 18 5 18H14C14.2387 18 14.4676 17.9052 14.6364 17.7364C14.8052 17.5676 14.9 17.3387 14.9 17.1V14.4H15.8C16.5161 14.4 17.2028 14.1155 17.7092 13.6092C18.2155 13.1028 18.5 12.4161 18.5 11.7V6.3C18.5 5.58392 18.2155 4.89716 17.7092 4.39081C17.2028 3.88446 16.5161 3.6 15.8 3.6ZM5.9 1.8H13.1V3.6H5.9V1.8ZM13.1 16.2H5.9V12.6H13.1V16.2ZM16.7 11.7C16.7 11.9387 16.6052 12.1676 16.4364 12.3364C16.2676 12.5052 16.0387 12.6 15.8 12.6H14.9V11.7C14.9 11.4613 14.8052 11.2324 14.6364 11.0636C14.4676 10.8948 14.2387 10.8 14 10.8H5C4.76131 10.8 4.53239 10.8948 4.3636 11.0636C4.19482 11.2324 4.1 11.4613 4.1 11.7V12.6H3.2C2.9613 12.6 2.73239 12.5052 2.5636 12.3364C2.39482 12.1676 2.3 11.9387 2.3 11.7V6.3C2.3 6.0613 2.39482 5.83239 2.5636 5.6636C2.73239 5.49482 2.9613 5.4 3.2 5.4H15.8C16.0387 5.4 16.2676 5.49482 16.4364 5.6636C16.6052 5.83239 16.7 6.0613 16.7 6.3V11.7Z\" \/>\n                    <\/svg>\n\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div><\/figcaption><\/figure><\/div><!-- \/.recipe-card-image --><div class=\"recipe-card-heading\"><h2 class=\"recipe-card-title\"><span class=\"ez-toc-section\" id=\"Pesto_de_chou_kale_et_noisettes\"><\/span>Pesto de chou kale et noisettes<span class=\"ez-toc-section-end\"><\/span><\/h2><div class=\"recipe-sub-title\"><span class=\"recipe-card-author\">Recipe by Helene<\/span><div class=\"wpzoom-rating-stars-container\" data-rating=\"5.0\" data-rating-total=\"3\" data-recipe-id=\"7132\" data-post-id=\"7132\" data-user-can-rate=\"1\">\n\t\t\t\t<ul class=\"wpzoom-rating-stars\"><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><\/ul><span class=\"wpzoom-rating-stars-average\"><span class=\"wpzoom-rating-average\">5.0<\/span> from <span class=\"wpzoom-rating-total-votes\">3<\/span> votes<\/span>\n\t\t\t\t<em class=\"wpzoom-rating-stars-tooltip\"><\/em>\n\t\t\t<\/div><\/div><\/div><!-- \/.recipe-card-heading --><div class=\"wpzoom-nosleep-toggle-container\">\n        <label class=\"switch\">\n            <input type=\"checkbox\" id=\"toggle_button\">\n            <div class=\"slider round\"><\/div>\n        <\/label><span class=\"wpzoom-nosleep-label\">Cook Mode<\/span><p class=\"recipe-card-no-sleep no-print\">Permet \u00e0 la recette de rester visible plus longtemps<\/p><\/div><div class=\"recipe-card-details\"><div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 1024 1024\"><path d=\"M768 520V51q0-10-4-19.5T753 15q-7-7-16.5-11T717 0q-10 0-19.5 4T681 15q-8 7-11.5 16.5T666 51v469q-34 9-62.5 29T555 596q-21 28-32 61t-11 67q0 40 14 91t40.5 97q26.5 46 64.5 78 38 31 86 31 47 0 85-31 38-32 64.5-78t40.5-97q15-51 15-91 0-34-11-67t-32-61q-21-27-49.5-47T768 520zm-51 402q-31 0-67-68t-36-127q-1-21 6.5-41.5T642 650q15-16 34-25.5t41-10.5q21 1 40.5 10.5T791 650q15 15 22 35.5t6 41.5q0 59-35.5 127T717 922zM358 0q-10 0-19.5 4T322 15q-7 7-11 16.5T307 51v280l-51 34V51q0-10-4-19.5T241 15q-7-7-16.5-11T205 0q-10 0-19.5 4T169 15q-8 7-11.5 16.5T154 51v314l-52-34V51q0-10-3.5-19.5T87 15Q80 8 70.5 4T51 0Q41 0 31.5 4T15 15Q8 22 4 31.5T0 51v307q0 7 1.5 13T6 383q3 5 7.5 9.5T23 401l131 87v485q0 10 3.5 19.5T169 1009q7 7 16.5 11t19.5 4q10 0 19.5-4t16.5-11q7-7 11-16.5t4-19.5V488l131-87q5-4 9-8.5t7-9.5q3-6 5-12t2-13V51q0-10-4-19.5T395 15q-8-7-17-11t-20-4z\" \/><\/svg><\/span><span class=\"detail-item-label\">Servings<\/span><p class=\"detail-item-value\">6<\/p><span class=\"detail-item-unit\">servings<\/span><\/div><div class=\"detail-item detail-item-1\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 0C9.62663 0 7.30655 0.703788 5.33316 2.02236C3.35977 3.34094 1.8217 5.21508 0.913451 7.4078C0.00519941 9.60051 -0.232441 12.0133 0.230582 14.3411C0.693605 16.6689 1.83649 18.807 3.51472 20.4853C5.19295 22.1635 7.33115 23.3064 9.65892 23.7694C11.9867 24.2324 14.3995 23.9948 16.5922 23.0865C18.7849 22.1783 20.6591 20.6402 21.9776 18.6668C23.2962 16.6934 24 14.3734 24 12C24 10.4241 23.6896 8.8637 23.0866 7.4078C22.4835 5.95189 21.5996 4.62902 20.4853 3.51472C19.371 2.40041 18.0481 1.5165 16.5922 0.913445C15.1363 0.310389 13.5759 0 12 0ZM12 21.6C10.1013 21.6 8.24524 21.037 6.66653 19.9821C5.08782 18.9272 3.85736 17.4279 3.13076 15.6738C2.40416 13.9196 2.21405 11.9893 2.58447 10.1271C2.95488 8.26491 3.86919 6.55436 5.21178 5.21177C6.55436 3.86919 8.26492 2.95488 10.1271 2.58446C11.9894 2.21404 13.9196 2.40415 15.6738 3.13076C17.4279 3.85736 18.9272 5.08781 19.9821 6.66652C21.037 8.24524 21.6 10.1013 21.6 12C21.6 14.5461 20.5886 16.9879 18.7882 18.7882C16.9879 20.5886 14.5461 21.6 12 21.6ZM15.72 12.756L13.2 11.304V6C13.2 5.68174 13.0736 5.37651 12.8485 5.15147C12.6235 4.92643 12.3183 4.8 12 4.8C11.6817 4.8 11.3765 4.92643 11.1515 5.15147C10.9264 5.37651 10.8 5.68174 10.8 6V12C10.8 12 10.8 12.096 10.8 12.144C10.8071 12.2267 10.8274 12.3077 10.86 12.384C10.8847 12.4552 10.9169 12.5236 10.956 12.588C10.9888 12.6562 11.0291 12.7206 11.076 12.78L11.268 12.936L11.376 13.044L14.496 14.844C14.6789 14.9477 14.8858 15.0014 15.096 15C15.3617 15.0019 15.6205 14.9155 15.8318 14.7544C16.0431 14.5933 16.195 14.3667 16.2637 14.11C16.3323 13.8533 16.3138 13.5811 16.2111 13.3361C16.1083 13.091 15.9272 12.887 15.696 12.756H15.72Z\" fill=\"currentColor\" \/><\/svg><\/span><span class=\"detail-item-label\">Prep time<\/span><p class=\"detail-item-value\">10<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><div class=\"detail-item detail-item-2\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg viewbox=\"0 0 512.0016 512.0155\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 278.014q1 34-21 46-13 6-30 5v84q0 41-28 70t-70 29H151q-42 0-72-29t-30-70v-84q-16 1-28-5-22-12-21-46 0-8 7-11.5t13.5 0q6.5 3.5 5.5 11.5 0 18 8 23 5 3 15 2v-52q15 11 62 19 60 9 145.5 9t149.5-10q38-6 55-14v48q11 1 17-2 8-5 8-23-1-8 5.5-11.5t13.5 0q7 3.5 7 11.5zm-150 193q29-10 43-37t13.5-57q-.5-30-.5-60v-12q-1-10-10-14.5t-17.5 0q-8.5 4.5-8.5 14.5 1 5 2 21t1.5 26q.5 10-1 26t-4.5 26.5q-3 10.5-10 20t-17 13.5q-10 3-12 13t4.5 17q6.5 7 16.5 3zm-310-237q0-12 .5-16.5t6-13q5.5-8.5 16.5-13t33.5-8.5q22.5-4 56.5-6-11 3-10 15 0 6 4 10t11 4h1q28-1 49-21l5-4q3-4 6-7h25q23 0 44 1 2 1 5 4l6 6q21 20 49 21h1q7 0 11-4t4-10q1-9-7-14 35 3 56 8t29.5 13.5q8.5 8.5 10 14.5t1.5 19q0 3-5 6-15 12-73.5 19.5t-131.5 7.5q-75 0-132-7.5t-69-19.5q-3-2-3-5zm158-73q4-3 6-5 13-11 29-13l.5-.5.5-.5q3 0 8-1h18q5 0 6.5.5t5.5 1.5h4q15 3 27 13l6 6q1 0 2 1t1 2q3 2 5 4 4 4 8 7 11 7 24 8 9 1 8 8l-4 6v4l-3-4q-27-2-45-19l-4-4q-1-2-2-2l-5-5q-5-4-9-7-7-3-17-5h-1q-3-1-5-1-4-1-8-1h-12q-3 0-5 1-8 1-15 6-4 3-8 7-3 3-7 6l-4 5q-19 17-44 19-4 0-5.5-2t-1.5-4q0-8 7-8 13-1 24-9 4-3 8-7 2-1 4-3 1-1 3-4zm-53-157q4-5 9.5-3t7.5 7.5q2 5.5-2 11.5-5 7-5 13.5t3 11l8 12q5 7.5 7 11.5 12 25 0 50-3 6-8.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3-15.5t-4.5-13.5q-2.5-5-8-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 7.5 12t7 11.5q13 25 1 50-4 6-9.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 8 12t7.5 11.5q12 25 0 50-4 6-9.5 6t-9-5.5q-3.5-5.5-1.5-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-10-24 8-48z\" \/><\/svg><\/span><span class=\"detail-item-label\">Cooking time<\/span><p class=\"detail-item-value\">1<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><\/div><!-- \/.details-items --><\/div><!-- \/.recipe-card-details --><div class=\"recipe-card-food-labels\"><ul class=\"food-labels-list\"><\/ul><\/div><div class=\"recipe-card-ingredients\"><h3 class=\"ingredients-title\">Ingredients<\/h3><ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5c82\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>140g chou kale (sans la nervure centrale)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5cc7\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>40g parmesan<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5cf0\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>40g noisettes grill\u00e9es<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5d14\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>1 petite gousse d'ail (ou de l'huile aromatis\u00e9e \u00e0 l'ail comme dans cette <a href=\"https:\/\/www.minutepapillote.com\/huile-d-ail-confit\/\">huile \u00e0 l'ail confit<\/a> fa\u00e7on Ottolenghi)<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5d5a\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>8Og huile d'olive (ou moins si vous pr\u00e9f\u00e9rez).\u00a0<\/p><p>NB : si vous utilisez de l'huile \u00e0 l'ail, r\u00e9duisez la quantit\u00e9 d'huile d'olive \u00e0 ajouter<\/p><\/span><\/div><\/li><li id=\"wpzoom-rcb-ingredient-item-6a56e2d1e5d8d\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><div class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><p>sel<\/p><\/span><\/div><\/li><\/ul><\/div><!-- \/.recipe-card-ingredients --><div class=\"recipe-card-directions\"><h3 class=\"directions-title\">Directions<\/h3><ul class=\"directions-list\"><li id=\"wpzoom-rcb-62451a6\" class=\"direction-step\"><p>Apr\u00e8s avoir enlev\u00e9 la nervure centrale du kale, plonger les feuilles dans une casserole d'eau bouillante. Pocher pendant 30 secondes \u00e0 1 minute, l'objectif est de ramollir les feuilles sans toutefois les faire cuire<\/p><\/li><li id=\"wpzoom-rcb-f36e068\" class=\"direction-step\"><p>Essorer grossi\u00e8rement les feuilles (il peut rester un tout peu d'eau) et placer dans le bol du mixer avec l'ail, le parmesan et les noisettes<\/p><\/li><li id=\"wpzoom-rcb-346ffe3\" class=\"direction-step\"><p>Mixer grossi\u00e8rement\u00a0<\/p><\/li><li id=\"wpzoom-rcb-7a09cd2\" class=\"direction-step\"><p>Puis ajouter l'huile d'olive (vous pouvez en mettre un peu moins que la quantit\u00e9 indiqu\u00e9e si vous pr\u00e9f\u00e9rez) et mixer \u00e0 nouveau<\/p><\/li><li id=\"wpzoom-rcb-ca18b68\" class=\"direction-step\"><p>Enfin, ajouter du sel, go\u00fbter et rectifier l'assaisonnement si n\u00e9cessaire<\/p><\/li><li id=\"wpzoom-rcb-8f49579\" class=\"direction-step\"><p>Servir avec des tranches de pain grill\u00e9\u00a0<\/p><\/li><\/ul><\/div><!-- \/.recipe-card-directions --><div class=\"recipe-card-notes\"><h3 class=\"notes-title\">La p&#039;tite astuce<\/h3><ul class=\"recipe-card-notes-list\"><li class=\"wpzoom-rc-note-text\">Vous pouvez remplacer les noisettes par des pignons de pin (comme dans un pesto traditionnel), des noix de cajou ou bien des graines de tournesol. En fait, ce que vous avez dans le placard !<\/li><\/ul><\/div><!-- \/.recipe-card-notes -->\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Pesto de chou kale et noisettes\",\"image\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pesto-de-chou-kale-et-noisettes-750x530.jpeg\",\"description\":\"\",\"keywords\":[\"facile\",\"huile d&#039;olive\",\"parmesan\",\"rapide\",\"sans gluten\",\"sante\"],\"author\":{\"@type\":\"Person\",\"name\":\"Helene\"},\"datePublished\":\"2022-02-16T14:02:20+02:00\",\"prepTime\":\"PT10M\",\"cookTime\":\"PT1M\",\"totalTime\":\"PT11M\",\"recipeCategory\":[\"Ap\\u00e9rotime et entr\\u00e9es\",\"Sans gluten\",\"Sauces et condiments\",\"V\\u00e9g\\u00e9tarien\",\"Vite fait - bien fait\"],\"recipeCuisine\":[],\"recipeYield\":[\"6\",\"6 servings\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"140g chou kale (sans la nervure centrale)\",\"40g parmesan\",\"40g noisettes grill\\u00e9es\",\"1 petite gousse d'ail (ou de l'huile aromatis\\u00e9e \\u00e0 l'ail comme dans cette huile \\u00e0 l'ail confit fa\\u00e7on Ottolenghi)\",\"8Og huile d'olive (ou moins si vous pr\\u00e9f\\u00e9rez).\\u00a0NB : si vous utilisez de l'huile \\u00e0 l'ail, r\\u00e9duisez la quantit\\u00e9 d'huile d'olive \\u00e0 ajouter\",\"sel\"],\"recipeInstructions\":[{\"@type\":\"HowToStep\",\"name\":\"Apr\\u00e8s avoir enlev\\u00e9 la nervure centrale du kale, plonger les feuilles dans une casserole d'eau bouillante. Pocher pendant 30 secondes \\u00e0 1 minute, l'objectif est de ramollir les feuilles sans toutefois les faire cuire\",\"text\":\"Apr\\u00e8s avoir enlev\\u00e9 la nervure centrale du kale, plonger les feuilles dans une casserole d'eau bouillante. Pocher pendant 30 secondes \\u00e0 1 minute, l'objectif est de ramollir les feuilles sans toutefois les faire cuire\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-62451a6\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Essorer grossi\\u00e8rement les feuilles (il peut rester un tout peu d'eau) et placer dans le bol du mixer avec l'ail, le parmesan et les noisettes\",\"text\":\"Essorer grossi\\u00e8rement les feuilles (il peut rester un tout peu d'eau) et placer dans le bol du mixer avec l'ail, le parmesan et les noisettes\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-f36e068\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Mixer grossi\\u00e8rement\\u00a0\",\"text\":\"Mixer grossi\\u00e8rement\\u00a0\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-346ffe3\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Puis ajouter l'huile d'olive (vous pouvez en mettre un peu moins que la quantit\\u00e9 indiqu\\u00e9e si vous pr\\u00e9f\\u00e9rez) et mixer \\u00e0 nouveau\",\"text\":\"Puis ajouter l'huile d'olive (vous pouvez en mettre un peu moins que la quantit\\u00e9 indiqu\\u00e9e si vous pr\\u00e9f\\u00e9rez) et mixer \\u00e0 nouveau\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-7a09cd2\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Enfin, ajouter du sel, go\\u00fbter et rectifier l'assaisonnement si n\\u00e9cessaire\",\"text\":\"Enfin, ajouter du sel, go\\u00fbter et rectifier l'assaisonnement si n\\u00e9cessaire\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-ca18b68\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Servir avec des tranches de pain grill\\u00e9\\u00a0\",\"text\":\"Servir avec des tranches de pain grill\\u00e9\\u00a0\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/pesto-chou-kale-noisettes\\\/#wpzoom-rcb-8f49579\",\"image\":\"\"}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"ratingCount\":3,\"reviewCount\":1}}<\/script><\/div><!-- \/.wp-block-wpzoom-recipe-card-block-recipe-card -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9199052 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9199052\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-39f6251\" data-id=\"39f6251\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5a200 elementor-widget elementor-widget-text-editor\" data-id=\"1a5a200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous aimez le parmesan ? Besoin d&rsquo;id\u00e9es pour un ap\u00e9ritif ? Essayez ces d\u00e9licieux<a href=\"https:\/\/www.minutepapillote.com\/sables-aperitifs-parmesan-et-piment-despelette\/\" target=\"_blank\" rel=\"noopener\"> sabl\u00e9s au parmesan et Piment d&rsquo;Espelette<\/a>\u00a0(ou un autre piment d&rsquo;ailleurs, \u00e7a fonctionne aussi !)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19e88a3\" data-id=\"19e88a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed77a45 elementor-widget elementor-widget-image\" data-id=\"ed77a45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.minutepapillote.com\/sables-aperitifs-parmesan-et-piment-despelette\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/12\/sables-aperitifs-parmesan-3-750x530.jpeg\" class=\"attachment-large size-large wp-image-6916\" alt=\"sabl\u00e9s ap\u00e9ritifs parmesan et piment d&apos;Espelette\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/12\/sables-aperitifs-parmesan-3-750x530.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/12\/sables-aperitifs-parmesan-3-750x530-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, zoom sur un superaliment de l&rsquo;hiver. Il n&rsquo;y en a pas tant que \u00e7a, alors n&rsquo;h\u00e9sitez pas, foncez sur cette recette de pesto de chou kale et noisettes ! Et puisqu&rsquo;elle a beaucoup pour plaire, cette p&rsquo;tite recette est aussi d&rsquo;une grande simplicit\u00e9 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[52,413,55,416,105],"tags":[74,67,46,75,122,106],"class_list":["post-7132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apero-entrees","category-sans-gluten","category-sauces-condiments","category-vegetarien","category-vite-fait-bien-fait","tag-facile","tag-huile-dolive","tag-parmesan","tag-rapide","tag-sans-gluten","tag-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pesto de chou kale et noisettes - chouette, c&#039;est l&#039;hiver ! - Minute Papillote<\/title>\n<meta name=\"description\" content=\"Recette d&#039;hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesto de chou kale et noisettes - chouette, c&#039;est l&#039;hiver !\" \/>\n<meta property=\"og:description\" content=\"Recette d&#039;hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/\" \/>\n<meta property=\"og:site_name\" content=\"Minute Papillote\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T13:02:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-19T04:13:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/\"},\"author\":{\"name\":\"Helene\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"headline\":\"Pesto de chou kale et noisettes &#8211; chouette, c&rsquo;est l&rsquo;hiver !\",\"datePublished\":\"2022-02-16T13:02:20+00:00\",\"dateModified\":\"2023-10-19T04:13:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/\"},\"wordCount\":917,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg\",\"keywords\":[\"facile\",\"huile d&#039;olive\",\"parmesan\",\"rapide\",\"sans gluten\",\"sante\"],\"articleSection\":[\"Ap\u00e9rotime et entr\u00e9es\",\"Sans gluten\",\"Sauces et condiments\",\"V\u00e9g\u00e9tarien\",\"Vite fait - bien fait\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/\",\"name\":\"Pesto de chou kale et noisettes - chouette, c'est l'hiver ! - Minute Papillote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg\",\"datePublished\":\"2022-02-16T13:02:20+00:00\",\"dateModified\":\"2023-10-19T04:13:14+00:00\",\"description\":\"Recette d'hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg\",\"width\":750,\"height\":548,\"caption\":\"un pesto de chou kale facile \u00e0 pr\u00e9parer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/pesto-chou-kale-noisettes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.minutepapillote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesto de chou kale et noisettes &#8211; chouette, c&#8217;est l&#8217;hiver !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/\",\"name\":\"MinutePapillote\",\"description\":\"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minutepapillote.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\",\"name\":\"Helene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"width\":498,\"height\":245,\"caption\":\"Helene\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\"},\"sameAs\":[\"https:\\\/\\\/www.minutepapillote.com\",\"https:\\\/\\\/www.instagram.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ-l3TtP5ifNkp2Cb_ZmIkw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pesto de chou kale et noisettes - chouette, c'est l'hiver ! - Minute Papillote","description":"Recette d'hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/","og_locale":"en_US","og_type":"article","og_title":"Pesto de chou kale et noisettes - chouette, c'est l'hiver !","og_description":"Recette d'hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !","og_url":"https:\/\/www.minutepapillote.com\/en\/pesto-chou-kale-noisettes\/","og_site_name":"Minute Papillote","article_published_time":"2022-02-16T13:02:20+00:00","article_modified_time":"2023-10-19T04:13:14+00:00","og_image":[{"width":750,"height":548,"url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg","type":"image\/jpeg"}],"author":"Helene","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#article","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/"},"author":{"name":"Helene","@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"headline":"Pesto de chou kale et noisettes &#8211; chouette, c&rsquo;est l&rsquo;hiver !","datePublished":"2022-02-16T13:02:20+00:00","dateModified":"2023-10-19T04:13:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/"},"wordCount":917,"commentCount":7,"publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"image":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg","keywords":["facile","huile d&#039;olive","parmesan","rapide","sans gluten","sante"],"articleSection":["Ap\u00e9rotime et entr\u00e9es","Sans gluten","Sauces et condiments","V\u00e9g\u00e9tarien","Vite fait - bien fait"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/","url":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/","name":"Pesto de chou kale et noisettes - chouette, c'est l'hiver ! - Minute Papillote","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#primaryimage"},"image":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg","datePublished":"2022-02-16T13:02:20+00:00","dateModified":"2023-10-19T04:13:14+00:00","description":"Recette d'hiver, simple et chaleureuse par excellence. Ce pesto de chou kale et noisettes sera parfait pour un ap\u00e9ritif convivial !","breadcrumb":{"@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#primaryimage","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2022\/02\/pesto-chou-kale-et-noisettes-en-pot-1-750x548.jpeg","width":750,"height":548,"caption":"un pesto de chou kale facile \u00e0 pr\u00e9parer"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minutepapillote.com\/pesto-chou-kale-noisettes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.minutepapillote.com\/"},{"@type":"ListItem","position":2,"name":"Pesto de chou kale et noisettes &#8211; chouette, c&#8217;est l&#8217;hiver !"}]},{"@type":"WebSite","@id":"https:\/\/www.minutepapillote.com\/#website","url":"https:\/\/www.minutepapillote.com\/","name":"MinutePapillote","description":"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs","publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minutepapillote.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c","name":"Helene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","width":498,"height":245,"caption":"Helene"},"logo":{"@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png"},"sameAs":["https:\/\/www.minutepapillote.com","https:\/\/www.instagram.com\/helene_minutepapillote\/","https:\/\/www.pinterest.com\/helene_minutepapillote\/","https:\/\/www.youtube.com\/channel\/UCJ-l3TtP5ifNkp2Cb_ZmIkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/comments?post=7132"}],"version-history":[{"count":0,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/7132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media\/7148"}],"wp:attachment":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media?parent=7132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/categories?post=7132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/tags?post=7132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}