{"id":6337,"date":"2021-10-04T12:48:17","date_gmt":"2021-10-04T11:48:17","guid":{"rendered":"https:\/\/www.minutepapillote.com\/?p=6337"},"modified":"2026-06-23T16:29:26","modified_gmt":"2026-06-23T14:29:26","slug":"samoussas-au-boeuf-a-peine-epice","status":"publish","type":"post","link":"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/","title":{"rendered":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Chez nous , les samoussas sont un peu comme les muffins sal\u00e9s ou les tartes aux l\u00e9gumes. Un plat simple et r\u00e9confortant, facile \u00e0 pr\u00e9parer, et qui, en outre&#8230;  Permet de valoriser de nombreux petits restes de frigo, impatients de rejoindre nos papilles \u00e9moustill\u00e9es ! Vous l&rsquo;aurez compris, les samoussas chez nous, c&rsquo;est une belle mani\u00e8re de se faire plaisir, tout en faisant partie de la team gourmande #jenejetterien. Ici je vous propose des samoussas au boeuf \u00e0 peine \u00e9pic\u00e9, des triangles croustillants qui r\u00e9v\u00e8lent une farce de boeuf (et oui&#8230;) relev\u00e9e de garam masala, oignons, coriandre&#8230; mais pas que !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">L&#039;article en un coup d&#039;oeil :<\/span>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #f4926a;color:#f4926a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #f4926a;color:#f4926a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/#Les_samoussas_au_boeuf_a_peine_epice_ou_la_creativite_a_lhonneur\" >Les samoussas au boeuf \u00e0 peine \u00e9pic\u00e9, ou la cr\u00e9ativit\u00e9 \u00e0 l&rsquo;honneur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/#Les_samoussas_%E2%80%93_quels_seront_les_votres\" >Les samoussas &#8211; quels seront les v\u00f4tres ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/#Samoussas_au_boeuf_a_peine_epice\" >Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"h-les-samoussas-au-boeuf-a-peine-epice-ou-la-creativite-a-l-honneur\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_samoussas_au_boeuf_a_peine_epice_ou_la_creativite_a_lhonneur\"><\/span>Les samoussas au boeuf \u00e0 peine \u00e9pic\u00e9, ou la cr\u00e9ativit\u00e9 \u00e0 l&rsquo;honneur<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous ne connaissez pas encore tr\u00e8s bien les samoussas, ce sont des triangles de p\u00e2te chaude et croustillante enveloppant une farce tr\u00e8s aromatique \u00e0 base de viande ou de l\u00e9gumes. C&rsquo;est traditionnellement un plat indien, propos\u00e9 fa\u00e7on \u00ab\u00a0street food\u00a0\u00bb par des marchands ambulants. Une douce invitation au voyage&#8230; Ces feuillet\u00e9s ont su s\u00e9duire au cours des si\u00e8cles de nombreuses populations visit\u00e9es par les Indiens. Si bien qu&rsquo;aujourd&rsquo;hui, on peut trouver des samoussas dans de nombreuses r\u00e9gions du monde. La recette de la farce change, la p\u00e2te n&rsquo;est toujours la m\u00eame, la cuisson non plus&#8230; Je vous propose donc ces samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 de mani\u00e8re tout \u00e0 fait d\u00e9complex\u00e9e, tant il est possible de d\u00e9vier et contourner la recette d&rsquo;origine !<\/p>\n\n\n\n<h3 id=\"h-les-samoussas-cuisson-a-la-poele-ou-au-four\" class=\"wp-block-heading\">Les samoussas &#8211; cuisson \u00e0 la po\u00eale ou au four ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, je vous l&rsquo;accorde, cela para\u00eet un peu b\u00eate de dire cela &#8211; cuisson \u00e0 la po\u00eale ou au four ? Que choisir ? Un peu dans l&rsquo;esprit &#8211; fromage ou dessert ? Ou les deux ? Mais dans quel \u00e9tat j&rsquo;erre ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ponse est pourtant fort simple !  Cuisson \u00e0 la po\u00eale, je cuis dans des quantit\u00e9s non n\u00e9gligeables d&rsquo;huile (!) \/ Cuisson au four, je badigeonne du bout de mon pinceau de cuisine (ou  de sopalin si je n&rsquo;ai pas de pinceau) un peu de beurre fondu sur les samoussas avant d&rsquo;enfourner. On est bien d&rsquo;accord, chacun fait ses choix&#8230; En tous cas, vous avez compris le mien \ud83d\ude09<\/p>\n\n\n\n<h3 id=\"h-le-grand-dilemme-feuilles-de-brick-ou-pate-filo\" class=\"wp-block-heading\">Le GRAND dilemme : feuilles de brick ou p\u00e2te filo ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Je vous sens un peu h\u00e9sitant&#8230; Mais de quoi parle-t-elle ? C\u00e9koi\u00e7a ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici donc un petit reminder. Les feuilles de brick et la p\u00e2te filo ont la m\u00eame fonction &#8211; On pourrait dire qu&rsquo;elles sont une version orientale et maghr\u00e9bine de nos p\u00e2tes \u00e0 tarte. C&rsquo;est une tr\u00e8s grosse approximation, car m\u00eame si elles se composent de farine de bl\u00e9 comme les p\u00e2tes \u00e0 tartes, elles sont beaucoup (beaucoup !) plus fines.  A manipuler avec pr\u00e9caution donc. Elles servent \u00e0 envelopper des farces sal\u00e9es ou sucr\u00e9es assez denses. Quelques exemples de petites merveilles : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>avec les feuilles de brick (qu&rsquo;on peut aussi orthographier brik) : aum\u00f4ni\u00e8res, pastilla, bourek&#8230;<\/li>\n\n\n\n<li>avec la p\u00e2te filo (encore plus fine que les feuilles de brick) : spanakopita, baklava&#8230;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les feuilles de brick sont d\u00e9sormais relativement faciles \u00e0 trouver en grande surface (rayon p\u00e2tes \u00e0 tarte fra\u00eeches ou rayon surgel\u00e9s), la p\u00e2te filo peut-\u00eatre un peu moins. Cela vaut pourtant la peine de chercher un peu car elles ont la tr\u00e8s grande qualit\u00e9 de se conserver tr\u00e8s longtemps &#8211; Donc, une fois la p\u00e2te trouv\u00e9e, elle peut encore patienter quelques temps au r\u00e9frig\u00e9rateur. Personnellement je l&rsquo;utilise \u00e0 la place d&rsquo;une p\u00e2te bris\u00e9e ou feuillet\u00e9e traditionnelles, comme par exemple cette <a href=\"https:\/\/www.minutepapillote.com\/quiche-toute-legere-aux-epinards-frais\/\">quiche toute l\u00e9g\u00e8re aux \u00e9pinards frais<\/a>. Les quiches sont alors d\u00e9licieusement croustillantes&#8230; et tr\u00e8s peu riches en mati\u00e8re grasse. On gagne sur les deux tableaux !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors&#8230; convaincu.e ?<\/p>\n\n\n\n<h3 id=\"h-les-samoussas-au-boeuf-a-peine-epice-ou-la-version-fond-de-frigo\" class=\"wp-block-heading\">Les samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 ou la version \u00ab\u00a0fond de frigo\u00a0\u00bb<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Non, ne soyez pas apeur\u00e9s&#8230; cette version #fourzitou respecte tout de m\u00eame certains codes ! Car si la libert\u00e9 est grande sur la composition de ces petits beignets, pour faire sa propre farce, il est juste n\u00e9cessaire de se souvenir que :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>celle-ci ne doit pas \u00eatre trop aqueuse ou liquide, sinon elle d\u00e9tremperait la p\u00e2te &#8211; et adieu le joli beignet croustillant ! On oublie donc la grosse po\u00eal\u00e9e de courgettes (mais possible \u00e9videmment d&rsquo;ajouter quelques d\u00e9s crus)<\/li>\n\n\n\n<li>environ la moiti\u00e9 de la pr\u00e9paration doit \u00eatre compos\u00e9e d&rsquo;une <strong>viande <\/strong>(traditionnellement poulet ou b\u0153uf). Ou pour une version v\u00e9g\u00e9tarienne de <strong>pommes de terre<\/strong> ou de <strong>l\u00e9gumineuses<\/strong> (d\u00e9j\u00e0 cuites)<\/li>\n\n\n\n<li>ajouter des <strong>petits pois<\/strong> n&rsquo;est pas obligatoire, mais cela permet d&rsquo;avoir une structure tout en apportant de la douceur et du moelleux<\/li>\n\n\n\n<li><strong>la r\u00e9ussite repose sur la composition aromatique !<\/strong> Ne pas h\u00e9siter \u00e0 faire revenir de l&rsquo;\u00e9chalote ou de l&rsquo;oignon, ajouter des \u00e9pices \u00e0 base cardamome, cannelle, gingembre&#8230; Tout ce qui \u00e9voque des <strong>saveurs chaudes et ensoleill\u00e9es<\/strong>. Et le piment qui va avec si vous aimez \ud83d\ude09<\/li>\n\n\n\n<li>personnellement, j&rsquo;aime ajouter quelques \u00e9l\u00e9ments crus a la fin de la cuisson de la farce. Dans cette recette j&rsquo;ai mis des <strong>oignons de printemps,<\/strong> mais parfois j&rsquo;ajoute un reste de <strong>poivrons<\/strong> (d\u00e9licieux !), quelques d\u00e9s de courgettes (\u00e0 ce moment-l\u00e0 j&rsquo;ajoute un peu plus d&rsquo;\u00e9pices)&#8230; Et pourquoi pas un peu d&rsquo;oignon rouge ?<\/li>\n\n\n\n<li>enfin, pour cette recette  \u00ab\u00a0fond de frigo\u00a0\u00bb, j&rsquo;avais un reste de tofu&#8230; qui a fait des merveilles !<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_samoussas_%E2%80%93_quels_seront_les_votres\"><\/span>Les samoussas &#8211; quels seront les v\u00f4tres ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous l&rsquo;aurez compris, libre \u00e0 vous de suivre la recette, ou d&rsquo;ajouter votre \u00ab\u00a0grain de sel\u00a0\u00bb en fonction de la composition de votre frigo ! Vous me direz ? Cuisson au four ou \u00e0 la po\u00eale ? P\u00e2te filo ou feuilles de brick ? Mais aussi de quoi se compose votre farce ? Allez, j&rsquo;attends vos retours \ud83d\ude42<\/p>\n\n\n<div id=\"wpzoom-premium-recipe-card\" class=\"is-style-newdesign wp-block-wpzoom-recipe-card-block-recipe-card header-content-align-left block-alignment-left\">\n\t\t\t<div class=\"recipe-card-image\">\n\t\t\t<figure>\n\t\t\t\t<a class=\"recipe-card-image-popup-link\" href=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"530\" src=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2.jpeg\" class=\"wpzoom-recipe-card-image\" alt=\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9\" id=\"6338\" data-pin-media=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2.jpeg\" data-pin-description=\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9\" srcset=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2.jpeg 750w, https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2-300x212.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpzoom-recipe-card-pinit\">\n\t            <a class=\"btn-pinit-link no-print\" data-pin-do=\"buttonPin\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url=https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/&#038;media=https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/09\/Image-2-2.jpeg&#038;description=Samoussas%20au%20boeuf%20\u00e0%20peine%20\u00e9pic\u00e9\" data-pin-custom=\"true\" aria-label=\"Pin recipe on Pinterest\" title=\"Pin recipe on Pinterest\" >\n\t            \t<SVG class=\"wpzoom-rcb-icon-pinit-link\" enable-background=\"new 0 0 30 30\" height=\"30px\" id=\"Pinterest\" version=\"1.1\" viewBox=\"0 0 30 30\" width=\"30px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t            \t    <Path class=\"wpzoom-rcb-pinit-icon\" d=\"M16,0C7.813,0,3,6.105,3,11c0,2.964,2,6,3,6s2,0,2-1s-2-2-2-5c0-4.354,4.773-8,10-8c4.627,0,7,3.224,7,7  c0,4.968-2.735,9-6,9c-1.803,0-3.433-1.172-3-3c0.519-2.184,1-2,2-6c0.342-1.368-0.433-3-2-3c-1.843,0-4,1.446-4,4c0,1.627,1,3,1,3  s-2.245,7.863-2.576,9.263C7.766,26.049,6.938,30,7.938,30S10,28,12,23c0.295-0.738,1-3,1-3c0.599,1.142,3.14,2,5,2  c5.539,0,9-5.24,9-12C27,4.888,22.58,0,16,0z\" \/>\n\t            \t<\/SVG>\n\t            \t<span>Pin<\/span>\n\t            <\/a>\n\t        <\/div><div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link no-print\" href=\"#wpzoom-premium-recipe-card\" aria-label=\"Print recipe\" title=\"Print recipe\" title=\"Print directions\" data-recipe-id=\"6337\">\n                    <svg viewBox=\"0 0 32 32\" width=\"18\" height=\"18\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"wpzoom-rcb-icon-print-link\" aria-hidden=\"true\" focusable=\"false\"><g data-name=\"Layer 55\" id=\"Layer_55\"><path class=\"wpzoom-rcb-print-icon\" d=\"M28,25H25a1,1,0,0,1,0-2h3a1,1,0,0,0,1-1V10a1,1,0,0,0-1-1H4a1,1,0,0,0-1,1V22a1,1,0,0,0,1,1H7a1,1,0,0,1,0,2H4a3,3,0,0,1-3-3V10A3,3,0,0,1,4,7H28a3,3,0,0,1,3,3V22A3,3,0,0,1,28,25Z\"><\/path><path class=\"wpzoom-rcb-print-icon\" d=\"M25,31H7a1,1,0,0,1-1-1V20a1,1,0,0,1,1-1H25a1,1,0,0,1,1,1V30A1,1,0,0,1,25,31ZM8,29H24V21H8Z\"><\/path><path class=\"wpzoom-rcb-print-icon\" d=\"M25,9a1,1,0,0,1-1-1V3H8V8A1,1,0,0,1,6,8V2A1,1,0,0,1,7,1H25a1,1,0,0,1,1,1V8A1,1,0,0,1,25,9Z\"><\/path><rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"2\" x=\"24\" y=\"11\"><\/rect><rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"4\" x=\"18\" y=\"11\"><\/rect><\/g><\/svg>\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div>\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div><!-- \/.recipe-card-image -->\n\t\t\t\t<div class=\"recipe-card-heading\">\n\t\n\t\t\n\t\t\t\t<h2 class=\"recipe-card-title\"><span class=\"ez-toc-section\" id=\"Samoussas_au_boeuf_a_peine_epice\"><\/span>Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\t\t\t\t\t\t<div class=\"recipe-sub-title\">\n                            <span class=\"recipe-card-author\">Recipe by H\u00e9l\u00e8ne Thiers<\/span>\n            \n            <div class=\"wpzoom-rating-stars-container\" data-rating=\"5.0\" data-rating-total=\"1\" data-recipe-id=\"6337\" data-post-id=\"6337\" data-user-can-rate=\"1\">\n\t\t\t\t<ul class=\"wpzoom-rating-stars\"><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><li class=\"wpz-star-icon wpz-full-star\"><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-empty-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-full-svg\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-svg wpzoom-rating-star-partial wpzoom-rating-star-half\"><span class=\"wpzoom-rating-star-outline\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.1-32c9 0 17.3 5.1 21.4 13.1L383 125.3 542.9 150.7c8.9 1.4 16.3 7.7 19.1 16.3s.5 18-5.8 24.4L441.7 305.9 467 465.8c1.4 8.9-2.3 17.9-9.6 23.2s-17 6.1-25 2L288.1 417.6 143.8 491c-8 4.1-17.7 3.3-25-2s-11-14.2-9.6-23.2L134.4 305.9 20 191.4c-6.4-6.4-8.6-15.8-5.8-24.4s10.1-14.9 19.1-16.3l159.9-25.4 73.6-144.2c4.1-8 12.4-13.1 21.4-13.1zm0 76.8L230.3 158c-3.5 6.8-10 11.6-17.6 12.8l-125.5 20 89.8 89.9c5.4 5.4 7.9 13.1 6.7 20.7l-19.8 125.5 113.3-57.6c6.8-3.5 14.9-3.5 21.8 0l113.3 57.6-19.8-125.5c-1.2-7.6 1.3-15.3 6.7-20.7l89.8-89.9-125.5-20c-7.6-1.2-14.1-6-17.6-12.8L288.1 44.8z\" \/><\/svg><\/span><span class=\"wpzoom-rating-star-filled\"><svg viewbox=\"0 0 576 512\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M309.5-18.9c-4.1-8-12.4-13.1-21.4-13.1s-17.3 5.1-21.4 13.1L193.1 125.3 33.2 150.7c-8.9 1.4-16.3 7.7-19.1 16.3s-.5 18 5.8 24.4l114.4 114.5-25.2 159.9c-1.4 8.9 2.3 17.9 9.6 23.2s16.9 6.1 25 2L288.1 417.6 432.4 491c8 4.1 17.7 3.3 25-2s11-14.2 9.6-23.2L441.7 305.9 556.1 191.4c6.4-6.4 8.6-15.8 5.8-24.4s-10.1-14.9-19.1-16.3L383 125.3 309.5-18.9z\" \/><\/svg><\/span><\/span><\/li><\/ul><span class=\"wpzoom-rating-stars-average\"><span class=\"wpzoom-rating-average\">5.0<\/span> from <span class=\"wpzoom-rating-total-votes\">1<\/span> vote<\/span>\n\t\t\t\t<em class=\"wpzoom-rating-stars-tooltip\"><\/em>\n\t\t\t<\/div>        <\/div>\n\n        \n\t\t<div class=\"recipe-card-details-top\">\n                    <\/div>\n\t<\/div><!-- \/.recipe-card-heading -->\n\n\t\n\t\t\t<div class=\"recipe-card-details\">\n\t\t\t<div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 1024 1024\"><path d=\"M768 520V51q0-10-4-19.5T753 15q-7-7-16.5-11T717 0q-10 0-19.5 4T681 15q-8 7-11.5 16.5T666 51v469q-34 9-62.5 29T555 596q-21 28-32 61t-11 67q0 40 14 91t40.5 97q26.5 46 64.5 78 38 31 86 31 47 0 85-31 38-32 64.5-78t40.5-97q15-51 15-91 0-34-11-67t-32-61q-21-27-49.5-47T768 520zm-51 402q-31 0-67-68t-36-127q-1-21 6.5-41.5T642 650q15-16 34-25.5t41-10.5q21 1 40.5 10.5T791 650q15 15 22 35.5t6 41.5q0 59-35.5 127T717 922zM358 0q-10 0-19.5 4T322 15q-7 7-11 16.5T307 51v280l-51 34V51q0-10-4-19.5T241 15q-7-7-16.5-11T205 0q-10 0-19.5 4T169 15q-8 7-11.5 16.5T154 51v314l-52-34V51q0-10-3.5-19.5T87 15Q80 8 70.5 4T51 0Q41 0 31.5 4T15 15Q8 22 4 31.5T0 51v307q0 7 1.5 13T6 383q3 5 7.5 9.5T23 401l131 87v485q0 10 3.5 19.5T169 1009q7 7 16.5 11t19.5 4q10 0 19.5-4t16.5-11q7-7 11-16.5t4-19.5V488l131-87q5-4 9-8.5t7-9.5q3-6 5-12t2-13V51q0-10-4-19.5T395 15q-8-7-17-11t-20-4z\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Servings<\/span><p class=\"detail-item-value\">6<\/p><span class=\"detail-item-unit\">servings<\/span><\/div><div class=\"detail-item detail-item-1\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 0C9.62663 0 7.30655 0.703788 5.33316 2.02236C3.35977 3.34094 1.8217 5.21508 0.913451 7.4078C0.00519941 9.60051 -0.232441 12.0133 0.230582 14.3411C0.693605 16.6689 1.83649 18.807 3.51472 20.4853C5.19295 22.1635 7.33115 23.3064 9.65892 23.7694C11.9867 24.2324 14.3995 23.9948 16.5922 23.0865C18.7849 22.1783 20.6591 20.6402 21.9776 18.6668C23.2962 16.6934 24 14.3734 24 12C24 10.4241 23.6896 8.8637 23.0866 7.4078C22.4835 5.95189 21.5996 4.62902 20.4853 3.51472C19.371 2.40041 18.0481 1.5165 16.5922 0.913445C15.1363 0.310389 13.5759 0 12 0ZM12 21.6C10.1013 21.6 8.24524 21.037 6.66653 19.9821C5.08782 18.9272 3.85736 17.4279 3.13076 15.6738C2.40416 13.9196 2.21405 11.9893 2.58447 10.1271C2.95488 8.26491 3.86919 6.55436 5.21178 5.21177C6.55436 3.86919 8.26492 2.95488 10.1271 2.58446C11.9894 2.21404 13.9196 2.40415 15.6738 3.13076C17.4279 3.85736 18.9272 5.08781 19.9821 6.66652C21.037 8.24524 21.6 10.1013 21.6 12C21.6 14.5461 20.5886 16.9879 18.7882 18.7882C16.9879 20.5886 14.5461 21.6 12 21.6ZM15.72 12.756L13.2 11.304V6C13.2 5.68174 13.0736 5.37651 12.8485 5.15147C12.6235 4.92643 12.3183 4.8 12 4.8C11.6817 4.8 11.3765 4.92643 11.1515 5.15147C10.9264 5.37651 10.8 5.68174 10.8 6V12C10.8 12 10.8 12.096 10.8 12.144C10.8071 12.2267 10.8274 12.3077 10.86 12.384C10.8847 12.4552 10.9169 12.5236 10.956 12.588C10.9888 12.6562 11.0291 12.7206 11.076 12.78L11.268 12.936L11.376 13.044L14.496 14.844C14.6789 14.9477 14.8858 15.0014 15.096 15C15.3617 15.0019 15.6205 14.9155 15.8318 14.7544C16.0431 14.5933 16.195 14.3667 16.2637 14.11C16.3323 13.8533 16.3138 13.5811 16.2111 13.3361C16.1083 13.091 15.9272 12.887 15.696 12.756H15.72Z\" fill=\"currentColor\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Prep time<\/span><p class=\"detail-item-value\">50<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><div class=\"detail-item detail-item-2\"><span class=\"detail-item-icon\" aria-hidden=\"true\"><svg viewbox=\"0 0 512.0016 512.0155\" width=\"24\" height=\"24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 278.014q1 34-21 46-13 6-30 5v84q0 41-28 70t-70 29H151q-42 0-72-29t-30-70v-84q-16 1-28-5-22-12-21-46 0-8 7-11.5t13.5 0q6.5 3.5 5.5 11.5 0 18 8 23 5 3 15 2v-52q15 11 62 19 60 9 145.5 9t149.5-10q38-6 55-14v48q11 1 17-2 8-5 8-23-1-8 5.5-11.5t13.5 0q7 3.5 7 11.5zm-150 193q29-10 43-37t13.5-57q-.5-30-.5-60v-12q-1-10-10-14.5t-17.5 0q-8.5 4.5-8.5 14.5 1 5 2 21t1.5 26q.5 10-1 26t-4.5 26.5q-3 10.5-10 20t-17 13.5q-10 3-12 13t4.5 17q6.5 7 16.5 3zm-310-237q0-12 .5-16.5t6-13q5.5-8.5 16.5-13t33.5-8.5q22.5-4 56.5-6-11 3-10 15 0 6 4 10t11 4h1q28-1 49-21l5-4q3-4 6-7h25q23 0 44 1 2 1 5 4l6 6q21 20 49 21h1q7 0 11-4t4-10q1-9-7-14 35 3 56 8t29.5 13.5q8.5 8.5 10 14.5t1.5 19q0 3-5 6-15 12-73.5 19.5t-131.5 7.5q-75 0-132-7.5t-69-19.5q-3-2-3-5zm158-73q4-3 6-5 13-11 29-13l.5-.5.5-.5q3 0 8-1h18q5 0 6.5.5t5.5 1.5h4q15 3 27 13l6 6q1 0 2 1t1 2q3 2 5 4 4 4 8 7 11 7 24 8 9 1 8 8l-4 6v4l-3-4q-27-2-45-19l-4-4q-1-2-2-2l-5-5q-5-4-9-7-7-3-17-5h-1q-3-1-5-1-4-1-8-1h-12q-3 0-5 1-8 1-15 6-4 3-8 7-3 3-7 6l-4 5q-19 17-44 19-4 0-5.5-2t-1.5-4q0-8 7-8 13-1 24-9 4-3 8-7 2-1 4-3 1-1 3-4zm-53-157q4-5 9.5-3t7.5 7.5q2 5.5-2 11.5-5 7-5 13.5t3 11l8 12q5 7.5 7 11.5 12 25 0 50-3 6-8.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3-15.5t-4.5-13.5q-2.5-5-8-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 7.5 12t7 11.5q13 25 1 50-4 6-9.5 6t-9.5-5.5q-4-5.5-1-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-11-24 8-48zm78 0q4-5 10-3t7.5 7.5q1.5 5.5-1.5 11.5-5 7-5 13.5t2.5 11q2.5 4.5 8 12t7.5 11.5q12 25 0 50-4 6-9.5 6t-9-5.5q-3.5-5.5-1.5-11.5 5-7 3.5-15.5t-4.5-13.5q-3-5-8.5-13t-7.5-13q-10-24 8-48z\"><\/path><\/svg><\/span><span class=\"detail-item-label\">Cooking time<\/span><p class=\"detail-item-value\">30<\/p><span class=\"detail-item-unit\">minutes<\/span><\/div><\/div>\n\t\t<\/div>\n\t\t\n\t\n\t\n    \t\t        <div class=\"wpzoom-nosleep-toggle-container\">\n            <label class=\"switch\">\n\t\t\t\t<input type=\"checkbox\" id=\"toggle_button\">\n                <div class=\"slider round\"><\/div>\n            <\/label>\n                                <span class=\"wpzoom-nosleep-label\">Cook Mode<\/span>\n                                            <p class=\"recipe-card-no-sleep no-print\">Permet \u00e0 la recette de rester visible plus longtemps<\/p>\n                    <\/div>\n    \n\t\t\n\t\t\t<div class=\"recipe-card-ingredients\">\n            \t\t\t\n\t\t\t<h3 class=\"ingredients-title\">Ingr\u00e9dients<\/h3>\n            \t\t\t<ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-615333419f6c3\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">\u00e9chalote<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-615333419f6c4\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">200<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">viande de boeuf hach\u00e9e (peut \u00eatre surgel\u00e9e)<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-615333419f6c6\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">100<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">tofu ferme<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-615333419f6c5\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">80<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">g<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">petits pois (peuvent \u00eatre aussi surgel\u00e9s)<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16329921805655394\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">1<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">piment oiseau &#8211; ou plus si vous aimez \u00e9pic\u00e9 ! (\u00e0 d\u00e9faut, des flocons de piment ou \u00e9ventuellement du paprika)<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-1632902978779820\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">2<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">cuill\u00e8re \u00e0 caf\u00e9<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">mango chutney \u00e9pic\u00e9 (ou \u00e0 d\u00e9faut 1 cuiller \u00e0 caf\u00e9 de confiture de prune, abricot&#8230; voire un peu plus si vous aimez le m\u00e9lange sucr\u00e9\/sal\u00e9)<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16329912295141765\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">4<\/span>    <span class=\"wpzoom-rcb-ingredient-name\">oignons de printemps<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-16329912577561858\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">10<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">feuilles<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">menthe (environ)<\/span>  <\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-1632902933698559\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-amount\">2<\/span> <span class=\"wpzoom-rcb-ingredient wpzoom-rcb-ingredient-unit\">cuill\u00e8res \u00e0 soupe<\/span>   <span class=\"wpzoom-rcb-ingredient-name\">garam masala (ou au go\u00fbt)<\/span>  <\/p><\/li><\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t<div class=\"recipe-card-directions\">\n\t\t\t<h3 class=\"directions-title\">Instructions<\/h3>\n\t\t\t<ul class=\"directions-list\"><li id=\"wpzoom-rcb-direction-step-615333419f6c7\" class=\"direction-step\">Faire revenir dans un peu d&rsquo;huile neutre (ou encore mieux du ghee, ce beurre clarifi\u00e9) l&rsquo;\u00e9chalote \u00e9minc\u00e9e et le tofu coup\u00e9 en tous petits d\u00e9s<\/li><li id=\"wpzoom-rcb-direction-step-615333419f6c8\" class=\"direction-step\">Lorsque l&rsquo;\u00e9chalote et le tofu ont \u00e0 peine pris en couleur, ajouter la viande hach\u00e9e , du sel et le garam masala puis m\u00e9langer<\/li><li id=\"wpzoom-rcb-direction-step-615333419f6c9\" class=\"direction-step\">Faire revenir \u00e0 feu moyen 2 \u00e0 3 minutes (5 minutes si vous utilisez de la viande surgel\u00e9e) puis ajouter les petits pois et le piment oiseau<\/li><li id=\"wpzoom-rcb-direction-step-16329916990673788\" class=\"direction-step\">Lorsque la viande et les petits pois sont cuits (compter 5 \u00e0 10 minutes) ajouter du sel et le chutney de mangues puis gouter. Ajuster en fonction de votre gout en ajoutant \u00e9ventuellement un peu plus de chutney (ou \u00e0 d\u00e9faut, de confiture). <\/li><li id=\"wpzoom-rcb-direction-step-16329921651965389\" class=\"direction-step\">Ajouter les oignons de printemps et les feuilles de menthe \u00e9minc\u00e9s<\/li><li id=\"wpzoom-rcb-direction-step-16329923419956491\" class=\"direction-step\">Et voil\u00e0, la farce est pr\u00eate ! La laisser un peu refroidir avant de remplir les feuilles filo &#8211; sinon la farce ramollirait trop la p\u00e2te<\/li><li id=\"wpzoom-rcb-direction-step-16329930269167108\" class=\"direction-step\">D\u00e9couper ensuite de longues lani\u00e8res de feuilles filo, mettre un peu de farce sur l&rsquo;une d&rsquo;entre elles puis plier &#8211; je vous laisse regarder la vid\u00e9o ci-dessous pour la technique&#8230; une image vaut parfois plus que de nombreux mots !<\/li><li id=\"wpzoom-rcb-direction-step-16329931390648545\" class=\"direction-step\">Faire fondre du beurre (du ghee si vous avez) et \u00e0 l&rsquo;aide d&rsquo;un pinceau de cuisine (ou d&rsquo;un peu de sopalin) enduire les samoussas sur les deux faces<\/li><li id=\"wpzoom-rcb-direction-step-16329932369659146\" class=\"direction-step\">Les d\u00e9poser au fur et \u00e0 mesure sur une feuille de papier cuisson (sans qu&rsquo;ils se chevauchent)<\/li><li id=\"wpzoom-rcb-direction-step-16329933339499891\" class=\"direction-step\">Enfourner \u00e0 180\u00b0<\/li><li id=\"wpzoom-rcb-direction-step-16329933424159960\" class=\"direction-step\">Au bout d&rsquo;une dizaine de minutes, retourner \u00e9ventuellement d\u00e9licatement les samoussas puis poursuivre la cuisson une vingtaine de minutes (bien surveiller la cuisson, les samoussas doivent \u00eatre dor\u00e9s&#8230; mais pas plus !)<\/li><li id=\"wpzoom-rcb-direction-step-163299341256210849\" class=\"direction-step\">D\u00e9guster avec une salade par exemple<\/li><\/ul>\n\t\t<\/div>\n\t\n\t\t\t\n\t\n\t\n\t\n\t\n\t\n\t\n\t\n\t\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\n    \t\n\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Samoussas au boeuf \\u00e0 peine \\u00e9pic\\u00e9\",\"image\":[\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Image-2-2.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Image-2-2-500x500.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Image-2-2-500x375.jpeg\",\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Image-2-2-480x270.jpeg\"],\"description\":\"\",\"keywords\":\"\\u00e9pices, fond de frigo, p\\u00e2te filo, \\u00e9pices, fond de frigo, p\\u00e2te filo\",\"author\":{\"@type\":\"Person\",\"name\":\"Helene\"},\"datePublished\":\"2021-10-04T12:48:17+02:00\",\"prepTime\":\"PT50M\",\"cookTime\":\"PT30M\",\"totalTime\":\"PT1H20M\",\"recipeCategory\":[\"Ap\\u00e9rotime et entr\\u00e9es\"],\"recipeCuisine\":[],\"recipeYield\":[\"6\",\"6 servings\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"1  \\u00e9chalote\",\"200 g viande de boeuf hach\\u00e9e (peut \\u00eatre surgel\\u00e9e)\",\"100 g tofu ferme\",\"80 g petits pois (peuvent \\u00eatre aussi surgel\\u00e9s)\",\"1  piment oiseau - ou plus si vous aimez \\u00e9pic\\u00e9 ! (\\u00e0 d\\u00e9faut, des flocons de piment ou \\u00e9ventuellement du paprika)\",\"2 cuill\\u00e8re \\u00e0 caf\\u00e9 mango chutney \\u00e9pic\\u00e9 (ou \\u00e0 d\\u00e9faut 1 cuiller \\u00e0 caf\\u00e9 de confiture de prune, abricot... voire un peu plus si vous aimez le m\\u00e9lange sucr\\u00e9\\\/sal\\u00e9)\",\"4  oignons de printemps\",\"10 feuilles menthe (environ)\",\"2 cuill\\u00e8res \\u00e0 soupe garam masala (ou au go\\u00fbt)\"],\"recipeInstructions\":[{\"@type\":\"HowToStep\",\"name\":\"Faire revenir dans un peu d'huile neutre (ou encore mieux du ghee, ce beurre clarifi\\u00e9) l'\\u00e9chalote \\u00e9minc\\u00e9e et le tofu coup\\u00e9 en tous petits d\\u00e9s\",\"text\":\"Faire revenir dans un peu d'huile neutre (ou encore mieux du ghee, ce beurre clarifi\\u00e9) l'\\u00e9chalote \\u00e9minc\\u00e9e et le tofu coup\\u00e9 en tous petits d\\u00e9s\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-615333419f6c7\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Lorsque l'\\u00e9chalote et le tofu ont \\u00e0 peine pris en couleur, ajouter la viande hach\\u00e9e , du sel et le garam masala puis m\\u00e9langer\",\"text\":\"Lorsque l'\\u00e9chalote et le tofu ont \\u00e0 peine pris en couleur, ajouter la viande hach\\u00e9e , du sel et le garam masala puis m\\u00e9langer\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-615333419f6c8\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Faire revenir \\u00e0 feu moyen 2 \\u00e0 3 minutes (5 minutes si vous utilisez de la viande surgel\\u00e9e) puis ajouter les petits pois et le piment oiseau\",\"text\":\"Faire revenir \\u00e0 feu moyen 2 \\u00e0 3 minutes (5 minutes si vous utilisez de la viande surgel\\u00e9e) puis ajouter les petits pois et le piment oiseau\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-615333419f6c9\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Lorsque la viande et les petits pois sont cuits (compter 5 \\u00e0 10 minutes) ajouter du sel et le chutney de mangues puis gouter. Ajuster en fonction de votre gout en ajoutant \\u00e9ventuellement un peu plus de chutney (ou \\u00e0 d\\u00e9faut, de confiture).\",\"text\":\"Lorsque la viande et les petits pois sont cuits (compter 5 \\u00e0 10 minutes) ajouter du sel et le chutney de mangues puis gouter. Ajuster en fonction de votre gout en ajoutant \\u00e9ventuellement un peu plus de chutney (ou \\u00e0 d\\u00e9faut, de confiture).\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329916990673788\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Ajouter les oignons de printemps et les feuilles de menthe \\u00e9minc\\u00e9s\",\"text\":\"Ajouter les oignons de printemps et les feuilles de menthe \\u00e9minc\\u00e9s\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329921651965389\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Et voil\\u00e0, la farce est pr\\u00eate ! La laisser un peu refroidir avant de remplir les feuilles filo - sinon la farce ramollirait trop la p\\u00e2te\",\"text\":\"Et voil\\u00e0, la farce est pr\\u00eate ! La laisser un peu refroidir avant de remplir les feuilles filo - sinon la farce ramollirait trop la p\\u00e2te\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329923419956491\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"D\\u00e9couper ensuite de longues lani\\u00e8res de feuilles filo, mettre un peu de farce sur l'une d'entre elles puis plier - je vous laisse regarder la vid\\u00e9o ci-dessous pour la technique... une image vaut parfois plus que de nombreux mots !\",\"text\":\"D\\u00e9couper ensuite de longues lani\\u00e8res de feuilles filo, mettre un peu de farce sur l'une d'entre elles puis plier - je vous laisse regarder la vid\\u00e9o ci-dessous pour la technique... une image vaut parfois plus que de nombreux mots !\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329930269167108\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Faire fondre du beurre (du ghee si vous avez) et \\u00e0 l'aide d'un pinceau de cuisine (ou d'un peu de sopalin) enduire les samoussas sur les deux faces\",\"text\":\"Faire fondre du beurre (du ghee si vous avez) et \\u00e0 l'aide d'un pinceau de cuisine (ou d'un peu de sopalin) enduire les samoussas sur les deux faces\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329931390648545\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Les d\\u00e9poser au fur et \\u00e0 mesure sur une feuille de papier cuisson (sans qu'ils se chevauchent)\",\"text\":\"Les d\\u00e9poser au fur et \\u00e0 mesure sur une feuille de papier cuisson (sans qu'ils se chevauchent)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329932369659146\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Enfourner \\u00e0 180\\u00b0\",\"text\":\"Enfourner \\u00e0 180\\u00b0\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329933339499891\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Au bout d'une dizaine de minutes, retourner \\u00e9ventuellement d\\u00e9licatement les samoussas puis poursuivre la cuisson une vingtaine de minutes (bien surveiller la cuisson, les samoussas doivent \\u00eatre dor\\u00e9s... mais pas plus !)\",\"text\":\"Au bout d'une dizaine de minutes, retourner \\u00e9ventuellement d\\u00e9licatement les samoussas puis poursuivre la cuisson une vingtaine de minutes (bien surveiller la cuisson, les samoussas doivent \\u00eatre dor\\u00e9s... mais pas plus !)\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-16329933424159960\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"D\\u00e9guster avec une salade par exemple\",\"text\":\"D\\u00e9guster avec une salade par exemple\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/en\\\/samoussas-au-boeuf-a-peine-epice\\\/#wpzoom-rcb-direction-step-163299341256210849\",\"image\":\"\"}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"ratingCount\":1},\"review\":[]}<\/script>\n\t<\/div><!-- \/.wp-block-wpzoom-recipe-card-block-recipe-card -->\n\n<style id=\"wpzoom-rcb-block-template-default-inline-css\" type=\"text\/css\">\n\t.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .details-items .detail-item .detail-item-icon {\n                color: #FFA921;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .details-items .detail-item .detail-item-icon svg path {\n                fill: #FFA921;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients {\n                background-color: #FBF9E7;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes .recipe-card-notes-list > li {\n                background-color: #FBF9E7;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default {\n                background-color: #FFFFFF !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-ingredients .ingredients-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-directions,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-directions .directions-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-title {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .recipe-card-notes .recipe-card-notes-list li {\n                color: #333333 !important;\n            }\n.wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .ingredients-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .directions-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .video-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .equipment-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .notes-title,\n                .wp-block-wpzoom-recipe-card-block-recipe-card.is-style-default .nutrition-title {\n                color: #333333 !important;\n            }\n<\/style>\n\n\n<p class=\"wp-block-paragraph\">Une id\u00e9e d&rsquo;entr\u00e9e fra\u00eeche et d\u00e9licate \u00e0 servir juste avant de d\u00e9guster ces samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 ? Pourquoi ne pas essayer ces <a href=\"https:\/\/www.minutepapillote.com\/soupe-froide-de-petits-pois-menthe-et-noisettes-grillees\/\" target=\"_blank\" rel=\"noreferrer noopener\">verrines<\/a><a href=\"https:\/\/www.minutepapillote.com\/soupe-froide-de-petits-pois-menthe-et-noisettes-grillees\/\"> de soupe de petits pois menth<\/a><a href=\"https:\/\/www.minutepapillote.com\/soupe-froide-de-petits-pois-menthe-et-noisettes-grillees\/\" rel=\"sponsored nofollow\">e et noisettes grill\u00e9es<\/a> ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez nous , les samoussas sont un peu comme les muffins sal\u00e9s ou les tartes aux l\u00e9gumes. Un plat simple et r\u00e9confortant, facile \u00e0 pr\u00e9parer, et qui, en outre&#8230; Permet de valoriser de nombreux petits restes de frigo, impatients de rejoindre nos papilles \u00e9moustill\u00e9es ! [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[52],"tags":[117,116,115],"class_list":["post-6337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apero-entrees","tag-epices","tag-fond-de-frigo","tag-pate-filo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 - Minute Papillote<\/title>\n<meta name=\"description\" content=\"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9\" \/>\n<meta property=\"og:description\" content=\"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/\" \/>\n<meta property=\"og:site_name\" content=\"Minute Papillote\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T11:48:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T14:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/\"},\"author\":{\"name\":\"Helene\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"headline\":\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9\",\"datePublished\":\"2021-10-04T11:48:17+00:00\",\"dateModified\":\"2026-06-23T14:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/\"},\"wordCount\":1046,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Samoussa-au-boeuf-a-peine-epice-1.jpeg\",\"keywords\":[\"\u00e9pices\",\"fond de frigo\",\"p\u00e2te filo\"],\"articleSection\":[\"Ap\u00e9rotime et entr\u00e9es\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/\",\"name\":\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 - Minute Papillote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Samoussa-au-boeuf-a-peine-epice-1.jpeg\",\"datePublished\":\"2021-10-04T11:48:17+00:00\",\"dateModified\":\"2026-06-23T14:29:26+00:00\",\"description\":\"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Samoussa-au-boeuf-a-peine-epice-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Samoussa-au-boeuf-a-peine-epice-1.jpeg\",\"width\":750,\"height\":530,\"caption\":\"Samoussa au boeuf \u00e0 peine \u00e9pic\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/samoussas-au-boeuf-a-peine-epice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.minutepapillote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/\",\"name\":\"MinutePapillote\",\"description\":\"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minutepapillote.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/#\\\/schema\\\/person\\\/4c2e55effaacb798cc77a96cbb8e939c\",\"name\":\"Helene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"url\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"contentUrl\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\",\"width\":498,\"height\":245,\"caption\":\"Helene\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.minutepapillote.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-MinutePapillote-logo2021Bd-1.png\"},\"sameAs\":[\"https:\\\/\\\/www.minutepapillote.com\",\"https:\\\/\\\/www.instagram.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/helene_minutepapillote\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJ-l3TtP5ifNkp2Cb_ZmIkw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 - Minute Papillote","description":"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/","og_locale":"en_US","og_type":"article","og_title":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9","og_description":"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !","og_url":"https:\/\/www.minutepapillote.com\/en\/samoussas-au-boeuf-a-peine-epice\/","og_site_name":"Minute Papillote","article_published_time":"2021-10-04T11:48:17+00:00","article_modified_time":"2026-06-23T14:29:26+00:00","og_image":[{"width":750,"height":530,"url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg","type":"image\/jpeg"}],"author":"Helene","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#article","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/"},"author":{"name":"Helene","@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"headline":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9","datePublished":"2021-10-04T11:48:17+00:00","dateModified":"2026-06-23T14:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/"},"wordCount":1046,"commentCount":2,"publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"image":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg","keywords":["\u00e9pices","fond de frigo","p\u00e2te filo"],"articleSection":["Ap\u00e9rotime et entr\u00e9es"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/","url":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/","name":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 - Minute Papillote","isPartOf":{"@id":"https:\/\/www.minutepapillote.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#primaryimage"},"image":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg","datePublished":"2021-10-04T11:48:17+00:00","dateModified":"2026-06-23T14:29:26+00:00","description":"De d\u00e9licieux et croustillants samoussas au boeuf \u00e0 peine \u00e9pic\u00e9 : la recette mais aussi des astuces pour cr\u00e9er vos propres samoussas !","breadcrumb":{"@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#primaryimage","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/10\/Samoussa-au-boeuf-a-peine-epice-1.jpeg","width":750,"height":530,"caption":"Samoussa au boeuf \u00e0 peine \u00e9pic\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minutepapillote.com\/samoussas-au-boeuf-a-peine-epice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.minutepapillote.com\/"},{"@type":"ListItem","position":2,"name":"Samoussas au boeuf \u00e0 peine \u00e9pic\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.minutepapillote.com\/#website","url":"https:\/\/www.minutepapillote.com\/","name":"MinutePapillote","description":"Recettes simples et gourmandes, expliqu\u00e9es pas-\u00e0-pas, cuisine du quotidien et d&#039;ailleurs","publisher":{"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minutepapillote.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.minutepapillote.com\/#\/schema\/person\/4c2e55effaacb798cc77a96cbb8e939c","name":"Helene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","url":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","contentUrl":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png","width":498,"height":245,"caption":"Helene"},"logo":{"@id":"https:\/\/www.minutepapillote.com\/wp-content\/uploads\/2021\/07\/cropped-MinutePapillote-logo2021Bd-1.png"},"sameAs":["https:\/\/www.minutepapillote.com","https:\/\/www.instagram.com\/helene_minutepapillote\/","https:\/\/www.pinterest.com\/helene_minutepapillote\/","https:\/\/www.youtube.com\/channel\/UCJ-l3TtP5ifNkp2Cb_ZmIkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/comments?post=6337"}],"version-history":[{"count":1,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/6337\/revisions"}],"predecessor-version":[{"id":14998,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/posts\/6337\/revisions\/14998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media\/6457"}],"wp:attachment":[{"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/media?parent=6337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/categories?post=6337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minutepapillote.com\/en\/wp-json\/wp\/v2\/tags?post=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}